{"id":12416,"date":"2018-12-27T14:13:46","date_gmt":"2018-12-27T16:13:46","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=12416"},"modified":"2018-12-27T14:13:46","modified_gmt":"2018-12-27T16:13:46","slug":"elenco-do-atletico-de-alagoinhas-se-reapresenta-apos-recesso-do-natal","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/elenco-do-atletico-de-alagoinhas-se-reapresenta-apos-recesso-do-natal\/","title":{"rendered":"Elenco do Atl\u00e9tico de Alagoinhas se reapresenta ap\u00f3s recesso do Natal"},"content":{"rendered":"<p style=\"text-align: justify;\">[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]Ontem, quarta-feira(26), a equipe Carcar\u00e1 se reapresentou ap\u00f3s o recesso de Natal. A apresenta\u00e7\u00e3o e o treinamento aconteceu no CT da Catuense, mais um local utilizado pelo Atl\u00e9tico para realizar as suas atividades visando o Campeonato Baiano 2018. Essa parceria \u00e9 fruto de um acerto com os diretores da Catuense e do Atl\u00e9tico de Alagoinhas. Ainda no dia de ontem o jogador Junior Gaucho, o mais novo contratado do Atl\u00e9tico, se apresentou ao clube e j\u00e1 integra o elenco.<\/p>\n<p style=\"text-align: justify;\">Logo mais, \u00e1s 15:30, o Carcar\u00e1 realizar\u00e1 mais um amistoso. A partida ser\u00e1 contra o time do Vitoria que vai disputar a Copa S\u00e3o Paulo de futebol Junior a partir de janeiro. O jogo Vit\u00f3ria x Atl\u00e9tico de Alagoinhas ser\u00e1 disputado no Barrad\u00e3o.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-390102986\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<h6 style=\"text-align: right;\"><span style=\"color: #999999;\">Por Andr\u00e9 Luiz para o News Infoco<\/span><\/h6>\n<p style=\"text-align: justify;\">\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Elenco do Atl\u00e9tico de Alagoinhas se reapresenta ap\u00f3s recesso do Natal' data-link='https:\/\/newsinfoco.com.br\/inicio\/elenco-do-atletico-de-alagoinhas-se-reapresenta-apos-recesso-do-natal\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]Ontem, quarta-feira(26), a equipe Carcar\u00e1 se reapresentou ap\u00f3s o recesso de Natal. A apresenta\u00e7\u00e3o e o treinamento aconteceu no CT da Catuense, mais um local utilizado pelo Atl\u00e9tico para realizar as suas atividades visando o Campeonato Baiano 2018. Essa parceria \u00e9 fruto de um acerto com os diretores da Catuense e do Atl\u00e9tico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[30,36],"tags":[],"class_list":["post-12416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-esporte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/12416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=12416"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/12416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/12417"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=12416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=12416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=12416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}