{"id":12955,"date":"2019-01-23T23:09:19","date_gmt":"2019-01-24T01:09:19","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=12955"},"modified":"2019-01-23T23:09:19","modified_gmt":"2019-01-24T01:09:19","slug":"esperamos-o-pior-diz-bolsonaro-sobre-risco-de-resistencia-de-maduro","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/esperamos-o-pior-diz-bolsonaro-sobre-risco-de-resistencia-de-maduro\/","title":{"rendered":"\u2018Esperamos o pior\u2019, diz Bolsonaro sobre risco de resist\u00eancia de Maduro"},"content":{"rendered":"<p style=\"text-align: justify;\">[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]O presidente Jair Bolsonaro afirmou nesta quarta-feira, 23, estar preocupado com a possibilidade de que haja uma resist\u00eancia por parte de Nicol\u00e1s Maduro, diante da decis\u00e3o de Brasil, EUA, Col\u00f4mbia e outros pa\u00edses de reconhecer o opositor Juan Guaid\u00f3 como o presidente leg\u00edtimo da Venezuela. \u201cTodos n\u00f3s conhecemos um pouquinho Nicol\u00e1s Maduro. Esperamos o pior. H\u00e1 uma preocupa\u00e7\u00e3o, sim\u201d, disse Bolsonaro em declara\u00e7\u00f5es exclusivas ao Estado. \u201cMas achamos que Guaid\u00f3 n\u00e3o receber\u00e1 qualquer tipo de retalia\u00e7\u00e3o de Maduro, at\u00e9 porque o mundo est\u00e1 de olho nisso e os EUA tamb\u00e9m reconheceram\u201d, afirmou o presidente. Bolsonaro participou nesta quarta-feira em Davos de uma reuni\u00e3o com os presidentes da Col\u00f4mbia, Equador e Costa Rica, al\u00e9m de chanceleres do Canad\u00e1 e outros pa\u00edses.<\/p>\n<p style=\"text-align: justify;\">Instantes depois de dar as declara\u00e7\u00f5es ao Estado, diante da imprensa internacional, ele confirmou a decis\u00e3o do governo brasileiro. \u201cO Brasil reconhece Guaid\u00f3 como presidente da Venezuela. O Brasil, juntamente com os demais pa\u00edses do Grupo de Lima, que est\u00e3o reconhecendo um a um esse fato, daremos todo o apoio pol\u00edtico necess\u00e1rio para que esse processo siga seu destino\u201d, disse. Ao deixar o encontro em Davos dedicado \u00e0 crise venezuelana, membros da oposi\u00e7\u00e3o de Caracas n\u00e3o continham as l\u00e1grimas diante dos an\u00fancios dos diferentes governos da regi\u00e3o. \u201cVamos dar todo o apoio para que a transi\u00e7\u00e3o possa ocorrer\u201d, completou Iv\u00e1n Duque, presidente da Col\u00f4mbia. O presidente dos Estados Unidos, Donald Trump, reconheceu Guaid\u00f3 como presidente de facto do pa\u00eds e convocou l\u00edderes latino-americanos a fazerem o mesmo. Trump elogiou tamb\u00e9m as manifesta\u00e7\u00f5es desta quarta-feira na Venezuela. Horas depois, Maduro anunciou a ruptura das rela\u00e7\u00f5es diplom\u00e1ticas entre Venezuela e EUA e deu um prazo de 72 horas para os diplomatas americanos deixarem o pa\u00eds. Se o epicentro dos protestos estava em Caracas, foi longe dali, nos Alpes su\u00ed\u00e7os, que come\u00e7ou a ser desenhado a estrutura do que ocorreria diante dos protestos. A meta era a de construir uma alian\u00e7a ampla que pudesse blindar Guaid\u00f3.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1638202492\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">Logo pela manh\u00e3, antes mesmo de o povo venezuelano sair \u00e0s ruas, o chanceler Ernesto Araujo ja estava reunido em Davos com o ministro de Rela\u00e7\u00f5es Exteriores do Paraguai, Luis Alberto Castiglioni. \u201cQueremos que seja ampliado para permitir que haja um impacto\u201d, disse o paraguaio. \u201cHoje, a \u00fanica maneira \u00e9 a press\u00e3o internacional\u201d, declarou. \u201cPrecisamos de uma alian\u00e7a global\u201d, disse. A esperan\u00e7a dos diplomatas \u00e9 de que, com os EUA no Grupo e o Brasil fazendo parte dos Brics, possa haver uma press\u00e3o maior sobre russos e chineses, que mant\u00e9m o apoio a Maduro. Ao longo do dia, um dos objetivos era o de chegar tamb\u00e9m a um consenso para que uma alian\u00e7a internacional fosse estabelecida para pressionar Maduro. Na vis\u00e3o de alguns dos governos da regi\u00e3o, o Grupo de Lima amea\u00e7ava ficar sem impacto se continuasse a fazer declara\u00e7\u00f5es de for\u00e7a, mas sem o envolvimento dos EUA e pot\u00eancias. A ideia era a de acompanhar passo \u00e0 passo o que estava ocorrendo em Caracas, enquanto se proliferaram as reuni\u00f5es em Davos.<\/p>\n<p style=\"text-align: justify;\">O pr\u00f3prio Itamaraty indicou que iria \u201csentir a temperatura\u201d das primeiras horas dos protestos para avaliar se declararia o apoio oficial \u00e0 oposi\u00e7\u00e3o. O risco, segundo a chancelaria, era de que o protesto fosse seguido por viol\u00eancia. O Estado apurou que colombianos e outros pa\u00edses da regi\u00e3o j\u00e1 queriam ter declarado apoio a Guaid\u00f3 logo que os protestos come\u00e7aram. A decis\u00e3o, por\u00e9m, foi a de aguardar uma sinaliza\u00e7\u00e3o americana, justamente para garantir a for\u00e7a da medida e evitar que o problema se transformasse apenas em uma situa\u00e7\u00e3o de impasse diplom\u00e1tico dentro da Am\u00e9rica Latina. O reconhecimento americano acabou ocorrendo perto das 18h do hor\u00e1rio su\u00ed\u00e7o. Neste momento, por uma coincid\u00eancia, o F\u00f3rum Econ\u00f4mico Mundial havia organizado uma reuni\u00e3o fechada entre l\u00edderes da ONU e os presidentes da regi\u00e3o, entre eles Jair Bolsonaro. Oficialmente, o tema era a resposta \u00e0 crise humanit\u00e1ria na Venezuela. Fontes que estiveram dentro do encontro, por\u00e9m, confirmaram ao Estado que o tom mudou diante dos acontecimentos e o que se decidiu foi o de acelerar o processo de reconhecimento para dar um sinal claro das inten\u00e7\u00f5es da regi\u00e3o. Quando a parte formal do encontro terminou, os presidentes da regi\u00e3o passaram a se reunir de forma separada. Um dos envolvidos nas conversas era Eduardo Bolsonaro, filho do presidente. A decis\u00e3o foi a de seguir o gesto americano e passar a dar apoio a Guaid\u00f3. \u201cAcompanhamos o processo em dire\u00e7\u00e3o da democracia para que o povo venezuelano se libere\u201d, declarou Ivan Duque, presidente da Col\u00f4mbia. Enquanto os presidentes faziam a declara\u00e7\u00e3o, membros da oposi\u00e7\u00e3o venezuelana que estavam em Davos para o encontro n\u00e3o aguentavam as l\u00e1grimas e se abra\u00e7avam.<\/p>\n<p style=\"text-align: right;\"><span style=\"color: #999999;\">Estadao<\/span><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='\u2018Esperamos o pior\u2019, diz Bolsonaro sobre risco de resist\u00eancia de Maduro' data-link='https:\/\/newsinfoco.com.br\/inicio\/esperamos-o-pior-diz-bolsonaro-sobre-risco-de-resistencia-de-maduro\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]O presidente Jair Bolsonaro afirmou nesta quarta-feira, 23, estar preocupado com a possibilidade de que haja uma resist\u00eancia por parte de Nicol\u00e1s Maduro, diante da decis\u00e3o de Brasil, EUA, Col\u00f4mbia e outros pa\u00edses de reconhecer o opositor Juan Guaid\u00f3 como o presidente leg\u00edtimo da Venezuela. \u201cTodos n\u00f3s conhecemos um pouquinho Nicol\u00e1s Maduro. Esperamos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-12955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/12955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=12955"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/12955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/12956"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=12955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=12955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=12955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}