{"id":12968,"date":"2019-01-24T18:21:49","date_gmt":"2019-01-24T20:21:49","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=12968"},"modified":"2019-01-24T18:21:49","modified_gmt":"2019-01-24T20:21:49","slug":"apos-falhas-no-jogo-contra-o-jequie-goleiro-do-atletico-de-alagoinhas-tem-seu-contrato-rescindido","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/apos-falhas-no-jogo-contra-o-jequie-goleiro-do-atletico-de-alagoinhas-tem-seu-contrato-rescindido\/","title":{"rendered":"Ap\u00f3s falhas no jogo contra o Jequi\u00e9, goleiro do Atl\u00e9tico de Alagoinhas tem seu contrato rescindido"},"content":{"rendered":"<p style=\"text-align: justify;\">[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]Ap\u00f3s o empate em 4X4 com o time do Jequi\u00e9 em pleno Carneir\u00e3o, o goleiro da equipe do Atl\u00e9tico de Alagoinhas, Rodrigo Ramos, e a diretoria do Carcar\u00e1 chegaram a um acordo e o jogador acabou sendo dispensado. Rodrigo Ramos foi uma das pe\u00e7a mais criticadas pela imprensa e por torcedores atleticanos ap\u00f3s o jogo.<\/p>\n<p style=\"text-align: justify;\">Se analisarmos os dois jogos disputados pelo Atl\u00e9tico na Campeonato Baiano, o experiente goleiro levou 6 gols, dois na partida diante da Juazeirense e 4 no jogo do Jequi\u00e9. Segundo a diretoria do Atl\u00e9tico de Alagoinhas um novo goleiro dever\u00e1 ser contratado.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-975202983\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">Hoje(24) pela manh\u00e3 os jogadores do Carcar\u00e1 fizeram um trabalho fisico em uma academia aqui de Alagoinhas e a partir de amanh\u00e3 sexta-feira come\u00e7a a prepara\u00e7\u00e3o para o jogo contra o Vit\u00f3ria da Conquista que vai acontecer no dia 3 de fevereiro no est\u00e1dio Lomanto J\u00fanior na cidade de Vitoria da Conquista.<\/p>\n<h6 style=\"text-align: right;\">Por Andr\u00e9 Luiz para o News Infoco<\/h6>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ap\u00f3s falhas no jogo contra o Jequi\u00e9, goleiro do Atl\u00e9tico de Alagoinhas tem seu contrato rescindido' data-link='https:\/\/newsinfoco.com.br\/inicio\/apos-falhas-no-jogo-contra-o-jequie-goleiro-do-atletico-de-alagoinhas-tem-seu-contrato-rescindido\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]Ap\u00f3s o empate em 4X4 com o time do Jequi\u00e9 em pleno Carneir\u00e3o, o goleiro da equipe do Atl\u00e9tico de Alagoinhas, Rodrigo Ramos, e a diretoria do Carcar\u00e1 chegaram a um acordo e o jogador acabou sendo dispensado. Rodrigo Ramos foi uma das pe\u00e7a mais criticadas pela imprensa e por torcedores atleticanos ap\u00f3s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[30,36],"tags":[],"class_list":["post-12968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-esporte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/12968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=12968"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/12968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/12969"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=12968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=12968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=12968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}