{"id":13143,"date":"2019-02-02T20:47:44","date_gmt":"2019-02-02T22:47:44","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=13143"},"modified":"2019-02-02T20:47:44","modified_gmt":"2019-02-02T22:47:44","slug":"novos-servidores-municipais-foram-empossados-em-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/novos-servidores-municipais-foram-empossados-em-alagoinhas\/","title":{"rendered":"Novos servidores municipais foram empossados em Alagoinhas"},"content":{"rendered":"<p>[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]A Prefeitura empossou, na manh\u00e3 desta sexta-feira (1), novos servidores municipais, que foram recepcionados no Gabinete pelo secret\u00e1rio de governo, Gustavo Carmo, pela secret\u00e1ria de Administra\u00e7\u00e3o, Leila Vila Flor, e pela comandante da Guarda Municipal, Renata Fortaleza.<\/p>\n<p>Tamb\u00e9m estiveram na solenidade o coordenador de Concursos e Sele\u00e7\u00f5es, Ant\u00f4nio Alves e o corregedor Fabrizio Costa.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3274545522\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>No total, 11 efetivos devem se juntar \u00e0 Guarda Municipal de Alagoinhas, se unindo aos 164 profissionais do setor e agregando \u00e0s for\u00e7as locais que atuam na seguran\u00e7a do cidad\u00e3o e dos bens p\u00fablicos.<\/p>\n<p>Tamb\u00e9m foram admitidos, em decorr\u00eancia de processo seletivo, 2 servidores da Secretaria Municipal de Assist\u00eancia Social (SEMAS) e 2 da Secretaria Municipal de Sa\u00fade (SESAU).<\/p>\n<p style=\"text-align: justify;\">O secret\u00e1rio de governo, Gustavo Carmo, conduziu o ato simb\u00f3lico e destacou que o servi\u00e7o p\u00fablico exige dedica\u00e7\u00e3o, comprometimento e responsabilidade nas atribui\u00e7\u00f5es de cada fun\u00e7\u00e3o. \u201cPassar em um concurso \u00e9 resultado de muita dedica\u00e7\u00e3o. Esse momento, no gabinete, \u00e9 de acolhimento. Voc\u00eas tomam posse hoje para fazer parte de um todo, de um instrumento que \u00e9 vital para as pessoas, que \u00e9 o poder p\u00fablico municipal. Essa uni\u00e3o, entre profissionais na condi\u00e7\u00e3o de secret\u00e1rios, comissionados e efetivos, \u00e9 que faz com que isso que est\u00e1 aqui seja muito maior do que a estrutura f\u00edsica da prefeitura. \u00c9 com foco na qualidade do servi\u00e7o prestado que o Governo Joaquim Neto realiza suas a\u00e7\u00f5es e voc\u00eas fazem parte disso\u201d, salientou aos novos efetivos.<\/p>\n<p style=\"text-align: justify;\">O subsecret\u00e1rio de Educa\u00e7\u00e3o, Jean Afonso, ressaltou que o servi\u00e7o p\u00fablico precisa ser entendido e encarado, em todas as inst\u00e2ncias, como um servi\u00e7o de qualidade, e a secret\u00e1ria de Administra\u00e7\u00e3o, Leila Vila Flor, acrescentou que as atividades do setor p\u00fablico interferem diretamente na qualidade de vida da popula\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">As admiss\u00f5es ser\u00e3o publicadas em di\u00e1rio oficial do munic\u00edpio.<\/p>\n<h6 style=\"text-align: right;\">Secom Alagoinhas<\/h6>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Novos servidores municipais foram empossados em Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/novos-servidores-municipais-foram-empossados-em-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]A Prefeitura empossou, na manh\u00e3 desta sexta-feira (1), novos servidores municipais, que foram recepcionados no Gabinete pelo secret\u00e1rio de governo, Gustavo Carmo, pela secret\u00e1ria de Administra\u00e7\u00e3o, Leila Vila Flor, e pela comandante da Guarda Municipal, Renata Fortaleza. Tamb\u00e9m estiveram na solenidade o coordenador de Concursos e Sele\u00e7\u00f5es, Ant\u00f4nio Alves e o corregedor Fabrizio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,30],"tags":[],"class_list":["post-13143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-destaque"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/13143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=13143"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/13143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/13146"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=13143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=13143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=13143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}