{"id":14505,"date":"2019-04-06T18:20:35","date_gmt":"2019-04-06T21:20:35","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=14505"},"modified":"2019-04-06T18:22:09","modified_gmt":"2019-04-06T21:22:09","slug":"nao-faremos-nenhuma-alianca-nesse-momento-que-nao-seja-construida-atraves-do-governador-rui-costa-afirma-paulo-cezar","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/nao-faremos-nenhuma-alianca-nesse-momento-que-nao-seja-construida-atraves-do-governador-rui-costa-afirma-paulo-cezar\/","title":{"rendered":"&#8216;N\u00e3o faremos nenhuma alian\u00e7a nesse momento que n\u00e3o seja constru\u00edda atrav\u00e9s do Governador, Rui Costa&#8221;, afirma Paulo Cezar"},"content":{"rendered":"<p style=\"text-align: justify;\">No dia de hoje(06) o site News Infoco publicou mat\u00e9ria em que fontes revelavam uma tentativa de aproxima\u00e7\u00e3o do ex-prefeito Paulo Cezar com o deputado federal Paulo Azi pensando nas elei\u00e7\u00f5es do ano que vem, onde Paulo Cezar figura como um pretenso candidato e com chances reais de vit\u00f3ria.<\/p>\n<p style=\"text-align: justify;\">Nos arranjos para a concretiza\u00e7\u00e3o dessa alian\u00e7a, Paulo Cezar estaria disposto a ceder a indica\u00e7\u00e3o do vice na chapa e espa\u00e7o no governo em troca do apoio do deputado Paulo Azi. A inten\u00e7\u00e3o \u00e9 unir for\u00e7as para derrotar o atual prefeito Joaquim Neto, desafeto politico de ambos.<a href=\"http:\/\/newsinfoco.com.br\/2019\/04\/06\/paulo-cezar-quer-apoio-do-deputado-paulo-azi-nas-eleicoes-de-2020\/\"> ( veja aqui a mat\u00e9ria completa )<\/a><\/p><div class=\"newsi-conteudo_19\" id=\"newsi-436870331\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">Depois da veicula\u00e7\u00e3o da mat\u00e9ria, o ex-prefeito Paulo Cezar entrou em contato com o site News Infoco, reafirmando que uma sa\u00edda sua da base do governo Rui Costa est\u00e1 descartada.\u00a0\u201cSou Governo. N\u00e3o faremos nenhuma alian\u00e7a nesse momento que n\u00e3o seja constru\u00edda atrav\u00e9s do Governador, Rui Costa. N\u00e3o existe hip\u00f3tese em sair da base de sustenta\u00e7\u00e3o do melhor governador do Brasil. N\u00e3o acredito que essa informa\u00e7\u00e3o tenha vindo de ningu\u00e9m do nosso grupo pol\u00edtico\u201d, palavras do ex-prefeito, Paulo Cezar.<\/p>\n<div class=\"gs\">\n<div class=\"\">\n<div id=\":nl\" class=\"a3s aXjCH \">\n<div dir=\"auto\">\n<div dir=\"auto\" style=\"text-align: justify;\">Ainda segundo Paulo Cezar \u201cestamos tranquilos quanto a isso. N\u00e3o vamos ficar nesse jogo de especula\u00e7\u00f5es. Temos que sentar com o Governador e definir para qual partido n\u00f3s vamos. Ap\u00f3s essa conversa, n\u00f3s temos a certeza de que teremos um direcionamento para 2020. Alagoinhas \u00e9 uma cidade polo e que representa muito ao Governo do Estado\u201d, concluiu. Paulo Cezar aguarda uma orienta\u00e7\u00e3o do Governador para definir a qual partido ele vai ingressar. Nos pr\u00f3ximos dias, esse encaminhamento poder\u00e1 acontecer ap\u00f3s uma conversa com o chefe do executivo estadual.<\/div>\n<\/div>\n<h6 dir=\"auto\" style=\"text-align: right;\">Por Caio Pimenta para o News Infoco<\/h6>\n<div class=\"adL\"><\/div>\n<\/div>\n<p class=\"hi\" style=\"text-align: justify;\">\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text=''N\u00e3o faremos nenhuma alian\u00e7a nesse momento que n\u00e3o seja constru\u00edda atrav\u00e9s do Governador, Rui Costa\", afirma Paulo Cezar' data-link='https:\/\/newsinfoco.com.br\/inicio\/nao-faremos-nenhuma-alianca-nesse-momento-que-nao-seja-construida-atraves-do-governador-rui-costa-afirma-paulo-cezar\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>No dia de hoje(06) o site News Infoco publicou mat\u00e9ria em que fontes revelavam uma tentativa de aproxima\u00e7\u00e3o do ex-prefeito Paulo Cezar com o deputado federal Paulo Azi pensando nas elei\u00e7\u00f5es do ano que vem, onde Paulo Cezar figura como um pretenso candidato e com chances reais de vit\u00f3ria. Nos arranjos para a concretiza\u00e7\u00e3o dessa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,30],"tags":[],"class_list":["post-14505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-destaque"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/14505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=14505"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/14505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/11750"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=14505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=14505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=14505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}