{"id":18387,"date":"2019-11-03T19:53:50","date_gmt":"2019-11-03T21:53:50","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=18387"},"modified":"2019-11-03T20:03:02","modified_gmt":"2019-11-03T22:03:02","slug":"pesquisa-demonstra-desilusao-do-eleitor-com-as-forcas-politicas-tradicionais-de-alagoinhas-por-caio-pimenta","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/pesquisa-demonstra-desilusao-do-eleitor-com-as-forcas-politicas-tradicionais-de-alagoinhas-por-caio-pimenta\/","title":{"rendered":"Pesquisa demonstra desilus\u00e3o do eleitor com as for\u00e7as pol\u00edticas tradicionais de Alagoinhas &#8211; Por Caio Pimenta"},"content":{"rendered":"<p style=\"text-align: justify;\">&#8216;ELES N\u00c3O NOS REPRESENTAM!&#8217;. Assim poderia ter sido o titulo da mat\u00e9ria do site Bahianoticias que na \u00faltima ter\u00e7a-feira(29) divulgou o resultado de uma pesquisa eleitoral tendo como objeto a cidade de Alagoinhas. O site preferiu dar uma &#8216;moral&#8217; ao l\u00edder da pesquisa, o ex-prefeito da cidade, Paulo Cezar, que alcan\u00e7ou quase 20% das inten\u00e7\u00f5es de votos. Um n\u00famero bem distante do segundo colocado, o atual prefeito Joaquim Neto que aparece com quase 7%. A pesquisa tamb\u00e9m tr\u00e1s 3 nomes do PT citados pelo eleitor, o sindicalista Radiovaldo Costa, o deputado federal Joseildo Ramos e o vereador Luciano Sergio.<\/p>\n<p style=\"text-align: justify;\">Valorizo aqui os n\u00fameros da pesquisa espont\u00e2nea, onde\u00a0uma pergunta \u00e9 feita aos entrevistados e n\u00e3o \u00e9 dada nenhuma alternativa para resposta. Esse tipo de pesquisa ao meu ver tem mais relev\u00e2ncia do que a pesquisa estimulada, onde uma lista \u00e9 passada para os entrevistados escolherem algumas das alternativas com nomes j\u00e1 pr\u00e9-definidos pelo entrevistador. A pesquisa espont\u00e2nea \u00e9 a lembran\u00e7a do eleitor, \u00e9 o nome que lhe vem a cabe\u00e7a quando imagina algu\u00e9m sentado na cadeira do prefeito e por isso aqui neste artigo darei \u00eanfase a ela.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-639806858\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">O resultado foi muito comemorado pelo grupo de Paulo Cezar, que apontou a grande diferen\u00e7a para seus advers\u00e1rios, sendo ele lider inconteste da pesquisa. Os simpatizantes de Joaquim Neto tamb\u00e9m comemoraram, tanto a segunda coloca\u00e7\u00e3o isolada, como a diminui\u00e7\u00e3o acentuada na rejei\u00e7\u00e3o ao seu nome, que na pesquisa estimulada ficou na casa dos 30%. Os petistas tamb\u00e9m comemoraram pela lembran\u00e7a do eleitor aos 3 nomes do partido. Eles acreditam que ao se juntarem, o nome escolhido pelo partido, com o apoio dos outros dois, garante a competitividade na disputa. Os outros candidatos citados, sem muita express\u00e3o at\u00e9 aqui, tamb\u00e9m comemoraram pela cita\u00e7\u00e3o de seus nomes. Quem n\u00e3o teve motivos para comemorar foi o grupo do deputado Paulo Azi, cujo o pr\u00e9-candidato do DEM, Fabricio Faro, nem sequer foi citado pelos entrevistados. Culpa de seus correligion\u00e1rios que fazem mais for\u00e7a para uma alian\u00e7a entre Paulo Azi e Paulo Cezar, do que o fortalecimento de seu nome.<\/p>\n<p style=\"text-align: justify;\">Mas notem quanta mediocridade. A pesquisa espont\u00e2nea demonstrou que 61,3% dos entrevistados n\u00e3o tem candidato. \u00c9 demonstra\u00e7\u00e3o inequ\u00edvoca do grande desprezo que a popula\u00e7\u00e3o nutre pelos pol\u00edticos locais. Isso \u00e9 motivo de comemora\u00e7\u00e3o?!<\/p>\n<p style=\"text-align: justify;\">Quando se apresenta a pesquisa estimulada, o numero de entrevistados que ainda sim afirma n\u00e3o ter candidato cai para 17,12%, mas se percebe que o candidato Fabricio Faro do DEM, por exemplo, que nem sequer foi citado na pesquisa espontanea, aparece com 4,55% na estimulada. \u00c9 como se o eleitor dissesse &#8216;se s\u00f3 tiver esses ai, eu tenho que escolher algu\u00e9m mesmo, vou votar no menos pior&#8217; e a\u00ed escolhe entre as op\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">\u00c9 uma vergonha para uma cidade do porte de Alagoinhas, se perceber a fal\u00eancia do seu quadro politico. Isso traz desesperan\u00e7a aos alagoinhenses e favorece a ascens\u00e3o de candidatos populistas, muitas vezes corruptos, que sentem nesse ambiente o momento propicio para se espalhar.<\/p>\n<p style=\"text-align: justify;\"><strong>Caio Pimenta \u00e9 Bacharel em Direito, radialista, comentarista do Programa Primeira M\u00e3o da r\u00e1dio Ouro Negro FM 100,5 FM e r\u00e1dio 2 de Julho. Ele tamb\u00e9m \u00e9 editor-chefe do site News Infoco.<\/strong><\/p>\n<div class=\"share-to-whatsapp-wrapper\"><\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Pesquisa demonstra desilus\u00e3o do eleitor com as for\u00e7as pol\u00edticas tradicionais de Alagoinhas - Por Caio Pimenta' data-link='https:\/\/newsinfoco.com.br\/inicio\/pesquisa-demonstra-desilusao-do-eleitor-com-as-forcas-politicas-tradicionais-de-alagoinhas-por-caio-pimenta\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8216;ELES N\u00c3O NOS REPRESENTAM!&#8217;. Assim poderia ter sido o titulo da mat\u00e9ria do site Bahianoticias que na \u00faltima ter\u00e7a-feira(29) divulgou o resultado de uma pesquisa eleitoral tendo como objeto a cidade de Alagoinhas. O site preferiu dar uma &#8216;moral&#8217; ao l\u00edder da pesquisa, o ex-prefeito da cidade, Paulo Cezar, que alcan\u00e7ou quase 20% das inten\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-18387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caio-pimenta"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/18387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=18387"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/18387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/18094"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=18387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=18387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=18387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}