{"id":18566,"date":"2019-11-09T00:02:06","date_gmt":"2019-11-09T02:02:06","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=18566"},"modified":"2019-11-09T00:02:06","modified_gmt":"2019-11-09T02:02:06","slug":"em-discurso-lula-ataca-lado-podre-da-justica-do-mp-e-da-pf-e-diz-que-percorrera-o-pais","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/em-discurso-lula-ataca-lado-podre-da-justica-do-mp-e-da-pf-e-diz-que-percorrera-o-pais\/","title":{"rendered":"Em discurso, Lula ataca \u2018lado podre\u2019 da Justi\u00e7a, do MP e da PF e diz que percorrer\u00e1 o pa\u00eds"},"content":{"rendered":"<p style=\"text-align: justify;\">Lula livre j\u00e1 fez seu primeiro palanque. \u00c0 sa\u00edda da sede da Pol\u00edcia Federal, em Curitiba, onde passou preso 580 dias, cumprindo pena no processo do triplex do Guaruj\u00e1, o petista atacou as institui\u00e7\u00f5es que o cercaram e levaram \u00e0 sua condena\u00e7\u00e3o. \u201cDe um lado, o lado podre do Estado brasileiro, o lado podre da Justi\u00e7a, o lado pode do Minist\u00e9rio P\u00fablico, o lado podre da Receita Federal, o lado podre da Pol\u00edcia Federal, que trabalharam para tentar criminalizar a esquerda, criminalizar o PT, criminalizar o Lula\u201d. Ele seguiu, em meio aos manifestantes que o ovacionaram. \u201cLado mentiroso da Pol\u00edcia Federal, lado mentiroso e canalha do Minist\u00e9rio P\u00fablico e da for\u00e7a- tarefa\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cSe pegar o (Deltan) Dallagnol (chefe da for\u00e7a-tarefa do Minist\u00e9rio P\u00fablico Federal em Curitiba), o (S\u00e9rgio) Moro (ex-juiz da Lava Jato) e alguns delegados, enfia e bate num liquidificador. O que sobrar n\u00e3o \u00e9 dez por cento da honestidade que eu represento. Eles t\u00eam que saber que car\u00e1ter e dignidade n\u00e3o \u00e9 uma coisa que a gente compra em shopping center, no bar\u201d.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3985905709\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">Um ano e sete meses ap\u00f3s ser preso na Opera\u00e7\u00e3o Lava Jato para cumprir pena de corrup\u00e7\u00e3o passiva e lavagem de dinheiro no processo do triplex do Guaruj\u00e1, o ex-presidente Luiz In\u00e1cio Lula da Silva deixou na tarde desta sexta, 8, a cela especial da Pol\u00edcia Federal em Curitiba.<\/p>\n<p style=\"text-align: justify;\">Lula saiu da sede da PF \u00e0s 17H42 \u2014 pouco mais de uma hora depois da expedi\u00e7\u00e3o do alvar\u00e1 de soltura. Uma multid\u00e3o de manifestantes saudou o ex-presidente empunhando bandeiras do PT gritando palavras de ordem.<br \/>\nA ordem de soltura do petista foi dada pelo juiz Danilo Pereira J\u00fanior, da 12\u00aa Vara Federal de Curitiba, menos de 24 horas depois de o Supremo Tribunal Federal declarar inconstitucional a pris\u00e3o ap\u00f3s condena\u00e7\u00e3o em segunda inst\u00e2ncia \u2013 caso de Lula.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Em discurso, Lula ataca \u2018lado podre\u2019 da Justi\u00e7a, do MP e da PF e diz que percorrer\u00e1 o pa\u00eds' data-link='https:\/\/newsinfoco.com.br\/inicio\/em-discurso-lula-ataca-lado-podre-da-justica-do-mp-e-da-pf-e-diz-que-percorrera-o-pais\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Lula livre j\u00e1 fez seu primeiro palanque. \u00c0 sa\u00edda da sede da Pol\u00edcia Federal, em Curitiba, onde passou preso 580 dias, cumprindo pena no processo do triplex do Guaruj\u00e1, o petista atacou as institui\u00e7\u00f5es que o cercaram e levaram \u00e0 sua condena\u00e7\u00e3o. \u201cDe um lado, o lado podre do Estado brasileiro, o lado podre da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21,30],"tags":[],"class_list":["post-18566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaque"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/18566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=18566"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/18566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/18567"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=18566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=18566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=18566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}