{"id":18598,"date":"2019-11-10T18:37:08","date_gmt":"2019-11-10T20:37:08","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=18598"},"modified":"2019-11-10T18:37:08","modified_gmt":"2019-11-10T20:37:08","slug":"lula-solto-abre-campo-para-eleicoes-municipais-serem-mais-ideologicas-em-alagoinhas-por-paulo-dias","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/lula-solto-abre-campo-para-eleicoes-municipais-serem-mais-ideologicas-em-alagoinhas-por-paulo-dias\/","title":{"rendered":"Lula solto abre campo para elei\u00e7\u00f5es municipais serem mais ideol\u00f3gicas em Alagoinhas &#8211; Por Paulo Dias"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A soltura do Lula dever\u00e1 tornar as elei\u00e7\u00f5es municipais mais ideol\u00f3gicas. Sem d\u00favidas, ser\u00e1 quebrada a escrita de que em elei\u00e7\u00f5es municipais n\u00e3o se discutem quest\u00f5es nacionais. At\u00e9 mesmo porque as elei\u00e7\u00f5es municipais t\u00eam grande peso nas elei\u00e7\u00f5es para o congresso dois anos depois. Lula solto ir\u00e1 comandar um ex\u00e9rcito de pessoas que ainda sonham de forma ut\u00f3pica com a implanta\u00e7\u00e3o do socialismo no Brasil, embora o PT, enquanto partido, at\u00e9 aqui, se apresentou mais como um amontoado de sindicalistas, em grande parte, desonestos, usando a imagem m\u00edtica do socialismo s\u00f3 para chegar ao poder.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">O mesmo pragmatismo ocorre na universidade, nos cursos de humanas(alunos e professores), uns lutando por mais verbas para seus projetos,\u00a0 outros pelo \u201cvelho carguinho comissionado\u201d e por verbas para as suas ONGS, os artistas, por sua vez, lutando por polpudos incentivos fiscais. Ainda tem um vasto ex\u00e9rcito de bo\u00eamios, <\/span><i><span style=\"font-weight: 400;\">bons Vivants<\/span><\/i><span style=\"font-weight: 400;\">, rastaf\u00e1ris de boutique, fil\u00f3sofos de bar e &#8220;lacradores&#8221; de todo o tipo no velho estilo \u201cquem n\u00e3o chora n\u00e3o mama\u201d. Em resumo, os defensores da cleptocracia, habitantes da lacrosfera. Tudo \u00e9 por dinheiro e poder.<\/span><\/p><div class=\"newsi-conteudo_19\" id=\"newsi-645156972\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A elei\u00e7\u00e3o municipal \u00e9, na verdade, o primeiro degrau para as elei\u00e7\u00f5es para presidente, governador, deputado, que ocorrem apenas ap\u00f3s dois anos. Isso fica mascarado quando n\u00e3o se discutem quest\u00f5es nacionais(ideol\u00f3gicas) nas elei\u00e7\u00f5es municipais Esse sempre foi um erro que vai cair por terra nas elei\u00e7\u00f5es de 2020 e ser\u00e1 muito saud\u00e1vel. Quem \u00e9 contra o socialismo, o bolivarianismo e o Foro de S\u00e3o Paulo n\u00e3o votar\u00e1 no candidato do PT e similares a prefeito e vereador. Quem \u00e9 contra o &#8220;capitalismo malvado&#8221; n\u00e3o votar\u00e1 na direita(j\u00e1 n\u00e3o votam mesmo). Podemos cortar o mal pela raiz, logo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Em Alagoinhas, Paulo Cezar responde a processo na justi\u00e7a, Joaquim Neto est\u00e1 \u00e0s voltas com uma secret\u00e1ria condenada na justi\u00e7a, surge Fabr\u00edcio Faro como alternativa, mas isso pode dividir os votos da direita e resultar na elei\u00e7\u00e3o da esquerda(corrupta em n\u00edvel nacional) com um m\u00ednimo de votos. Mas ainda temos que lembrar do PT, que quando no poder em Alagoinhas protagonizou alguns fatos, no minimo suspeitos. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Quero relembrar aqui do processo respondido pelo ent\u00e3o prefeito Jose\u00edldo Ramos, hoje deputado federal. Ele recorreu, e, nesse meio tempo, o suposto crime prescreveu. Interessante \u00e9 que o diretor envolvido com os contratos supostamente superfaturados de bandas, objeto da den\u00fancia, concorreu a vereador e foi o \u00fanico candidato do PT(exceto Radiovaldo) a ter bandas(v\u00e1rias) em seus com\u00edcios \u00e0 \u00e9poca. Mais interessante ainda \u00e9 que o fato n\u00e3o foi inserido no processo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">N\u00e3o podemos nos esquecer das suspeitas de superfaturamento na reforma do est\u00e1dio no governo Joseildo, embora nunca levado adiante pelo MP. Misteriosamente, essas den\u00fancias cessaram e, misteriosamente tamb\u00e9m, no mesmo per\u00edodo, Jose\u00edldo obteve 100% de aprova\u00e7\u00e3o de seus projetos na C\u00e2mara de Vereadores, formada por maioria de oposi\u00e7\u00e3o. Ou seja, n\u00e3o tem ningu\u00e9m santo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Outra quest\u00e3o que chama a aten\u00e7\u00e3o \u00e9 que\u00a0<\/span><span style=\"font-weight: 400;\">o deputado Marcelo Freixo(PSOL) estava no palanque de Lula, ap\u00f3s sua soltura, isso deixa margem \u00e0 d\u00favida se o PSOL ter\u00e1 candidatura pr\u00f3pria em 2020 em Alagoinhas, como dizem ou se vir\u00e1 como sat\u00e9lite, em apoio ao petismo.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Paulo Dias \u00e9 jornalista, graduado pela UFBA, especializado em Pedagogia e mestre em Cultura e Literatura pela UNEB. Tem passagens por v\u00e1rios jornais e assessorias de comunica\u00e7\u00e3o em Alagoinhas e Salvador. Atualmente escreve para o site News Infoco<\/strong><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Lula solto abre campo para elei\u00e7\u00f5es municipais serem mais ideol\u00f3gicas em Alagoinhas - Por Paulo Dias' data-link='https:\/\/newsinfoco.com.br\/inicio\/lula-solto-abre-campo-para-eleicoes-municipais-serem-mais-ideologicas-em-alagoinhas-por-paulo-dias\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A soltura do Lula dever\u00e1 tornar as elei\u00e7\u00f5es municipais mais ideol\u00f3gicas. Sem d\u00favidas, ser\u00e1 quebrada a escrita de que em elei\u00e7\u00f5es municipais n\u00e3o se discutem quest\u00f5es nacionais. At\u00e9 mesmo porque as elei\u00e7\u00f5es municipais t\u00eam grande peso nas elei\u00e7\u00f5es para o congresso dois anos depois. Lula solto ir\u00e1 comandar um ex\u00e9rcito de pessoas que ainda sonham [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[165],"tags":[],"class_list":["post-18598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paulo-dias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/18598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=18598"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/18598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/18382"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=18598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=18598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=18598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}