{"id":19079,"date":"2019-12-02T20:22:17","date_gmt":"2019-12-02T22:22:17","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=19079"},"modified":"2019-12-02T20:22:17","modified_gmt":"2019-12-02T22:22:17","slug":"seminario-discute-acoes-para-o-manejo-correto-de-residuos-solidos-em-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/seminario-discute-acoes-para-o-manejo-correto-de-residuos-solidos-em-alagoinhas\/","title":{"rendered":"Semin\u00e1rio discute a\u00e7\u00f5es para o manejo correto de res\u00edduos s\u00f3lidos em Alagoinhas"},"content":{"rendered":"<p style=\"text-align: justify;\">A Prefeitura de Alagoinhas realiza, na pr\u00f3xima quinta-feira (05), semin\u00e1rio sobre a Etapa 4 do Plano de Gest\u00e3o Integrada de Res\u00edduos S\u00f3lidos do Munic\u00edpio (PMGIRS).\u00a0O evento acontece \u00e0s 9h, no Audit\u00f3rio da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e Meio Ambiente SEDEA, localizado \u00e0 Rua Soror Joana Ang\u00e9lica, s\/n, 1\u00ba Andar.<\/p>\n<p style=\"text-align: justify;\">Nesta etapa ser\u00e3o apresentadas as propostas para a gest\u00e3o dos res\u00edduos s\u00f3lidos em Alagoinhas, definidos programas, projetos e a\u00e7\u00f5es, vinculados a um cronograma de execu\u00e7\u00e3o, para o efetivo alcance das metas estabelecidas.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1493244985\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">A elabora\u00e7\u00e3o do Plano de Gest\u00e3o Integrada de Res\u00edduos S\u00f3lidos do Munic\u00edpio (PMGIRS) atende \u00e0s disposi\u00e7\u00f5es da Lei Federal n\u00ba 12.305\/10, e prev\u00ea as metas e programas para o correto manejo de res\u00edduos s\u00f3lidos no munic\u00edpio no horizonte de 25 anos.<\/p>\n<p style=\"text-align: justify;\">O semin\u00e1rio \u00e9 aberto ao p\u00fablico e n\u00e3o h\u00e1 necessidade de inscri\u00e7\u00e3o.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Semin\u00e1rio discute a\u00e7\u00f5es para o manejo correto de res\u00edduos s\u00f3lidos em Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/seminario-discute-acoes-para-o-manejo-correto-de-residuos-solidos-em-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Alagoinhas realiza, na pr\u00f3xima quinta-feira (05), semin\u00e1rio sobre a Etapa 4 do Plano de Gest\u00e3o Integrada de Res\u00edduos S\u00f3lidos do Munic\u00edpio (PMGIRS).\u00a0O evento acontece \u00e0s 9h, no Audit\u00f3rio da Secretaria Municipal de Desenvolvimento Econ\u00f4mico e Meio Ambiente SEDEA, localizado \u00e0 Rua Soror Joana Ang\u00e9lica, s\/n, 1\u00ba Andar. Nesta etapa ser\u00e3o apresentadas as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,30],"tags":[],"class_list":["post-19079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-destaque"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/19079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=19079"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/19079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/19080"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=19079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=19079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=19079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}