{"id":19862,"date":"2020-01-13T17:29:22","date_gmt":"2020-01-13T20:29:22","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=19862"},"modified":"2020-01-13T18:36:04","modified_gmt":"2020-01-13T21:36:04","slug":"impasse-esquerda-contraria-as-mudancas-na-previdencia-nacional-agora-de-frente-com-a-reforma-de-rui-costa","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/impasse-esquerda-contraria-as-mudancas-na-previdencia-nacional-agora-de-frente-com-a-reforma-de-rui-costa\/","title":{"rendered":"Impasse: Esquerda contr\u00e1ria \u00e0s mudan\u00e7as na Previd\u00eancia Nacional, agora de frente com a reforma de Rui Costa"},"content":{"rendered":"<p style=\"text-align: justify;\">O Estado mais petista do Brasil far\u00e1 sua Reforma da Previd\u00eancia, liderada pelo governador petista Rui Costa. Coer\u00eancia nunca foi o forte do partido, mas agora a sigla vai passar por sua prova de fogo, pois estar\u00e1 durante meses no papel de vitrine, quando na reforma de Jair Bolsonaro foi pedra. V\u00e3o espernear para ingl\u00eas ver e depois votar favor\u00e1vel \u00e0 reforma ou v\u00e3o contra o governo como fizeram com Bolsonaro e quebrar o estado? O deputado do PC do B, Daniel Almeida, j\u00e1 come\u00e7ou esperneando. Se posicionou contra a convoca\u00e7\u00e3o extraordin\u00e1ria, que vai custar R$ 3,2 milh\u00f5es ao cofres p\u00fablicos, e contra a falta de di\u00e1logo com a base por parte de Rui Costa. Sindicatos j\u00e1 se movimentam para ficar contra. Bolsonaro colocou o povo nas ruas para lutar a favor da reforma da Previd\u00eancia Federal, e o PT teria o mesmo respaldo junto a seu eleitorado? O PT tem reduto na Bahia para fazer isso, resta saber se vai pagar o pre\u00e7o.<\/p>\n<p style=\"text-align: justify;\">A reforma da Previd\u00eancia Estadual, pode gerar, segundo o governo, uma economia da R$800 milh\u00f5es ano, quase 1\/10 da reforma federal, sinal de que o peso sobre o contribuinte ser\u00e1 grande. Segundo Caio Pimenta, comentarista do programa Primeira M\u00e3o, o PT entra nessa discuss\u00e3o com o \u00f4nus de ter quebrado o pr\u00f3prio Funprev, fundo previdenci\u00e1rio do servidor do estado, e o Planserv, plano de sa\u00fade dos servidores. Rui Costa desmontou o plano de sa\u00fade dos servidores e foi se tratar no S\u00edrio Liban\u00eas, ironizou Caio, indicando que essa novela ser\u00e1 um show de contorcionismo ideol\u00f3gico, como j\u00e1 se tornou comum para os esquerdistas. Daniel Almeida disse que ainda \u00e9 cedo para dizer se os ditos comunistas v\u00e3o votar contra ou a favor do projeto, pois o governo ter\u00e1 que dialogar com seus aliados, bem mais que com seus advers\u00e1rios.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1501218067\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">O PC do B tem dois pr\u00e9-candidatos a prefeito, Ol\u00edvia Santana, Salvador, e Fabr\u00edcio Falc\u00e3o, Vit\u00f3ria da Conquista. Votar a favor da reforma de Rui Costa poder\u00e1 prejudicar futuras candidaturas destes. A convoca\u00e7\u00e3o extraordin\u00e1ria de deputados foi contestada judicialmente. Por decis\u00e3o liminar a tramita\u00e7\u00e3o da PEC est\u00e1 suspensa. O deputado Alex Lima do PSB, vinculado aos vereadores alagoinhenses Anderson Baqueiro e Jorge da Farinha, se posicionou contra a suspens\u00e3o, portanto a favor da aprecia\u00e7\u00e3o em regime de urg\u00eancia do projeto que vai render a cada deputado R$25 mil, uma esp\u00e9cie de hora extra. Isso custar\u00e1 cerca de R$3,2 milh\u00f5es aos cofres estaduais. Um exemplo ruim, vindo de algu\u00e9m que \u00e9 considerado por seus aliados como representante de Alagoinhas na Assembleia Legislativa.<\/p>\n<p style=\"text-align: justify;\">A reforma da previd\u00eancia baiana deve penalizar sobretudo os servidores p\u00fablicos, segundo o deputado Hilton Coelho(PSOL), que n\u00e3o esquece sua origem no funcionalismo.<\/p>\n<p style=\"text-align: justify;\">A reforma da previd\u00eancia estadual foi tema do coment\u00e1rio de Caio Pimenta no programa Primeira M\u00e3o de hoje(13). Acompanhe:<\/p>\n<p><iframe loading=\"lazy\" title=\"Caio Pimenta critica vota\u00e7\u00e3o da PEC da Previdencia Estadual da Bahia sem discutir com servidores\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/CX1BhQytM7Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: right;\">Por Paulo Dias para o News Infoco<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Impasse: Esquerda contr\u00e1ria \u00e0s mudan\u00e7as na Previd\u00eancia Nacional, agora de frente com a reforma de Rui Costa' data-link='https:\/\/newsinfoco.com.br\/inicio\/impasse-esquerda-contraria-as-mudancas-na-previdencia-nacional-agora-de-frente-com-a-reforma-de-rui-costa\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O Estado mais petista do Brasil far\u00e1 sua Reforma da Previd\u00eancia, liderada pelo governador petista Rui Costa. Coer\u00eancia nunca foi o forte do partido, mas agora a sigla vai passar por sua prova de fogo, pois estar\u00e1 durante meses no papel de vitrine, quando na reforma de Jair Bolsonaro foi pedra. V\u00e3o espernear para ingl\u00eas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-19862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/19862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=19862"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/19862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/17418"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=19862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=19862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=19862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}