{"id":19904,"date":"2020-01-14T19:27:10","date_gmt":"2020-01-14T22:27:10","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=19904"},"modified":"2020-01-14T19:27:10","modified_gmt":"2020-01-14T22:27:10","slug":"apos-rui-retirar-pec-da-previdencia-da-al-ba-hilton-coelho-comemora-mais-um-tirano-recuou","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/apos-rui-retirar-pec-da-previdencia-da-al-ba-hilton-coelho-comemora-mais-um-tirano-recuou\/","title":{"rendered":"Ap\u00f3s Rui retirar PEC da Previd\u00eancia da AL-BA, Hilton Coelho comemora: \u2018Mais um tirano recuou\u2019"},"content":{"rendered":"<p style=\"text-align: justify;\">O deputado estadual Hilton Coelho (PSOL) comemorou, na manh\u00e3 desta ter\u00e7a-feira (14), a retirada da proposta de reforma da Previd\u00eancia estadual do Legislativo. A medida foi adotada pelo governo ap\u00f3s o socialista ter suspendido a tramita\u00e7\u00e3o do projeto por meio de uma liminar concedida pela desembargadora Rosita Falc\u00e3o.<\/p>\n<p style=\"text-align: justify;\">\u201cO dia 14 de janeiro de 2020 vai ficar marcado na hist\u00f3ria baiana como o dia em que mais um tirano recuou em face da luta organizada dos trabalhadores. O governador Rui Costa foi obrigado a retirar a Proposta de Emenda Constitucional n\u00ba 158\/2019 e o Projeto de Lei n\u00ba 23.722\/2020. A decis\u00e3o liminar concedida pelo Tribunal de Justi\u00e7a a nosso pedido demonstrou todos os v\u00edcios no procedimento da tramita\u00e7\u00e3o das proposi\u00e7\u00f5es do Executivo no Legislativo\u201d, disse o parlamentar.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3610082921\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">De acordo com Hilton, \u201cal\u00e9m da falta dos estudos atuariais e financeiros que d\u00e3o base \u00e0 reforma, o Executivo n\u00e3o submeteu a proposta ao Conselho Previdenci\u00e1rio do Estado, que \u00e9 \u00f3rg\u00e3o consultivo, deliberativo e de supervis\u00e3o superior, que tem por finalidade a formula\u00e7\u00e3o de normas e diretrizes para a execu\u00e7\u00e3o da pol\u00edtica previdenci\u00e1ria do Estado, para seus servidores e pensionistas, tem a seguinte composi\u00e7\u00e3o, de acordo com a Lei Estadual n\u00ba 10.955\/07\u201d.<\/p>\n<p style=\"text-align: justify;\">O psolita tamb\u00e9m contestou do l\u00edder do governo na AL-BA, deputado Rosemberg Pinto (PT) afirmando que \u201cn\u00e3o diminu\u00edmos o Poder Legislativo ao entrarmos com o Mandado de Seguran\u00e7a, ao contr\u00e1rio, possibilitou a amplia\u00e7\u00e3o do debate, for\u00e7ando o Executivo a perceber que o processo \u00e9 equivocado e levaria a uma a\u00e7\u00e3o direta de inconstitucionalidade, com poss\u00edvel ganho de causa para os trabalhadores\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cA estrat\u00e9gia de utilizar o Judici\u00e1rio como garantidor do devido processo legislativo foi t\u00e1tica utilizada pelo Partido dos Trabalhadores durante toda a sua hist\u00f3ria, na pr\u00f3pria tramita\u00e7\u00e3o da Reforma da Previd\u00eancia de Temer e Bolsonaro. Al\u00e9m disso, em S\u00e3o Paulo, a PEC e o PL da reforma da Previd\u00eancia encontram-se parados por a\u00e7\u00e3o judicial proposta pelo deputado Em\u00eddio de Souza (PT). A fala do governador Rui Costa e de seus seguidores tenta mascarar os enormes erros e incompet\u00eancias cometidos na elabora\u00e7\u00e3o das propostas e na tramita\u00e7\u00e3o na AL-BA\u201d, acrescentou.<\/p>\n<p style=\"text-align: justify;\">Hilton tamb\u00e9m voltou a defender que o governo discuta o projeto com os servidores. \u201cA cada dia se torna mais atual o nosso hino estadual que diz \u2018com tiranos n\u00e3o combinam brasileiros cora\u00e7\u00f5es\u2019. Esperamos que o Executivo, a exemplo do que ocorre no Maranh\u00e3o, crie comit\u00ea para discuss\u00e3o de poss\u00edveis altera\u00e7\u00f5es na Previd\u00eancia do Estado, com a participa\u00e7\u00e3o das entidades representativas dos servidores, e n\u00e3o submeta nova proposta no recesso parlamentar, novamente de forma apressada. J\u00e1 foi derrotado uma vez e sempre ser\u00e1 se tentar retirar direitos do funcionalismo estadual\u201d, pontuou.<\/p>\n<p style=\"text-align: justify;\">\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ap\u00f3s Rui retirar PEC da Previd\u00eancia da AL-BA, Hilton Coelho comemora: \u2018Mais um tirano recuou\u2019' data-link='https:\/\/newsinfoco.com.br\/inicio\/apos-rui-retirar-pec-da-previdencia-da-al-ba-hilton-coelho-comemora-mais-um-tirano-recuou\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Hilton Coelho (PSOL) comemorou, na manh\u00e3 desta ter\u00e7a-feira (14), a retirada da proposta de reforma da Previd\u00eancia estadual do Legislativo. A medida foi adotada pelo governo ap\u00f3s o socialista ter suspendido a tramita\u00e7\u00e3o do projeto por meio de uma liminar concedida pela desembargadora Rosita Falc\u00e3o. \u201cO dia 14 de janeiro de 2020 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19,30],"tags":[],"class_list":["post-19904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-destaque"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/19904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=19904"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/19904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/19905"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=19904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=19904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=19904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}