{"id":20662,"date":"2020-03-18T09:49:36","date_gmt":"2020-03-18T12:49:36","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=20662"},"modified":"2020-03-18T09:49:36","modified_gmt":"2020-03-18T12:49:36","slug":"prefeito-joaquim-neto-anuncia-decreto-com-regras-de-combate-ao-coronavirus-em-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/prefeito-joaquim-neto-anuncia-decreto-com-regras-de-combate-ao-coronavirus-em-alagoinhas\/","title":{"rendered":"Prefeito Joaquim Neto anuncia decreto com regras de combate ao coronav\u00edrus em Alagoinhas"},"content":{"rendered":"<p style=\"text-align: justify;\">O prefeito Joaquim Neto reuniu a imprensa de Alagoinhas na noite de ontem (17) para anunciar que hoje (18) ser\u00e1 publicado uma portaria regulando o funcionamento de uma s\u00e9rie de medidas que foram tomadas com vistas ao combate do coronav\u00edrus no munic\u00edpio. Al\u00e9m do prefeito estavam presentes os secret\u00e1rios da Sa\u00fade, Rosania Rabelo e de Governo e Comunica\u00e7\u00e3o, Gustavo Carmo.<\/p>\n<p style=\"text-align: justify;\">Dentre as medidas est\u00e3o:<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3471480167\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<ul>\n<li>Suspens\u00e3o das aulas em escolas p\u00fablicas e privadas por 15 dias<\/li>\n<li>Visitas ao lar dos idosos no igual per\u00edodo est\u00e3o proibidas<\/li>\n<li>Diminui\u00e7\u00e3o do fluxo de pessoas em casas lot\u00e9ricas e bancos, dist\u00e2ncia m\u00ednima de 1,80 de uma pessoa para outra<\/li>\n<li>Bares e restaurantes ter\u00e3o que obedecer dist\u00e2ncia m\u00ednima entre uma mesa e outra de 1,80<\/li>\n<li>Todos os estabelecimentos devem disponibilizar \u00e1lcool gel<\/li>\n<li>Guarda Municipal e funcion\u00e1rios das \u00e1reas de sa\u00fade, f\u00e9rias e licen\u00e7as est\u00e3o suspensas. Os que j\u00e1 est\u00e3o de f\u00e9rias podem ser convocados a qualquer momento para retornarem \u00e0s suas atividades<\/li>\n<li>Servidores p\u00fablicos municipais acima de 60 anos ser\u00e3o tamb\u00e9m dispensados de suas atividades por 15 dias<\/li>\n<li>Atendimentos em estabelecimentos p\u00fablicos e privados de sa\u00fade devem ser previamente agendados<\/li>\n<li>Suspens\u00e3o de qualquer tipo de evento p\u00fablico ou privado que venha comportar a partir de 50 pessoas<\/li>\n<li>Cultos e missas est\u00e3o inclu\u00eddos nestes dispositivos<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">O decreto ser\u00e1 publicado no decorrer do dia e uma nova avalia\u00e7\u00e3o ser\u00e1 feita a partir do dia 2 de abril, per\u00edodo em que se encerra o decreto, podendo ser ampliado o prazo ou retomadas as atividades normalmente, a depender do grau de contamina\u00e7\u00e3o pelo coronav\u00edrus.<\/p>\n<p style=\"text-align: right;\">GazetadosMunicipios com a colabora\u00e7\u00e3o de Marcos Arag\u00e3o<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Prefeito Joaquim Neto anuncia decreto com regras de combate ao coronav\u00edrus em Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/prefeito-joaquim-neto-anuncia-decreto-com-regras-de-combate-ao-coronavirus-em-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O prefeito Joaquim Neto reuniu a imprensa de Alagoinhas na noite de ontem (17) para anunciar que hoje (18) ser\u00e1 publicado uma portaria regulando o funcionamento de uma s\u00e9rie de medidas que foram tomadas com vistas ao combate do coronav\u00edrus no munic\u00edpio. Al\u00e9m do prefeito estavam presentes os secret\u00e1rios da Sa\u00fade, Rosania Rabelo e de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[167],"tags":[],"class_list":["post-20662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/20662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=20662"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/20662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/20663"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=20662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=20662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=20662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}