{"id":20883,"date":"2020-04-09T17:11:52","date_gmt":"2020-04-09T20:11:52","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=20883"},"modified":"2020-04-09T17:13:21","modified_gmt":"2020-04-09T20:13:21","slug":"mandetta-nao-e-um-santo-nem-bolsonaro-e-o-capeta-que-a-globo-pinta-por-paulo-dias","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/mandetta-nao-e-um-santo-nem-bolsonaro-e-o-capeta-que-a-globo-pinta-por-paulo-dias\/","title":{"rendered":"Mandetta n\u00e3o \u00e9 um santo, nem Bolsonaro \u00e9 o capeta que a Globo pinta &#8211; Por Paulo Dias"},"content":{"rendered":"<p style=\"text-align: justify;\">Luiz Henrique Mandetta, ministro da Sa\u00fade, por enquanto, est\u00e1 longe de ser um santo, assim como Jair Messias Bolsonaro, presidente que leva multid\u00f5es \u00e0s ruas, n\u00e3o \u00e9 o dem\u00f4nio que a Rede Globo tenta pintar incansavelmente com seu antijornalismo. Onde Mandetta errou?<\/p>\n<ol style=\"text-align: justify;\">\n<li>Divergiu, claramente e sem a menor cerim\u00f4nia, de Bolsonaro, seu chefe, quanto ao isolamento(quarentena).<\/li>\n<li>Conversava bonito, mas resolvia pouco. Priorizou negociar com a China e n\u00e3o procurou nenhuma alternativa dom\u00e9stica com a ind\u00fastria nacional.<\/li>\n<li>Se posicionou como salvador da p\u00e1tria quando nem infectologista \u00e9, escondia os m\u00e9ritos de Bolsonaro.<\/li>\n<li>N\u00e3o incentivou o uso da cloroquina que poderia ter salvado centenas de vidas.<\/li>\n<li>Tem um passado marcado por den\u00fancia de corrup\u00e7\u00e3o<\/li>\n<li>Fez conluio com secret\u00e1rios contr\u00e1rios ao presidente, liderados por D\u00f3ria, com os colegas do DEM, Caiado, Maia e Alcolumbre, que por sua vez s\u00e3o mancomunados com a banda podre do STF e com a m\u00eddia podre.<\/li>\n<li>Fez reuni\u00e3o virtual com Maia, Alcolumbre e D\u00f3ria, pol\u00edticos que tentam inviabilizar o governo Bolsonaro desde o seu primeiro dia.<\/li>\n<li>Passou por cima do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores e do presidente ao manifestar apoio \u00e0 China, pa\u00eds respons\u00e1vel por toda essa crise sanit\u00e1ria mundial, hoje questionado abertamente por pot\u00eancias como EUA e Jap\u00e3o.<\/li>\n<li>Mandetta pertence ao grupo que est\u00e1 vendendo o Brasil para a China.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Sem contar que j\u00e1 existem fortes suspeitas de que a quarentena \u00e9 apenas um meio de viabilizar livremente compras question\u00e1veis sem licita\u00e7\u00e3o e que o coronav\u00edrus j\u00e1 virou um grande neg\u00f3cio para muita gente. O pa\u00eds est\u00e1 de quatro para a China, seu embaixador faz o que quer e diz o que quer aqui dentro. Na Europa, n\u00e3o \u00e9 muito diferente, o trabalho escravo chin\u00eas virou sua nova mina de ouro, continente que enriqueceu sugando os demais continentes. Nada de novo, mas muito perigoso, dessa vez, em vista da China ser uma ferrenha ditadura e ter poucos escr\u00fapulos ou nenhum.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1138255950\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\"><strong><b>A CLOROQUINA<\/b><\/strong> &#8211; Especula-se que a crise Bolsonaro\/Mandetta tem dois pilares: a economia e a cloroquina. Quando surgiu o boato de que o presidente demitiria o ministro na segunda(06), a gota d\u2019\u00e1gua estava relacionada com o medicamento. Bolsonaro levou para dentro do Planalto, nesse dia, uma especialista que disse que o protocolo de Mandetta estava errado e estava deixando de salvar muitas vidas, por qu\u00ea? Porque a cloroquina estava sendo administrada apenas em pacientes graves(terminais), no entanto, segundo a conselheira de Bolsonaro, sua efic\u00e1cia s\u00f3 ocorre, quando aplicada no in\u00edcio dos sintomas. Especula-se tamb\u00e9m, segundo Caio Coppola, da CNN, que o rem\u00e9dio recomendado no protocolo de Mandetta para casos leves custa R$ 250.00 e que a cloroquina custa R$ 1,00 por comprimido. Pode haver interesse em favorecer o laborat\u00f3rio em quest\u00e3o e nisso pode existir corrup\u00e7\u00e3o, algo sobre o qual o ministro j\u00e1 foi acusado, bem como Maia e Alcolumbre, seus parceiros de DEM.<\/p>\n<p style=\"text-align: justify;\">As mancadas de Mandetta j\u00e1 v\u00eam de longe, afirma-se que ele liberou, em dezembro, no apagar das luzes, \u00a0R$ 1 bi para publicidade, contrariando uma das principais orienta\u00e7\u00f5es de Bolsonaro. Tamb\u00e9m n\u00e3o apresentou nenhum brilhantismo na condu\u00e7\u00e3o da pasta at\u00e9 ent\u00e3o. Poderia ter comprado respiradores no in\u00edcio da epidemia por precau\u00e7\u00e3o, nenhum mal faria. Agora com a crise, resolveu interligar todos os PSFs por internet, por que n\u00e3o fez antes, algo t\u00e3o \u00f3bvio? Em Alagoinhas, os PSFs nem telefone t\u00eam.<\/p>\n<p style=\"text-align: justify;\">Ainda sobre a cloroquina, relegada a segundo plano por Mandetta, pelos governadores e pela m\u00eddia, houve uma reviravolta de ontem para hoje(08), quando descobriu-se que o gestor da crise em S\u00e3o Paulo, o homem de confian\u00e7a do <strong><b>Ditad\u00f3ria<\/b><\/strong>, David Uip, se curou da Covid-19 com a cloroquina prescrita por ele mesmo. Por\u00e9m quando questionado por Datena, ontem(07) quis omitir o fato em uma atitude amplamente questionada sob o ponto de vista da \u00e9tica e da pr\u00f3pria \u00e9tica m\u00e9dica e do servi\u00e7o p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">O mesmo aconteceu com outro m\u00e9dico renomado, Roberto Kalil, que escondeu Igualmente o tratamento com a cloroquina e depois por press\u00e3o do p\u00fablico, manifesta nas redes sociais, teve que admitir o procedimento. A resist\u00eancia e a m\u00e1scara de Mandetta caiu por terra. O garoto de voz suave, quase sedutora, estava querendo o estrelato, sim, e os votos dos incautos. Verdadeiramente deu amplos motivos para ser exonerado, o maior deles, falta de fidelidade, motivada por uma ambi\u00e7\u00e3o desmedida. Mandetta e D\u00f3ria estavam jogando o mesmo jogo. A m\u00e3o de Deus na hist\u00f3ria \u00e9 algo impressionante, quando o capeta est\u00e1 muito solto, ele sempre puxa a corda. S\u00f3 Jesus na causa.<\/p>\n<p style=\"text-align: justify;\"><strong>Paulo Dias \u00e9 jornalista, graduado pela UFBA, especializado em Pedagogia e mestre em Cultura e Literatura pela UNEB. Tem passagens por v\u00e1rios jornais e assessorias de comunica\u00e7\u00e3o em Alagoinhas e Salvador. Atualmente escreve para o site News Infoco<\/strong><\/p>\n<div class=\"share-to-whatsapp-wrapper\"><\/div>\n<div class=\"share-to-whatsapp-wrapper\"><\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Mandetta n\u00e3o \u00e9 um santo, nem Bolsonaro \u00e9 o capeta que a Globo pinta - Por Paulo Dias' data-link='https:\/\/newsinfoco.com.br\/inicio\/mandetta-nao-e-um-santo-nem-bolsonaro-e-o-capeta-que-a-globo-pinta-por-paulo-dias\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Luiz Henrique Mandetta, ministro da Sa\u00fade, por enquanto, est\u00e1 longe de ser um santo, assim como Jair Messias Bolsonaro, presidente que leva multid\u00f5es \u00e0s ruas, n\u00e3o \u00e9 o dem\u00f4nio que a Rede Globo tenta pintar incansavelmente com seu antijornalismo. Onde Mandetta errou? Divergiu, claramente e sem a menor cerim\u00f4nia, de Bolsonaro, seu chefe, quanto ao [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[165],"tags":[],"class_list":["post-20883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paulo-dias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/20883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=20883"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/20883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/20884"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=20883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=20883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=20883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}