{"id":21325,"date":"2020-05-30T17:19:58","date_gmt":"2020-05-30T20:19:58","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=21325"},"modified":"2020-05-30T18:04:25","modified_gmt":"2020-05-30T21:04:25","slug":"homem-fica-preso-em-porta-giratoria-do-banco-do-brasil-em-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/homem-fica-preso-em-porta-giratoria-do-banco-do-brasil-em-alagoinhas\/","title":{"rendered":"Homem fica preso em porta girat\u00f3ria do Banco do Brasil em Alagoinhas"},"content":{"rendered":"<p style=\"text-align: justify;\">Um fato inusitado aconteceu na manh\u00e3 deste s\u00e1bado(30) em Alagoinhas. Um homem ficou preso por mais de uma hora na porta girat\u00f3ria da agencia do Banco do Brasil, localizada na rua Luiz Viana.<\/p>\n<p style=\"text-align: justify;\">Conforme apurou este site News Infoco, aparentemente o homem, ao inv\u00e9s de adentrar na porta principal da ag\u00eancia, preferiu adentrar pela porta girat\u00f3ria, que travou assim que ele entrou. Aos fim de semana as agencias do Banco do Brasil n\u00e3o funcionam, apenas os caixas eletr\u00f4nicos. Sem nenhum funcion\u00e1rio do banco por perto, o homem ficou preso aguardando por ajuda.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1030121092\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21327\" src=\"http:\/\/newsinfoco.com.br\/wp-content\/uploads\/2020\/05\/IMG-20200530-WA0218.jpg\" alt=\"\" width=\"337\" height=\"600\" srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2020\/05\/IMG-20200530-WA0218.jpg 337w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2020\/05\/IMG-20200530-WA0218-169x300.jpg 169w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2020\/05\/IMG-20200530-WA0218-236x420.jpg 236w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/p>\n<p style=\"text-align: justify;\">Por sorte do rapaz, o prefeito do munic\u00edpio, Joaquim Neto(PSD), passou pelo local, acompanhado por seu amigo Duda dos Churros, e ao ver a situa\u00e7\u00e3o comunicou \u00e0 gerencia do banco que enviou um funcion\u00e1rio para resolver o problema e soltar o cidad\u00e3o.<\/p>\n<p style=\"text-align: right;\">Por Caio Pimenta para o News Infoco<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Homem fica preso em porta girat\u00f3ria do Banco do Brasil em Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/homem-fica-preso-em-porta-giratoria-do-banco-do-brasil-em-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Um fato inusitado aconteceu na manh\u00e3 deste s\u00e1bado(30) em Alagoinhas. Um homem ficou preso por mais de uma hora na porta girat\u00f3ria da agencia do Banco do Brasil, localizada na rua Luiz Viana. Conforme apurou este site News Infoco, aparentemente o homem, ao inv\u00e9s de adentrar na porta principal da ag\u00eancia, preferiu adentrar pela porta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[167],"tags":[],"class_list":["post-21325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/21325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=21325"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/21325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/21326"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=21325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=21325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=21325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}