{"id":22603,"date":"2020-11-07T11:41:22","date_gmt":"2020-11-07T14:41:22","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=22603"},"modified":"2020-11-07T11:41:22","modified_gmt":"2020-11-07T14:41:22","slug":"jovem-acusa-seguranca-do-comite-de-paulo-cezar-de-agredi-lo-com-chutes-e-socos","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/jovem-acusa-seguranca-do-comite-de-paulo-cezar-de-agredi-lo-com-chutes-e-socos\/","title":{"rendered":"Jovem acusa seguran\u00e7a do comit\u00ea de Paulo Cezar de agredi-lo com chutes e socos"},"content":{"rendered":"<p style=\"text-align: justify;\">[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]O vale-tudo nas elei\u00e7\u00f5es municipais de Alagoinhas segue a todo o vapor. Se a democracia preconiza o debate de ideias, aqui em Alagoinhas as agress\u00f5es por quest\u00f5es politicas, sejam elas f\u00edsicas ou verbais, seguem envergonhando.<\/p>\n<p style=\"text-align: justify;\">Ontem(06), por exemplo, esteve na delegacia de Alagoinhas, um jovem, de 27 anos, que foi v\u00edtima de um ataque violento. No boletim de ocorr\u00eancia resgistrado sob o n\u00famero 1\u00aaDT ALAGOINHAS-BO-20-03903, ao qual o site News Infoco teve acesso, o jovem, de iniciais M.B.S, que ter\u00e1 o seu nome preservado por quest\u00f5es de seguran\u00e7a, alega ter sido agredido com murros e chutes que atingiram seu rosto e suas costelas. A a\u00e7\u00e3o, segundo o jovem, teria sido realizada por um homem identificado por ele como seguran\u00e7a do comit\u00ea de campanha do candidato Paulo Cezar.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3592181929\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\">O motivo da a\u00e7\u00e3o do seguran\u00e7a, de acordo com o boletim de ocorr\u00eancia, \u00e9 t\u00e3o est\u00fapido quanto o fato em si.\u00a0 O rapaz relata que estava do outro lado da rua, em frente ao comit\u00ea do candidato Joaquim Neto, quando olhou em dire\u00e7\u00e3o ao comit\u00ea do candidato Paulo Cezar. O seguran\u00e7a o teria questionado o motivo dele estar olhando para l\u00e1. O jovem est\u00e3o diz ter explicado que n\u00e3o olhava para o comit\u00ea e sim que procurava uma pessoa que ouvera marcado um encontro com ele naquele local. A partir dali, o seguran\u00e7a teria come\u00e7ado o verdeiro &#8220;show de pancadaria&#8221;, descarregando sua ira sobre o rapaz.<\/p>\n<p>Os ataques por motiva\u00e7\u00e3o politica tem se tornado corriqueiro na cidade.<\/p>\n<p style=\"text-align: justify;\">Integrantes da imprensa, inclusive este News Infoco, tem sido v\u00edtimas de ataques virtuais promovidas por pessoas que se dizem apoiadores do candidato Paulo Cezar. A pr\u00f3pria campanha Paulo Cezar tem protagonizado atitudes, como o ajuizamento de a\u00e7\u00f5es contra integrantes da imprensa, principalmente aqueles que questionam seus problemas judiciais, a fuga dos debates, e a falta de propostas politicas. A Associa\u00e7\u00e3o Nacional e Internacional de Imprensa(ANI) chegou a emitir uma nota de desagravo contra a postura da candidatura demista na cidade.<\/p>\n<p style=\"text-align: justify;\">Na \u00faltima sexta-feira(30) uma confus\u00e3o envolvendo apoiadores das campanhas Paulo Cezar e Joaquim Neto na regi\u00e3o da Pra\u00e7a Santa Izabel tamb\u00e9m foi registada.<\/p>\n<p>E assim vai seguindo Alagoinhas rumo ao dia 15 de novembro.<\/p>\n<p style=\"text-align: right;\">Por Caio Pimenta para o News Infoco<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Jovem acusa seguran\u00e7a do comit\u00ea de Paulo Cezar de agredi-lo com chutes e socos' data-link='https:\/\/newsinfoco.com.br\/inicio\/jovem-acusa-seguranca-do-comite-de-paulo-cezar-de-agredi-lo-com-chutes-e-socos\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>[sg_popup id=&#8221;11418&#8243; event=&#8221;inherit&#8221;][\/sg_popup]O vale-tudo nas elei\u00e7\u00f5es municipais de Alagoinhas segue a todo o vapor. Se a democracia preconiza o debate de ideias, aqui em Alagoinhas as agress\u00f5es por quest\u00f5es politicas, sejam elas f\u00edsicas ou verbais, seguem envergonhando. Ontem(06), por exemplo, esteve na delegacia de Alagoinhas, um jovem, de 27 anos, que foi v\u00edtima de um [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[167],"tags":[],"class_list":["post-22603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/22603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=22603"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/22603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/22604"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=22603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=22603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=22603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}