{"id":2309,"date":"2018-04-10T14:53:09","date_gmt":"2018-04-10T17:53:09","guid":{"rendered":"http:\/\/newsinfoco.com.br\/?p=2309"},"modified":"2018-04-10T14:53:09","modified_gmt":"2018-04-10T17:53:09","slug":"mark-zuckerberg-assume-culpa-em-declaracao-para-o-congresso-norte-americano","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/mark-zuckerberg-assume-culpa-em-declaracao-para-o-congresso-norte-americano\/","title":{"rendered":"Mark Zuckerberg assume culpa em declara\u00e7\u00e3o para o Congresso Norte-Americano"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Pr\u00f3ximo do depoimento de Mark Zuckerberg, fundador do\u00a0<strong>Facebook<\/strong>, ao congresso norte-americano, o Comit\u00ea de Energia e Com\u00e9rcio da C\u00e2mara dos Deputados dos Estados Unidos divulgou o comunicado preparado pelo CEO da rede social. Nele, Zuckerberg explica que o Facebook sempre foi uma organiza\u00e7\u00e3o otimista, concentrando-se em conectar pessoas e dar-lhes voz. Entretanto, o executivo tamb\u00e9m admite que a sua linha de pensamento idealista pode ter cegado a companhia para poss\u00edveis abusos do conjunto de ferramentas do Facebook por desenvolvedores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">No depoimento por escrito, divulgado na segunda-feira (9), Zuckerberg diz que a rede social n\u00e3o fez o suficiente para evitar o mau uso e chamou a responsabilidade a si.<\/span><\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3857337739\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">\u201cAgora est\u00e1 claro que n\u00e3o fizemos o suficiente para evitar que essas ferramentas fossem usadas para o mal tamb\u00e9m. Isso vale para not\u00edcias falsas, interfer\u00eancia estrangeira em elei\u00e7\u00f5es e discursos de \u00f3dio, mas tamb\u00e9m para desenvolvedores e privacidade de dados. N\u00e3o tivemos uma vis\u00e3o ampla o suficiente da nossa responsabilidade, e isso foi um grande erro. Foi um erro meu e eu sinto muito. Eu comecei o Facebook, conduzo e sou respons\u00e1vel pelo que acontece aqui\u201d, escreveu o Mark Zuckerberg, em \u201cmea culpa\u201d p\u00fablico ao Congresso dos Estados Unidos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A \u00edntegra da declara\u00e7\u00e3o tamb\u00e9m aborda o esc\u00e2ndalo envolvendo a Cambridge Analytica e a interfer\u00eancia eleitoral russa em 2016, explicando detalhadamente o que aconteceu em cada situa\u00e7\u00e3o e o que o Facebook est\u00e1 fazendo \u2014 agora, dois anos depois \u2014\u00a0 para resolver esses problemas. Leia a declara\u00e7\u00e3o completa neste\u00a0<a class=\"external-link\" style=\"color: #000000;\" href=\"http:\/\/idgnow.com.br\/internet\/2018\/04\/09\/scribd.com\/document\/375916863\/Zuckerberg-Statement-to-Congress\"><strong>link<\/strong><\/a>, em ingl\u00eas.<\/span><\/p>\n<div>\n<div style=\"text-align: justify;\"><span style=\"color: #000000;\">Ele tamb\u00e9m disse que os principais investimentos do Facebook em seguran\u00e7a em raz\u00e3o desses acontecimentos v\u00e3o impactar significativamente na lucratividade da companhia daqui para frente.\u00a0<\/span><\/div>\n<div><\/div>\n<\/div>\n<h6 style=\"text-align: right;\"><span style=\"color: #999999;\">Fonte:Tecmundo<\/span><\/h6>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Mark Zuckerberg assume culpa em declara\u00e7\u00e3o para o Congresso Norte-Americano' data-link='https:\/\/newsinfoco.com.br\/inicio\/mark-zuckerberg-assume-culpa-em-declaracao-para-o-congresso-norte-americano\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Pr\u00f3ximo do depoimento de Mark Zuckerberg, fundador do\u00a0Facebook, ao congresso norte-americano, o Comit\u00ea de Energia e Com\u00e9rcio da C\u00e2mara dos Deputados dos Estados Unidos divulgou o comunicado preparado pelo CEO da rede social. Nele, Zuckerberg explica que o Facebook sempre foi uma organiza\u00e7\u00e3o otimista, concentrando-se em conectar pessoas e dar-lhes voz. Entretanto, o executivo tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-e-tecnologia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/2309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=2309"}],"version-history":[{"count":0,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/2309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/2310"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=2309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=2309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=2309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}