{"id":29032,"date":"2022-02-23T11:37:55","date_gmt":"2022-02-23T14:37:55","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=29032"},"modified":"2022-02-23T11:37:55","modified_gmt":"2022-02-23T14:37:55","slug":"apos-pedido-de-vistas-a-projeto-de-concessao-de-terreno-a-dore-refrigerantes-forca-empresarial-de-alagoinhas-promete-mobilizacao-pela-aprovacao-da-materia","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/apos-pedido-de-vistas-a-projeto-de-concessao-de-terreno-a-dore-refrigerantes-forca-empresarial-de-alagoinhas-promete-mobilizacao-pela-aprovacao-da-materia\/","title":{"rendered":"Ap\u00f3s pedido de vistas a projeto de concess\u00e3o de terreno \u00e0 Dore Refrigerantes, For\u00e7a Empresarial de Alagoinhas promete mobiliza\u00e7\u00e3o pela aprova\u00e7\u00e3o da mat\u00e9ria"},"content":{"rendered":"<p>Ap\u00f3s o pedido de vistas solicitado pela base do Governo na C\u00e2mara no dia de ontem(22) suspender a vota\u00e7\u00e3o da concess\u00e3o do terreno para instala\u00e7\u00e3o da Dore Refrigerantes, a For\u00e7a Empresarial de Alagoinhas(movimento composto por ACIA, Sicom\u00e9rcio e CDL) articula uma grande mobiliza\u00e7\u00e3o em prol da aprova\u00e7\u00e3o do projeto. A informa\u00e7\u00e3o foi dada pelo presidente da Associa\u00e7\u00e3o Comercial e Industrial de Alagoinhas, Jos\u00e9 Carlos Garcia Teles, em entrevista concedida ao programa Primeira M\u00e3o, da r\u00e1dio Ouro Negro 100,5 FM, na manh\u00e3 de hoje(23).<\/p>\n<p>O projeto de concess\u00e3o, contendo apenas 2 p\u00e1ginas, tramita na Casa Legislativa Municipal h\u00e1 2 meses. Ontem a Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a, presidida pelo oposicionista Luciano Almeida(DEM), apresentou o parecer que foi aprovado em plen\u00e1rio.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2563775628\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Por\u00e9m, a Comiss\u00e3o de Or\u00e7amento, presidida pelo l\u00edder do Governo, Anderson Baqueiro(DEM), pediu vistas ao projeto, sob a justificativa que necessitava de mais informa\u00e7\u00f5es sobre a mat\u00e9ria. O pedido de vista foi aprovado por 9 votos a 5, com amplo apoio da bancada governista.<\/p>\n<p>O fato da bancada governista procrastinar a aprecia\u00e7\u00e3o da mat\u00e9ria revoltou a classe empresarial que pela manh\u00e3 recebeu uma mensagem do presidente da Casa, Cleto da Banana(PSD), cancelando uma reuni\u00e3o pr\u00e9-agendada com representantes da classe, com a promessa de que a mat\u00e9ria seria colocado em vota\u00e7\u00e3o j\u00e1 na sess\u00e3o de ontem a tarde.<\/p>\n<p>Jos\u00e9 Carlos cobrou do prefeito Joaquim Neto o convencimento da base governista, j\u00e1 que a oposi\u00e7\u00e3o anunciou publicamente na sess\u00e3o que havia fechado quest\u00e3o pela aprova\u00e7\u00e3o do projeto.<\/p>\n<p>O presidente da ACIA questionou se o prefeito realmente queria a celeridade do processo e demonstrou preocupa\u00e7\u00e3o com a demora na aprecia\u00e7\u00e3o do projeto que pode fazer com que os investidores troquem Alagoinhas por outro munic\u00edpio.<\/p>\n<p>A instala\u00e7\u00e3o de uma unidade da empresa Dore Refrigerantes na cidade gerar\u00e1 250 empregos diretos, fora os indiretos. Na entrevista, Jos\u00e9 Carlos afirmou que com a chegada da f\u00e1brica e com o consequente aumento da gera\u00e7\u00e3o de emprego e renda na cidade, o com\u00e9rcio vender\u00e1 mais, fazendo com que o setor tamb\u00e9m empregue mais gente. De acordo com ele, a atitude da base governista trabalha contra o desenvolvimento de Alagoinhas.<\/p>\n<p>Ele anunciou que a classe empresarial j\u00e1 se re\u00fane com outras entidades representativas para que seja formada uma grande mobiliza\u00e7\u00e3o no munic\u00edpio para cobrar a vota\u00e7\u00e3o da mat\u00e9ria o mais breve poss\u00edvel.<\/p>\n<p>Por Caio Pimenta para o News Infoco<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ap\u00f3s pedido de vistas a projeto de concess\u00e3o de terreno \u00e0 Dore Refrigerantes, For\u00e7a Empresarial de Alagoinhas promete mobiliza\u00e7\u00e3o pela aprova\u00e7\u00e3o da mat\u00e9ria' data-link='https:\/\/newsinfoco.com.br\/inicio\/apos-pedido-de-vistas-a-projeto-de-concessao-de-terreno-a-dore-refrigerantes-forca-empresarial-de-alagoinhas-promete-mobilizacao-pela-aprovacao-da-materia\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s o pedido de vistas solicitado pela base do Governo na C\u00e2mara no dia de ontem(22) suspender a vota\u00e7\u00e3o da concess\u00e3o do terreno para instala\u00e7\u00e3o da Dore Refrigerantes, a For\u00e7a Empresarial de Alagoinhas(movimento composto por ACIA, Sicom\u00e9rcio e CDL) articula uma grande mobiliza\u00e7\u00e3o em prol da aprova\u00e7\u00e3o do projeto. A informa\u00e7\u00e3o foi dada pelo presidente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-29032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/29032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=29032"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/29032\/revisions"}],"predecessor-version":[{"id":29034,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/29032\/revisions\/29034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/29033"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=29032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=29032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=29032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}