{"id":31061,"date":"2022-08-06T12:08:37","date_gmt":"2022-08-06T15:08:37","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=31061"},"modified":"2022-08-06T12:08:37","modified_gmt":"2022-08-06T15:08:37","slug":"com-apoio-da-prefeitura-os-eventos-esportivos-marathon-bike-e-marathon-night-run-agitam-alagoinhas-neste-final-de-semana","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/com-apoio-da-prefeitura-os-eventos-esportivos-marathon-bike-e-marathon-night-run-agitam-alagoinhas-neste-final-de-semana\/","title":{"rendered":"Com apoio da Prefeitura, os eventos esportivos Marathon Bike e Marathon Night Run agitam Alagoinhas neste final de semana"},"content":{"rendered":"<p>Neste final de semana, a agenda esportiva de Alagoinhas ser\u00e1 movimentada. Com 850 atletas inscritos de todo o pa\u00eds, no domingo (07), munic\u00edpio ir\u00e1 realizar a 16\u00aa Marathon Bike, uma das mais tradicionais provas do Montain Bike nordestino. Para completar a festa do esporte, no s\u00e1bado (06), acontece a 7\u00aa edi\u00e7\u00e3o da Marathon Night Run (para corredores amadores e profissionais), prova com percurso de 5Km e 10Km, e que contar\u00e1 com 550 participantes.<\/p>\n<p>A ideia \u00e9 unir praticantes do esporte, iniciantes e entusiastas, por meio de um grande evento, que contar\u00e1 com estandes de expositores, \u00e1rea de alimenta\u00e7\u00e3o, e outros espa\u00e7os. E para garantir suporte total \u00e0s competi\u00e7\u00f5es, a Prefeitura participa da iniciativa, com apoio da Secretaria de Cultura, Esporte e Turismo (SECET ), Superintend\u00eancia Municipal de Transporte e Tr\u00e2nsito (SMTT), da Guarda Municipal, da Secretaria Municipal de Comunica\u00e7\u00e3o (SECOM) e da Secretaria Municipal de Sa\u00fade (SESAU), que disponibilizar\u00e1 duas ambul\u00e2ncias.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2291271874\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A largada da 16\u00ba Marathon Bike acontecer\u00e1 \u00e0s 8h, em frente \u00e0 Pra\u00e7a dos Esportes, localizada na Avenida Lu\u00eds Viana, e que ser\u00e1 inaugurada \u00e0s 17h deste s\u00e1bado (06). Com percursos de 30km, 50km e 70 km, o evento integra, por meio de convite, o Ranking brasileiro da modalidade XCM de Montain Bike e o Ranking baiano XCM, na qual os terrenos misturam trechos de terra, trilhas e asfalto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-58898\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2022\/08\/jj-8-1024x635-1024x635.jpg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2022\/08\/jj-8-1024x635.jpg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2022\/08\/jj-8-1024x635-300x186.jpg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2022\/08\/jj-8-1024x635-768x476.jpg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2022\/08\/jj-8-1024x635-135x84.jpg 135w\" alt=\"\" width=\"800\" height=\"496\" \/><\/p>\n<p>\u201cEsse \u00e9 um grande evento que j\u00e1 virou tradi\u00e7\u00e3o em nossa cidade, por isso n\u00e3o poderia deixar de ter o apoio da nossa gest\u00e3o, uma vez que promove sa\u00fade, entretenimento e movimenta nossa economia, levando o nome de Alagoinhas para fora do estado\u201d, declarou o prefeito Joaquim Neto.<\/p>\n<p>De acordo com Jiovane Paulino, criador do Marathon Bike Alagoinhas, h\u00e1 18 anos existia apenas uma maratona de Mountain Bike na Bahia e outras poucas no restante do pa\u00eds.\u00a0 \u201cAp\u00f3s uma participa\u00e7\u00e3o que fiz em um destes eventos,\u00a0foi despertada uma paix\u00e3o\u00a0que me motivou a organizar uma competi\u00e7\u00e3o deste modelo aqui em Alagoinhas. Descobrimos uma regi\u00e3o muito rica e apta para a pr\u00e1tica desta modalidade, que foi sucesso j\u00e1 na primeira edi\u00e7\u00e3o e n\u00e3o tardou para sermos reconhecidos oficialmente como o maior e melhor evento da modalidade no Nordeste\u201d. Jiovane tamb\u00e9m disse que em 2022 era para estar sendo realizada a 18\u00b0 edi\u00e7\u00e3o do Marathon Bike, \u201cmas tivemos que parar por dois anos, por conta da pandemia. Gra\u00e7as a Deus, este ano estamos retornando com for\u00e7a total!\u201d.<\/p>\n<p><strong>Servi\u00e7o<\/strong><\/p>\n<p><strong>16\u00ba<\/strong>\u00a0<strong>Marathon Bike<\/strong><br \/>\nData: 7 de agosto (domingo)<br \/>\nHor\u00e1rio: 8h<br \/>\nConcentra\u00e7\u00e3o: Pra\u00e7a dos Esportes<\/p>\n<p><strong>7\u00aa Marathon Night Run<\/strong><br \/>\nData: 6 de agosto (s\u00e1bado)<br \/>\nHor\u00e1rio: 20h<br \/>\nConcentra\u00e7\u00e3o: Pra\u00e7a dos Esportes<\/p>\n<p>Haver\u00e1 premia\u00e7\u00e3o para os melhores colocados nas categorias oficiais.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Com apoio da Prefeitura, os eventos esportivos Marathon Bike e Marathon Night Run agitam Alagoinhas neste final de semana' data-link='https:\/\/newsinfoco.com.br\/inicio\/com-apoio-da-prefeitura-os-eventos-esportivos-marathon-bike-e-marathon-night-run-agitam-alagoinhas-neste-final-de-semana\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Neste final de semana, a agenda esportiva de Alagoinhas ser\u00e1 movimentada. Com 850 atletas inscritos de todo o pa\u00eds, no domingo (07), munic\u00edpio ir\u00e1 realizar a 16\u00aa Marathon Bike, uma das mais tradicionais provas do Montain Bike nordestino. Para completar a festa do esporte, no s\u00e1bado (06), acontece a 7\u00aa edi\u00e7\u00e3o da Marathon Night Run [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-31061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/31061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=31061"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/31061\/revisions"}],"predecessor-version":[{"id":31063,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/31061\/revisions\/31063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/31062"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=31061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=31061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=31061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}