{"id":32133,"date":"2022-12-11T11:51:54","date_gmt":"2022-12-11T14:51:54","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=32133"},"modified":"2022-12-11T12:05:10","modified_gmt":"2022-12-11T15:05:10","slug":"o-programa-municipal-de-organizacoes-sociais-de-alagoinhas-precisa-ser-melhor-discutido-por-caio-pimenta","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/o-programa-municipal-de-organizacoes-sociais-de-alagoinhas-precisa-ser-melhor-discutido-por-caio-pimenta\/","title":{"rendered":"O Programa Municipal de Organiza\u00e7\u00f5es Sociais de Alagoinhas precisa ser melhor discutido &#8211; Por Caio Pimenta"},"content":{"rendered":"<p>Ol\u00e1 amigo leitor, mais uma pol\u00eamica em Alagoinhas: o Programa Municipal de Organiza\u00e7\u00f5es Sociais&#8230; Ali\u00e1s, \u00e9 impressionante como qualquer coisa que se queira implantar no munic\u00edpio enfrenta oposi\u00e7\u00e3o ferrenha de um certo contingente de figuras, a maioria alijada do poder. Podemos citar como exemplo: as obras do bin\u00e1rio, reforma das pra\u00e7as, a obra de drenagem da Lagoa Cavada, zona azul, licita\u00e7\u00e3o do transporte p\u00fablico&#8230;. e por a\u00ed vai. Mas enfim, a bola da vez \u00e9 a sa\u00fade e esse projeto que tramita na Casa Legislativa. Ent\u00e3o vamos analisar.<\/p>\n<p>Em linhas gerais, esse Projeto de Lei permite que o munic\u00edpio mantenha contratos com institui\u00e7\u00f5es sem fins lucrativos para efetuar a gest\u00e3o de equipamentos de sa\u00fade no munic\u00edpio. \u00c9 uma modalidade que difere do que \u00e9 praticado hoje no munic\u00edpio e tem o objetivo de otimizar o atendimento \u00e0 popula\u00e7\u00e3o, j\u00e1 que institui\u00e7\u00f5es dessa monta n\u00e3o sofrem tanto com as burocracias legais a que deve se submeter a administra\u00e7\u00e3o p\u00fablica.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-4234036342\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Embora seja uma novidade para Alagoinhas, esse modelo de Programa j\u00e1 est\u00e1 presente em mais de 23 estados da federa\u00e7\u00e3o, inclusive a Bahia, e em mais de 200 munic\u00edpios brasileiros, de modo que o que se coloca \u00e9 a oportunidade do munic\u00edpio fazer parte desta tend\u00eancia.<\/p>\n<p>Existem experi\u00eancias exitosas nesta modalidade de gest\u00e3o, podemos citar o Instituto do C\u00e2ncer e o hospital estadual em Araraquara, ambos em S\u00e3o Paulo, que s\u00e3o geridos por OSs. E tamb\u00e9m experi\u00eancias n\u00e3o t\u00e3o boas, como \u00e9 o caso do Hospital Regional Dantas Bi\u00e3o. Neste segundo ponto, \u00e9 importante destacar que o costumeiro atraso de repasse do Governo do Estado as Oss que ali exerceram a gest\u00e3o, foi quase sempre o grande motivador das paralisa\u00e7\u00f5es e queda na qualidade da presta\u00e7\u00e3o do servi\u00e7o m\u00e9dico.<\/p>\n<p>Mas enfim&#8230; Diante deste cen\u00e1rio, o m\u00ednimo que pode ser feito \u00e9 uma real an\u00e1lise do texto enviado pelo executivo e as peculiaridades do munic\u00edpio, mas infelizmente o que se v\u00ea \u00e9 um festival de incoer\u00eancias e meias verdades que chegam a gerar verdadeiras injusti\u00e7as contra essas institui\u00e7\u00f5es sem fins lucrativos.<\/p>\n<p>S\u00e3o acusa\u00e7\u00f5es da oposi\u00e7\u00e3o: &#8220;A PL visa a terceiriza\u00e7\u00e3o\/quarteiriza\u00e7\u00e3o do servi\u00e7o m\u00e9dico&#8221;, &#8220;A PL visa a precariza\u00e7\u00e3o do servi\u00e7o m\u00e9dico e do trabalho no municipio&#8221;, etc. Isso beira a desonestidade intelectual ou \u00e9 ignor\u00e2ncia de quem as profere.<\/p>\n<p>Ent\u00e3o vamos combater as fake news:<\/p>\n<p>1 &#8211; As Organiza\u00e7\u00f5es Sociais de Sa\u00fade s\u00e3o institui\u00e7\u00f5es de natureza privada, mas SEM FINS LUCRATIVOS. ou seja, tudo o que ela arrecada\u00a0 do setor p\u00fablico \u00e9 reinvestido na pr\u00f3pria institui\u00e7\u00e3o. Elas n\u00e3o substituem o poder p\u00fablico na formula\u00e7\u00e3o das pol\u00edticas de sa\u00fade, apenas as executam, conforme as metas assistenciais estabelecidas nos contratos de gest\u00e3o. N\u00e3o se trata, em hip\u00f3tese alguma, de privatiza\u00e7\u00e3o da sa\u00fade, uma vez que n\u00e3o h\u00e1 lucro na opera\u00e7\u00e3o, os equipamentos continuam pertencendo ao Estado e os atendimentos s\u00e3o 100% pelo SUS.<\/p>\n<p>2 &#8211;\u00a0\u00c9 indevido falar em \u201cquarteiriza\u00e7\u00e3o\u201d, uma vez que, conforme parecer do STF, os contratos entre o poder p\u00fablico e as Organiza\u00e7\u00f5es Sociais de Sa\u00fade t\u00eam natureza de conv\u00eanio, constituindo-se, portanto, como uma parceria. As OSS atuam em nome do poder p\u00fablico e, portanto, n\u00e3o s\u00e3o terceirizadas. N\u00e3o cabe qualquer discuss\u00e3o sobre este aspecto.<\/p>\n<p>3 &#8211; A precariza\u00e7\u00e3o do trabalho ou do servi\u00e7o destas organiza\u00e7\u00f5es sociais elencadas tamb\u00e9m s\u00e3o inconsistentes. Isso porque todo o trabalhador contratado por essas institui\u00e7\u00f5es devem se submeter as regras trabalhistas existentes no pa\u00eds, seja contrata\u00e7\u00e3o por tempo determinado seja por tempo indeterminado.<\/p>\n<p>Temos como exemplo de Organiza\u00e7\u00e3o Social de Sa\u00fade na Bahia, as Obras Assistenciais Irm\u00e3 Dulce(OSID), que leva o nome de sua fundadora e que muito contribuiu e contribui para diminuir o sofrimento dos mais pobres. Al\u00e9m dos 21 n\u00facleos pertencentes \u00e0 institui\u00e7\u00e3o, a OSID atua ainda na gest\u00e3o de unidades externas de sa\u00fade, sendo respons\u00e1vel hoje pela administra\u00e7\u00e3o de tr\u00eas complexos p\u00fablicos, todos localizados na Bahia e vinculados ao Governo do Estado: Hospital do Oeste (Barreiras), Hospital Eurides Sant\u2019anna (Santa Rita de C\u00e1ssia) e Hospital Regional Dr. M\u00e1rio Dourado Sobrinho (Irec\u00ea). A entidade responde tamb\u00e9m pelo Centro de Conviv\u00eancia Irm\u00e3 Dulce dos Pobres, localizado no Centro Hist\u00f3rico de Salvador. \u00c9 uma injusti\u00e7a qualificar esta importante institui\u00e7\u00e3o como uma &#8220;precarizadora do trabalho ou servi\u00e7o&#8221; ou uma participe da &#8220;terceiriza\u00e7\u00e3o do servi\u00e7o m\u00e9dico&#8221;. Assim como as Obras Assistenciais Irm\u00e3 Dulce, se juntam tantas outras. \u00c9 estimado que no Brasil existam mais de 800 institui\u00e7\u00f5es desse tipo.<\/p>\n<p>A parceria com Entidades privadas representa a busca da moderniza\u00e7\u00e3o da Gest\u00e3o P\u00fablica na Sa\u00fade. Permite que se apliquem princ\u00edpios consagrados de administra\u00e7\u00e3o privada tornando as a\u00e7\u00f5es mais din\u00e2micas oferecendo maior agilidade.<\/p>\n<p>\u00c9 claro que para que este cen\u00e1rio possa ser efetivado \u00e9 preciso mecanismos de acompanhamento e fiscaliza\u00e7\u00e3o que cabem ao munic\u00edpio e aos pr\u00f3prios vereadores discutirem. Aliada a isso, um compromisso da Gest\u00e3o P\u00fablica em n\u00e3o atrasar os repasses.<\/p>\n<p>Al\u00e9m dessa quest\u00e3o mais t\u00e9cnica que acabei de apresentar, \u00e9 preciso trazermos a baila as quest\u00f5es politicas envolvidas nisso, que no m\u00ednimo se trata de incoer\u00eancia politica. Na bancada oposicionista na C\u00e2mara Municipal temos Juci Cardoso(PC do B), Thor de Ninha(PT), Jaldice Nunes(UB), Luciano Almeida(UB) e Luma Menezes(PDT). Todos eles at\u00e9 aqui cr\u00edticos da administra\u00e7\u00e3o de equipamentos de sa\u00fade pelas OSS.<\/p>\n<p>\u00c9 bom lembrarmos que tanto o Governo do Estado, apoiado pelos partidos de Juci Cardoso e Thor de Ninha, quanto a prefeitura da capital baiana, apoiada pelos partidos de Jaldice Nunes, Luciano Almeida e Luma Menezes, mant\u00e9m equipamentos de sa\u00fade geridos por Organiza\u00e7\u00f5es Sociais de Sa\u00fade. De modo que tal discurso de cr\u00edtica severa ao Programa Municipal de Organiza\u00e7\u00f5es Sociais , antes mesmo de um discuss\u00e3o mais aprofundada, \u00e9 extremamente hip\u00f3crita.<\/p>\n<p>\u00c9 preciso que discutamos seriamente mudan\u00e7as no sistema municipal de sa\u00fade. Reclama\u00e7\u00f5es por falta de medicamentos, m\u00e9dicos e atendimento s\u00e3o uma constante. Algo tem que ser feito. O Programa Municipal de Organiza\u00e7\u00f5es Sociais \u00e9 uma proposta que esta sendo colocada na mesa, tem que ser avaliada tecnicamente, sem interesses partid\u00e1rios e pol\u00edticos que atentem contra a popula\u00e7\u00e3o. Do mesmo modo que o m\u00ednimo que se espera de quem se mostra contr\u00e1rio \u00e9 que apresentem solu\u00e7\u00f5es alternativas ou que ao menos resolvam as suas pr\u00f3prias incoer\u00eancias.<\/p>\n<p><strong><em>Escrito por Caio Pimenta, advogado, \u00e2ncora do programa Primeira M\u00e3o, da radio Ouro Negro 100,5 FM. Ele tamb\u00e9m escreve sua coluna no site News Infoco, do qual \u00e9 editor- chefe e dirige a radio web 2 de julho.<\/em><\/strong><\/p>\n<div class=\"share-to-whatsapp-wrapper\"><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='O Programa Municipal de Organiza\u00e7\u00f5es Sociais de Alagoinhas precisa ser melhor discutido - Por Caio Pimenta' data-link='https:\/\/newsinfoco.com.br\/inicio\/o-programa-municipal-de-organizacoes-sociais-de-alagoinhas-precisa-ser-melhor-discutido-por-caio-pimenta\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 amigo leitor, mais uma pol\u00eamica em Alagoinhas: o Programa Municipal de Organiza\u00e7\u00f5es Sociais&#8230; Ali\u00e1s, \u00e9 impressionante como qualquer coisa que se queira implantar no munic\u00edpio enfrenta oposi\u00e7\u00e3o ferrenha de um certo contingente de figuras, a maioria alijada do poder. Podemos citar como exemplo: as obras do bin\u00e1rio, reforma das pra\u00e7as, a obra de drenagem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-32133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caio-pimenta"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=32133"}],"version-history":[{"count":3,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32133\/revisions"}],"predecessor-version":[{"id":32136,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32133\/revisions\/32136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/24733"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=32133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=32133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=32133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}