{"id":32141,"date":"2022-12-11T13:39:09","date_gmt":"2022-12-11T16:39:09","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=32141"},"modified":"2022-12-11T13:39:09","modified_gmt":"2022-12-11T16:39:09","slug":"manifestantes-convocam-ato-contra-diplomacao-de-lula","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/manifestantes-convocam-ato-contra-diplomacao-de-lula\/","title":{"rendered":"Manifestantes convocam ato contra diploma\u00e7\u00e3o de Lula"},"content":{"rendered":"<p>Nas redes sociais e em grupos de mensagens, apoiadores do presidente\u00a0Jair Bolsonaro\u00a0prometem realizar protestos contra a\u00a0diploma\u00e7\u00e3o de Lula\u00a0nesta segunda-feira (12). O assunto \u00e9 um dos mais\u00a0comentados na manh\u00e3 deste domingo no Twitter.<\/p>\n<p>Por garantia, a seguran\u00e7a ser\u00e1 refor\u00e7ada no\u00a0Distrito Federal.\u00a0A regi\u00e3o do pr\u00e9dio do\u00a0TSE\u00a0ter\u00e1 um esquema especial de tr\u00e2nsito e de seguran\u00e7a durante a diploma\u00e7\u00e3o do presidente eleito\u00a0Lula\u00a0e do vice-presidente\u00a0Geraldo Alckmin. A cerim\u00f4nia est\u00e1 marcada para as 14 horas.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2488898936\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Para o evento, que marca o fim do processo eleitoral, foram convidadas\u00a0cerca de 300 pessoas, entre elas os ex-presidentes\u00a0Jos\u00e9 Sarney\u00a0e\u00a0Dilma Rousseff. Tamb\u00e9m dever\u00e3o comparecer os\u00a0ministros do TSE\u00a0e do\u00a0STF, al\u00e9m de parlamentares, governadores e integrantes do futuro governo.<\/p>\n<p>A cerim\u00f4nia tem dura\u00e7\u00e3o prevista de uma hora. J\u00e1 a posse ocorrer\u00e1 no dia 1\u00ba de janeiro.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Manifestantes convocam ato contra diploma\u00e7\u00e3o de Lula' data-link='https:\/\/newsinfoco.com.br\/inicio\/manifestantes-convocam-ato-contra-diplomacao-de-lula\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Nas redes sociais e em grupos de mensagens, apoiadores do presidente\u00a0Jair Bolsonaro\u00a0prometem realizar protestos contra a\u00a0diploma\u00e7\u00e3o de Lula\u00a0nesta segunda-feira (12). O assunto \u00e9 um dos mais\u00a0comentados na manh\u00e3 deste domingo no Twitter. Por garantia, a seguran\u00e7a ser\u00e1 refor\u00e7ada no\u00a0Distrito Federal.\u00a0A regi\u00e3o do pr\u00e9dio do\u00a0TSE\u00a0ter\u00e1 um esquema especial de tr\u00e2nsito e de seguran\u00e7a durante a diploma\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-32141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=32141"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32141\/revisions"}],"predecessor-version":[{"id":32143,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32141\/revisions\/32143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/31770"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=32141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=32141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=32141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}