{"id":32967,"date":"2023-02-10T20:04:29","date_gmt":"2023-02-10T23:04:29","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=32967"},"modified":"2023-02-10T20:04:29","modified_gmt":"2023-02-10T23:04:29","slug":"apos-retornar-a-base-pp-busca-comando-da-adab","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/apos-retornar-a-base-pp-busca-comando-da-adab\/","title":{"rendered":"Ap\u00f3s retornar \u00e0 base, PP busca comando da Adab"},"content":{"rendered":"<p>De volta ao grupo governista na Assembleia Legislativa da Bahia, o Partido Progressista caminha para assumir o comando da Ag\u00eancia de Defesa Agropecu\u00e1ria da Bahia.<\/p>\n<p>Conforme informado pelo Bahia.ba, para cumprir as exig\u00eancias do governador Jer\u00f4nimo Rodrigues (PT), que busca um nome t\u00e9cnico, a sigla espera que Paulo Em\u00edlio Torres assuma a pasta.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-898257902\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Paulo j\u00e1 trabalha como fiscal estadual Agropecu\u00e1rio da Adab e teve passagens como diretor-geral da Ag\u00eancia, superintendente do Minist\u00e9rio da Agricultura, Pecu\u00e1ria e Abastecimento, e superintendente Federal de Agricultura.<\/p>\n<p>&nbsp;<\/p>\n<p>Politicaaovivo<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ap\u00f3s retornar \u00e0 base, PP busca comando da Adab' data-link='https:\/\/newsinfoco.com.br\/inicio\/apos-retornar-a-base-pp-busca-comando-da-adab\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>De volta ao grupo governista na Assembleia Legislativa da Bahia, o Partido Progressista caminha para assumir o comando da Ag\u00eancia de Defesa Agropecu\u00e1ria da Bahia. Conforme informado pelo Bahia.ba, para cumprir as exig\u00eancias do governador Jer\u00f4nimo Rodrigues (PT), que busca um nome t\u00e9cnico, a sigla espera que Paulo Em\u00edlio Torres assuma a pasta. Paulo j\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-32967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=32967"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32967\/revisions"}],"predecessor-version":[{"id":32969,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32967\/revisions\/32969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/32968"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=32967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=32967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=32967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}