{"id":32987,"date":"2023-02-12T18:41:47","date_gmt":"2023-02-12T21:41:47","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=32987"},"modified":"2023-02-12T18:41:47","modified_gmt":"2023-02-12T21:41:47","slug":"gera-requiao-desconversa-sobre-possivel-filiacao-de-pequeno-sales-ao-pt","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/gera-requiao-desconversa-sobre-possivel-filiacao-de-pequeno-sales-ao-pt\/","title":{"rendered":"Gera Requi\u00e3o desconversa sobre poss\u00edvel filia\u00e7\u00e3o de Pequeno Sales ao PT"},"content":{"rendered":"<p>Os movimentos em torno da poss\u00edvel filia\u00e7\u00e3o do prefeito de Catu, Pequeno Sales, ao PT continuam intensos. Procurado para comentar o assunto, o ex-prefeito da cidade Gera Requi\u00e3o (PT) desconversou.<\/p>\n<p>\u201cEm nossos dois mandatos, assim como durante nossa vida, buscamos colocar o bem estar do povo catuense em primeiro lugar. Enfrentamos uma pandemia e, durante o primeiro mandato, promovemos in\u00fameros avan\u00e7os na sa\u00fade educa\u00e7\u00e3o e infraestrutura\u201d, disse ao site Na Resenha.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-4142359371\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Ainda de acordo com o site, ap\u00f3s a confirma\u00e7\u00e3o de um encontro entre membros do diret\u00f3rio municipal do PT para, segundo o ex-vereador Professor Seles, analisar o pedido de filia\u00e7\u00e3o\u201d de Pequeno Sales, mexeram com os bastidores da politica em Catu.<\/p>\n<p>Pol\u00edticos ligados \u00e0 duas siglas que tiveram vota\u00e7\u00e3o expressiva em Catu nas \u00faltimas elei\u00e7\u00f5es sinalizaram que \u201ctem as portas totalmente abertas\u201d para receber o ex-prefeito Gera Requi\u00e3o, caso este opte por deixar o PT.<\/p>\n<p>Um dos entrevistados chegou a afirmar que o movimento do PT \u00e9 uma retalia\u00e7\u00e3o devido ao apoio franqueado por Gera Requi\u00e3o a uma chapa n\u00e3o petista durante o processo de sucess\u00e3o municipal.<\/p>\n<p>&nbsp;<\/p>\n<p>Bahia.ba<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Gera Requi\u00e3o desconversa sobre poss\u00edvel filia\u00e7\u00e3o de Pequeno Sales ao PT' data-link='https:\/\/newsinfoco.com.br\/inicio\/gera-requiao-desconversa-sobre-possivel-filiacao-de-pequeno-sales-ao-pt\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Os movimentos em torno da poss\u00edvel filia\u00e7\u00e3o do prefeito de Catu, Pequeno Sales, ao PT continuam intensos. Procurado para comentar o assunto, o ex-prefeito da cidade Gera Requi\u00e3o (PT) desconversou. \u201cEm nossos dois mandatos, assim como durante nossa vida, buscamos colocar o bem estar do povo catuense em primeiro lugar. Enfrentamos uma pandemia e, durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-32987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=32987"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32987\/revisions"}],"predecessor-version":[{"id":32988,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/32987\/revisions\/32988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/31955"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=32987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=32987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=32987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}