{"id":33000,"date":"2023-02-14T17:44:00","date_gmt":"2023-02-14T20:44:00","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33000"},"modified":"2023-02-14T17:45:40","modified_gmt":"2023-02-14T20:45:40","slug":"prefeito-joaquim-neto-exonera-andre-barros-do-comando-da-smtt-de-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/prefeito-joaquim-neto-exonera-andre-barros-do-comando-da-smtt-de-alagoinhas\/","title":{"rendered":"Prefeito Joaquim Neto exonera Andr\u00e9 Barros do comando da SMTT de Alagoinhas"},"content":{"rendered":"<p>O prefeito de Alagoinhas, Joaquim Neto(PSD), decidiu exonerar Andr\u00e9 Barros do comando da Superintend\u00eancia Municipal de Transporte e Tr\u00e2nsito de Alagoinhas(SMTT). A exonera\u00e7\u00e3o a pe* foi publicada na edi\u00e7\u00e3o do di\u00e1rio oficial desta ter\u00e7a-feira(14).<\/p>\n<p>Barros sai do comando da autarquia em meio a acusa\u00e7\u00f5es de tentar interferir e dificultar opera\u00e7\u00f5es da corpora\u00e7\u00e3o. Agentes de tr\u00e2nsito fizeram den\u00fancias p\u00fablicas contra o agora ex-superintendente que nega as acusa\u00e7\u00f5es.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2570343592\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Em entrevista concedida ao programa O Poder da Noticia, da r\u00e1dio Boa FM, na manh\u00e3 de hoje, Andr\u00e9 Barros se defendeu e afirmou haver interesses pol\u00edticos por parte de alguns agentes de tr\u00e2nsito para apresentar o que ele classifica como &#8220;falsas acusa\u00e7\u00f5es&#8221;.<\/p>\n<p>Durante sua fala, Andr\u00e9 revelou que h\u00e1 problemas dentro \u00f3rg\u00e3o criadas por \u201cpessoas que antes sorriam em gest\u00f5es anteriores e hoje n\u00e3o sorriem mais\u201d. A fala leva a crer que alguns agentes que antes gozavam de algumas regalias em governos passados, hoje tem uma postura acintosa contra o comando do \u00f3rg\u00e3o por ter essas regalias suspensas.<\/p>\n<p>Andr\u00e9 Barros \u00e9 o 5\u00aa superintendente que passa pela SMTT desde o primeiro mandato do Governo Joaquim Neto. Quem assume interinamente a superintend\u00eancia \u00e9 o diretor do \u00f3rg\u00e3o Geovane Santos.<\/p>\n<p>&nbsp;<\/p>\n<p>Por Caio Pimenta para o News Infoco<\/p>\n<div class=\"google-auto-placed ap_container\"><\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Prefeito Joaquim Neto exonera Andr\u00e9 Barros do comando da SMTT de Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/prefeito-joaquim-neto-exonera-andre-barros-do-comando-da-smtt-de-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O prefeito de Alagoinhas, Joaquim Neto(PSD), decidiu exonerar Andr\u00e9 Barros do comando da Superintend\u00eancia Municipal de Transporte e Tr\u00e2nsito de Alagoinhas(SMTT). A exonera\u00e7\u00e3o a pe* foi publicada na edi\u00e7\u00e3o do di\u00e1rio oficial desta ter\u00e7a-feira(14). Barros sai do comando da autarquia em meio a acusa\u00e7\u00f5es de tentar interferir e dificultar opera\u00e7\u00f5es da corpora\u00e7\u00e3o. Agentes de tr\u00e2nsito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-33000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33000"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33000\/revisions"}],"predecessor-version":[{"id":33002,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33000\/revisions\/33002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/32018"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}