{"id":33047,"date":"2023-02-20T11:46:58","date_gmt":"2023-02-20T14:46:58","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33047"},"modified":"2023-02-20T11:46:58","modified_gmt":"2023-02-20T14:46:58","slug":"delacao-do-fim-do-mundo-acumula-derrotas-no-stf-sob-efeito-lula-e-trava-processos","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/delacao-do-fim-do-mundo-acumula-derrotas-no-stf-sob-efeito-lula-e-trava-processos\/","title":{"rendered":"\u2018Dela\u00e7\u00e3o do fim do mundo\u2019 acumula derrotas no STF sob efeito Lula e trava processos"},"content":{"rendered":"<p>O acordo de colabora\u00e7\u00e3o que chegou a ser apelidado de \u201cdela\u00e7\u00e3o do fim do mundo\u201d pelo seu impacto na pol\u00edtica nacional agora tem sido gradualmente considerado inv\u00e1lido pelo STF (Supremo Tribunal Federal), travando uma s\u00e9rie de processos na Justi\u00e7a.<\/p>\n<p>A partir de um precedente que beneficiou o agora presidente Luiz In\u00e1cio Lula da Silva (PT), ordens do tribunal t\u00eam declarado suspensas a\u00e7\u00f5es penais que tiveram como base dados do acordo de leni\u00eancia da empreiteira Odebrecht.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1991723673\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>As decis\u00f5es mais recentes, em dezembro, favoreceram o hoje vice-presidente, Geraldo Alckmin (PSB), e o ex-candidato ao Governo de S\u00e3o Paulo Paulo Skaf (filiado hoje ao Republicanos). Eles conseguiram paralisar a tramita\u00e7\u00e3o de seus processos, que envolviam delatores da empreiteira, estendendo para si os efeitos da decis\u00e3o pr\u00f3-Lula.<\/p>\n<p>Formou-se ainda uma fila de pedidos de extens\u00e3o da medida feitos por outros investigados na Opera\u00e7\u00e3o Lava Jato e seus desdobramentos, que inclui o ex-deputado Eduardo Cunha (hoje no PTB) e o ex-senador Edison Lob\u00e3o (MDB). O respons\u00e1vel por analisar os pedidos \u00e9 o ministro Ricardo Lewandowski.<\/p>\n<p>A invalida\u00e7\u00e3o de parte do acordo da Odebrecht \u2014grupo hoje rebatizado de Novonor\u2014 teve seus primeiros passos quando a defesa de Lula recorreu \u00e0 corte para ter acesso \u00e0 \u00edntegra dos sistemas eletr\u00f4nicos da empreiteira, na \u00e9poca em que ainda respondia a a\u00e7\u00f5es da Lava Jato no Paran\u00e1.<\/p>\n<p>O petista dizia que a Vara Federal de Curitiba tolhia seu direito \u00e0 defesa ao dar seguimento a uma a\u00e7\u00e3o penal sem que seus advogados pudessem avaliar todos os dados entregues pela empreiteira.<\/p>\n<p>Os sistemas eletr\u00f4nicos, chamados de Drousys e MyWebDay, eram usados pela construtora para registrar pagamentos il\u00edcitos e ficavam armazenados secretamente na Europa. Esses dados s\u00e3o as principais provas de corrobora\u00e7\u00e3o dos relatos de irregularidades feitos por 78 executivos da empreiteira em depoimentos.<\/p>\n<p>Em agosto de 2020, os ministros Lewandowski e Gilmar Mendes determinaram que fosse concedido amplo acesso \u00e0 defesa ao conte\u00fado do acordo de leni\u00eancia. Como ficou vencido na ocasi\u00e3o o ministro Edson Fachin, que relata a Lava Jato no Supremo, Lewandowski passou a ser relator de um recurso da defesa chamado de reclama\u00e7\u00e3o.<\/p>\n<p>Na sequ\u00eancia, a defesa de Lula come\u00e7ou a fazer novas solicita\u00e7\u00f5es ao Supremo, analisadas primeiramente por Lewandowski em uma outra reclama\u00e7\u00e3o protocolada.<\/p>\n<p>No fim de 2020, por exemplo, pediu acesso a mensagens trocadas por procuradores apreendidas na Opera\u00e7\u00e3o Spoofing, que investigou o hackeamento dos telefones de autoridades da Lava Jato. Lewandowski concedeu o acesso, e os advogados de Lula trouxeram para os autos centenas de p\u00e1ginas de transcri\u00e7\u00f5es de conversas da for\u00e7a-tarefa feitas no aplicativo Telegram.<\/p>\n<p>A partir desses di\u00e1logos, o advogado que coordena a defesa de Lula, Cristiano Zanin Martins, pediu que o uso do acordo de leni\u00eancia contra o petista fosse invalidado.<\/p>\n<p>Lewandowski tamb\u00e9m aceitou esse pleito em 2021, ap\u00f3s uma das a\u00e7\u00f5es penais abertas contra Lula em Curitiba ter sido enviada ao Distrito Federal tamb\u00e9m por ordem do Supremo.<\/p>\n<p>Citando os di\u00e1logos dos procuradores, o ministro escreveu que os dados eletr\u00f4nicos da empreiteira tinham sido transportados sem as devidas precau\u00e7\u00f5es legais e que as tratativas internacionais para o acordo se deram \u201c\u00e0 margem da legisla\u00e7\u00e3o vigente\u201d.<\/p>\n<p>O acordo com a Odebrecht tinha sido firmado no fim de 2016 por autoridades do Brasil, da Su\u00ed\u00e7a e dos Estados Unidos e envolveu pagamento de multa projetada \u00e0 \u00e9poca em R$ 8,5 bilh\u00f5es.<\/p>\n<p>Lewandowski considera que ficou demonstrado que a negocia\u00e7\u00e3o ocorreu de modo informal, sem respeitar exig\u00eancias de coopera\u00e7\u00e3o internacional.<\/p>\n<p>O ministro do Supremo entendeu ainda que o ex-juiz Sergio Moro, hoje declarado parcial em sua atua\u00e7\u00e3o em rela\u00e7\u00e3o a Lula, despachou na recep\u00e7\u00e3o do acordo de leni\u00eancia como prova de acusa\u00e7\u00e3o.<\/p>\n<p>A medida de Lewandowski foi referendada por outros dois ministros que integram a Segunda Turma da corte, Gilmar e Kassio Nunes Marques, em fevereiro do ano passado.<\/p>\n<p>Diante dessa circunst\u00e2ncia, outros r\u00e9us passaram a pleitear a extens\u00e3o dos efeitos.<\/p>\n<p>Ainda em 2021, o empres\u00e1rio Walter Faria, dono da cervejaria Petr\u00f3polis, argumentou que a situa\u00e7\u00e3o dele era id\u00eantica \u00e0 de Lula e que a mesma medida deveria ser tomada.<\/p>\n<p>Solicita\u00e7\u00e3o do empres\u00e1rio j\u00e1 tinha sido atendida provisoriamente \u00e0 \u00e9poca por Lewandowski e foi reafirmada em mar\u00e7o passado. Ele respondia a a\u00e7\u00f5es penais nas quais foi acusado de participar do esquema ilegal de financiamento de pol\u00edticos arquitetado pela Odebrecht.<\/p>\n<p>O ex-ministro Paulo Bernardo Silva, que \u00e9 r\u00e9u na Justi\u00e7a Federal no Rio Grande do Sul, tamb\u00e9m teve a tramita\u00e7\u00e3o de a\u00e7\u00e3o penal suspensa em setembro.<\/p>\n<p>Na mesma semana, foram paralisadas a\u00e7\u00f5es penais eleitorais contra o prefeito do Rio, Eduardo Paes (PSD), e o deputado federal Pedro Paulo (PSD-RJ) que tramitavam no Rio. A medida incluiu ainda investiga\u00e7\u00f5es n\u00e3o finalizadas no estado.<\/p>\n<p>\u201cA acusa\u00e7\u00e3o baseou-se essencialmente nos documentos alegadamente extra\u00eddos dos sistemas de inform\u00e1tica denominados Drousys e MyWebDay\u201d, escreveu Lewandowski na decis\u00e3o.<\/p>\n<p>Em rela\u00e7\u00e3o a outros r\u00e9us, n\u00e3o houve a confirma\u00e7\u00e3o da decis\u00e3o pelos demais ministros at\u00e9 aqui. Os processos de Walter Faria acabaram trancados tamb\u00e9m em decorr\u00eancia de pedido com outra motiva\u00e7\u00e3o, tamb\u00e9m no Supremo.<\/p>\n<p>Em voto no julgamento de fevereiro de 2022, Fachin fez uma sequ\u00eancia de cr\u00edticas ao modo como se deu a tramita\u00e7\u00e3o dos pedidos relacionados ao acordo da Odebrecht a partir do caso de Lula.<\/p>\n<p>Disse que o \u00fanico embasamento para declarar a invalida\u00e7\u00e3o das provas do acordo de leni\u00eancia foram as mensagens hackeadas dos procuradores e que a tramita\u00e7\u00e3o violou o devido processo legal quando houve a amplia\u00e7\u00e3o dos pedidos das defesas. Tamb\u00e9m questionou a regularidade da perman\u00eancia de Lewandowski \u00e0 frente da an\u00e1lise desses pedidos.<\/p>\n<p>Em mar\u00e7o do ano passado, a Procuradoria-Geral da Rep\u00fablica, por meio da subprocuradora Lind\u00f4ra Ara\u00fajo, tamb\u00e9m fez questionamentos do tipo. Disse que \u201csujeitos totalmente estranhos\u201d ao ponto de partida do procedimento \u201caventuraram-se para postular \u2014e por vezes lograr\u2014 indevidas extens\u00f5es de efeitos\u201d.<\/p>\n<p>A pe\u00e7a do Minist\u00e9rio P\u00fablico nega que tenha havido irregularidades nas tratativas internacionais da colabora\u00e7\u00e3o da Odebrecht e diz que as decis\u00f5es estavam sendo tomadas no STF sem \u201cinstru\u00e7\u00e3o probat\u00f3ria ou oportunidade para o exerc\u00edcio do contradit\u00f3rio\u201d.<\/p>\n<p>O ministro Lewandowski tem dito nos despachos que o julgamento sobre a imprestabilidade das provas da empreiteira j\u00e1 transitou em julgado (encerrou sem possibilidade de novos recursos) com a an\u00e1lise do caso de Lula e que a decis\u00e3o da corte pode, sim, ser estendida.<\/p>\n<p>O magistrado recha\u00e7ou nos autos tamb\u00e9m a afirma\u00e7\u00e3o de que tenha havido alargamento indevido dos temas discutidos na reclama\u00e7\u00e3o inicialmente protocolada por Lula e disse que o acesso ao acordo de leni\u00eancia \u00e9 e sempre foi o objeto do procedimento.<\/p>\n<p>Procurada pela reportagem, a Novonor informou que \u201cdesde o in\u00edcio, vem colaborando de forma plena com as autoridades em busca do total esclarecimento de fatos do passado\u201d.<\/p>\n<p>\u201cHoje est\u00e1 inteiramente transformada e usa as mais recomendadas normas de conformidade, seguindo comprometida com uma atua\u00e7\u00e3o \u00e9tica, \u00edntegra e transparente\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"assinatura_exclusiva\">Felipe B\u00e4chtold\/Italo Nogueira\/Folhapress<\/span><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='\u2018Dela\u00e7\u00e3o do fim do mundo\u2019 acumula derrotas no STF sob efeito Lula e trava processos' data-link='https:\/\/newsinfoco.com.br\/inicio\/delacao-do-fim-do-mundo-acumula-derrotas-no-stf-sob-efeito-lula-e-trava-processos\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O acordo de colabora\u00e7\u00e3o que chegou a ser apelidado de \u201cdela\u00e7\u00e3o do fim do mundo\u201d pelo seu impacto na pol\u00edtica nacional agora tem sido gradualmente considerado inv\u00e1lido pelo STF (Supremo Tribunal Federal), travando uma s\u00e9rie de processos na Justi\u00e7a. A partir de um precedente que beneficiou o agora presidente Luiz In\u00e1cio Lula da Silva (PT), [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-33047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33047"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33047\/revisions"}],"predecessor-version":[{"id":33048,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33047\/revisions\/33048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/10689"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}