{"id":33063,"date":"2023-02-20T12:11:47","date_gmt":"2023-02-20T15:11:47","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33063"},"modified":"2023-02-20T12:11:47","modified_gmt":"2023-02-20T15:11:47","slug":"lula-perde-engajamento-nas-redes-sociais","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/lula-perde-engajamento-nas-redes-sociais\/","title":{"rendered":"Lula perde engajamento nas redes sociais"},"content":{"rendered":"<p>Um levantamento feito pela consultoria Bites, a pedido do jornal\u00a0<em>O Globo<\/em>, divulgado nesta segunda-feira, 20, mostra que as contas oficiais do presidente Lula est\u00e3o nos n\u00edveis mais baixos de engajamento desde o in\u00edcio do governo.<\/p>\n<p>O levantamento mostra que, desde o in\u00edcio do governo,\u00a0<strong><a href=\"https:\/\/twitter.com\/LulaOficial\" target=\"_blank\" rel=\"noopener\">Lula<\/a><\/strong>\u00a0fez cerca de 60 postagens por dia, se considerados Facebook, Twitter e Instagram. No per\u00edodo, o presidente alcan\u00e7ou, em m\u00e9dia, 29,5 mil curtidas, coment\u00e1rios e compartilhamentos por publica\u00e7\u00e3o. Durante a campanha, entre 16 de agosto e 30 de outubro, esse n\u00famero era mais duas vezes maior, e chegou a 72,7 mil.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3998260896\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A t\u00edtulo de compara\u00e7\u00e3o, a m\u00e9dia atingida pelo ex-presidente Jair Bolsonaro \u00e9 oito vezes maior do que a de Lula, segundo\u00a0<em>O Globo<\/em>, de 235,9 mil por postagem, e manteve-se praticamente a mesma da campanha, que era de 240,2 mil a cada publica\u00e7\u00e3o.<\/p>\n<p>O maior n\u00edvel de intera\u00e7\u00e3o de Lula foi na posse, em 1\u00ba de janeiro, e em 8 de janeiro, com as manifesta\u00e7\u00f5es no Distrito Federal. Na posse, o presidente teve 16 milh\u00f5es de intera\u00e7\u00f5es num dia; em 8 de janeiro, 7,6 milh\u00f5es.<\/p>\n<p>Entrevistado pelo\u00a0<em>Globo<\/em>, o fundador da Bites, Manoel Fernandes, disse que Lula conseguiu criar uma frente ampla digital durante a campanha eleitoral do ano passado, mas a comunica\u00e7\u00e3o no atual governo n\u00e3o prosseguiu com essa estrat\u00e9gia. \u201cOs apoios de campanha j\u00e1 n\u00e3o s\u00e3o utilizados agora. Falta ao governo uma estrat\u00e9gia mais clara e estruturada de comunica\u00e7\u00e3o no ambiente digital, criar uma grande alian\u00e7a nacional em torno da sua agenda de governo.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Revista Oeste<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Lula perde engajamento nas redes sociais' data-link='https:\/\/newsinfoco.com.br\/inicio\/lula-perde-engajamento-nas-redes-sociais\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Um levantamento feito pela consultoria Bites, a pedido do jornal\u00a0O Globo, divulgado nesta segunda-feira, 20, mostra que as contas oficiais do presidente Lula est\u00e3o nos n\u00edveis mais baixos de engajamento desde o in\u00edcio do governo. O levantamento mostra que, desde o in\u00edcio do governo,\u00a0Lula\u00a0fez cerca de 60 postagens por dia, se considerados Facebook, Twitter e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-33063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33063"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33063\/revisions"}],"predecessor-version":[{"id":33065,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33063\/revisions\/33065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33064"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}