{"id":33158,"date":"2023-02-24T20:58:14","date_gmt":"2023-02-24T23:58:14","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33158"},"modified":"2023-02-24T21:02:00","modified_gmt":"2023-02-25T00:02:00","slug":"bancada-feminina-da-camara-de-alagoinhas-faz-protesto-em-defesa-das-mulheres-de-ocupar-espacos-no-parlamento","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/bancada-feminina-da-camara-de-alagoinhas-faz-protesto-em-defesa-das-mulheres-de-ocupar-espacos-no-parlamento\/","title":{"rendered":"Bancada Feminina da C\u00e2mara de Alagoinhas faz protesto em defesa das mulheres de ocupar espa\u00e7os no parlamento"},"content":{"rendered":"<p dir=\"auto\">Nesta sexta-feira (24), dia que representa o marco de 91 anos da conquista do voto feminino no Brasil, as vereadoras da bancada feminina da C\u00e2mara de Alagoinhas Luma Menezes, Juci Cardoso e Jaldice Nunes participaram de um ato simb\u00f3lico em defesa ao direito da mulher parlamentar de exercer o seu trabalho com respeito e dignidade.<\/p>\n<p dir=\"auto\">As vereadoras viajaram para o munic\u00edpio de Muritiba com parlamentares de outras localidades em solidariedade, num ato de protesto e manifesta\u00e7\u00e3o em apoio e defesa de Perla da Concei\u00e7\u00e3o Santana Ferreira, \u00fanica vereadora da cidade. Segundo Luma Menezes Perla \u201cest\u00e1 com um processo de cassa\u00e7\u00e3o ao mandato por conta de uma atua\u00e7\u00e3o fiscalizadora muito forte. \u00c9 uma clara realidade de viol\u00eancia pol\u00edtica\u201d, ressaltou.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1139392983\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p dir=\"auto\">A vereadora Juci Cardoso ressaltou: \u201cHoje foi um dia hist\u00f3rico em que nos mobilizamos de diversas cidades para provar que o \u201cmexeu com uma, mexeu com todas\u201d n\u00e3o pode continuar sendo discursos vazios e hashtags de internet\u201d.<\/p>\n<p dir=\"auto\">A vereadora Jaldice Nunes pontuou: \u201cQuando tentam tirar o espa\u00e7o de Perla, o direito de fala e representatividade feminina, atinge todas n\u00f3s! O espa\u00e7o de Perla tamb\u00e9m \u00e9 nosso. Estamos constantemente em uma luta coletiva\u201d.<\/p>\n<p dir=\"auto\">Al\u00e9m das vereadoras de Alagoinhas, participaram do protesto: Perla (Muritiba), Juraneide Ferreira (Ara\u00e7\u00e1s), Linda Barros (Ara\u00e7\u00e1s), D\u00e9bora N\u00fabia (Itapicuru), Paloma (Janda\u00edra), Alana (Olindina), Marcelle Morais (Salvador), Dida Uzeda (Teodoro Sampaio) e Juliana Nascimento, (Santo Amaro). Durante a manifesta\u00e7\u00e3o o grupo caminhou pelas ruas dialogando com a popula\u00e7\u00e3o sobre o direito das mulheres de exercerem a sua fun\u00e7\u00e3o como parlamentar e ocuparem cargos p\u00fablicos.<\/p>\n<p dir=\"auto\">Ascom Camara<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Bancada Feminina da C\u00e2mara de Alagoinhas faz protesto em defesa das mulheres de ocupar espa\u00e7os no parlamento' data-link='https:\/\/newsinfoco.com.br\/inicio\/bancada-feminina-da-camara-de-alagoinhas-faz-protesto-em-defesa-das-mulheres-de-ocupar-espacos-no-parlamento\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Nesta sexta-feira (24), dia que representa o marco de 91 anos da conquista do voto feminino no Brasil, as vereadoras da bancada feminina da C\u00e2mara de Alagoinhas Luma Menezes, Juci Cardoso e Jaldice Nunes participaram de um ato simb\u00f3lico em defesa ao direito da mulher parlamentar de exercer o seu trabalho com respeito e dignidade. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-33158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33158"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33158\/revisions"}],"predecessor-version":[{"id":33161,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33158\/revisions\/33161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33159"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}