{"id":33171,"date":"2023-02-25T19:43:44","date_gmt":"2023-02-25T22:43:44","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33171"},"modified":"2023-02-25T19:47:29","modified_gmt":"2023-02-25T22:47:29","slug":"aumento-do-preco-do-diesel-e-reducao-de-passageiros-pagantes-aprofundaram-crise-no-transporte-publico-de-alagoinhas-diz-subprocurador-no-ba-tv","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/aumento-do-preco-do-diesel-e-reducao-de-passageiros-pagantes-aprofundaram-crise-no-transporte-publico-de-alagoinhas-diz-subprocurador-no-ba-tv\/","title":{"rendered":"Aumento do pre\u00e7o do diesel e redu\u00e7\u00e3o de passageiros pagantes aprofundaram crise no transporte p\u00fablico de Alagoinhas, diz subprocurador no BA TV"},"content":{"rendered":"<p>Desde ontem(24),a tarifa no transporte p\u00fablico de Alagoinhas acresceu R$0,20, passando de R$3,90 para R$4,10, e a meia passagem do estudante de R$1,95 para R$2,05. O aumento, decretado pelo prefeito Joaquim Neto(PSD), atendeu a uma recomenda\u00e7\u00e3o do Conselho Municipal de Transporte.<\/p>\n<p>Em entrevista concedida no dia de ontem ao jornal BA TV, da Tv Suba\u00e9, o subprocurador da prefeitura, Dr. Hilton Ribeiro, explicou os motivos que levaram o prefeito a atender a recomenda\u00e7\u00e3o do Conselho.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2790876227\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>De acordo com ele, o aumento cont\u00ednuo do pre\u00e7o internacional do \u00f3leo diesel, provocado pela guerra da R\u00fassia com a Ucr\u00e2nia, aliada a redu\u00e7\u00e3o do n\u00famero de passageiros pagantes registrado no sistema afetaram o financiamento dos custos do servi\u00e7o. Em resumo, a receita auferida no sistema n\u00e3o tem sido o suficiente para arcar com os custos do servi\u00e7o.<\/p>\n<p>Estudos t\u00e9cnicos efetuados pela SMTT apontam que para cumprir o que prev\u00ea o contrato firmado com a empresa concession\u00e1ria do transporte p\u00fablico(renova\u00e7\u00e3o de frota, aumento de linhas, etc) o valor da tarifa hoje deveria custar algo no entorno de R$6,15, o que na vis\u00e3o do Governo Municipal \u00e9 impratic\u00e1vel, levando em considera\u00e7\u00e3o o poder aquisitivo da popula\u00e7\u00e3o.<\/p>\n<p>Diante desta realidade, diz Dr. Hilton, a prefeitura decidiu aplicar um reajuste baseado no \u00cdndice Geral de Pre\u00e7os do Mercado (IGP-M), que ficou abaixo do reajuste do sal\u00e1rio m\u00ednimo. Assim, o novo valor \u00e9 um meio termo para atender o equil\u00edbrio financeiro das empresas e n\u00e3o onerar ainda mais o custo de vida do trabalhador.<\/p>\n<p class=\"p1\"><span class=\"s1\">Ap\u00f3s o an\u00fancio do aumento da tarifa, a Superintend\u00eancia Municipal de Transporte e Tr\u00e2nsito (SMTT) informou que novas linhas de \u00f4nibus passam a funcionar em Alagoinhas a partir de segunda-feira, dia 27 de fevereiro. O quadro de linhas<span class=\"Apple-converted-space\">\u00a0<\/span>foi modificado para melhor atender \u00e0 popula\u00e7\u00e3o.<span class=\"Apple-converted-space\">\u00a0\u00a0<\/span>S\u00e3o elas: <\/span><span class=\"s1\"><strong>Linha 5134<\/strong> \u2013 CRUZEIRO DOS MONTES VIA UNIRB e a <\/span><span class=\"s1\"><strong>Linha 5135<\/strong> \u2013 UNEB.<\/span><\/p>\n<p>Por Caio Pimenta para o News Infoco<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Aumento do pre\u00e7o do diesel e redu\u00e7\u00e3o de passageiros pagantes aprofundaram crise no transporte p\u00fablico de Alagoinhas, diz subprocurador no BA TV' data-link='https:\/\/newsinfoco.com.br\/inicio\/aumento-do-preco-do-diesel-e-reducao-de-passageiros-pagantes-aprofundaram-crise-no-transporte-publico-de-alagoinhas-diz-subprocurador-no-ba-tv\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Desde ontem(24),a tarifa no transporte p\u00fablico de Alagoinhas acresceu R$0,20, passando de R$3,90 para R$4,10, e a meia passagem do estudante de R$1,95 para R$2,05. O aumento, decretado pelo prefeito Joaquim Neto(PSD), atendeu a uma recomenda\u00e7\u00e3o do Conselho Municipal de Transporte. Em entrevista concedida no dia de ontem ao jornal BA TV, da Tv Suba\u00e9, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-33171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33171"}],"version-history":[{"count":3,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33171\/revisions"}],"predecessor-version":[{"id":33175,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33171\/revisions\/33175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33172"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}