{"id":33261,"date":"2023-03-08T17:31:06","date_gmt":"2023-03-08T20:31:06","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33261"},"modified":"2023-03-08T17:40:02","modified_gmt":"2023-03-08T20:40:02","slug":"correio-da-bahia-aline-peixoto-deve-vencer-disputa-para-vaga-no-tcm-com-ate-41-votos","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/correio-da-bahia-aline-peixoto-deve-vencer-disputa-para-vaga-no-tcm-com-ate-41-votos\/","title":{"rendered":"Correio da Bahia: Aline Peixoto deve vencer disputa para vaga no TCM com at\u00e9 41 votos"},"content":{"rendered":"<p>Os deputados da Assembleia Legislativa da Bahia votam, nesta quarta-feira (08), a nomea\u00e7\u00e3o do novo conselheiro do Tribunal de Contas dos Munic\u00edpios ap\u00f3s a sabatina realizada com os candidatos do governo, a ex-primeira-dama, Aline Peixoto, e da oposi\u00e7\u00e3o, o ex-deputado estadual Tom Ara\u00fajo (Uni\u00e3o Brasil).<\/p>\n<p>Conforme levantado nos bastidores pela coluna Sat\u00e9lite, do jornal Correio, a candidata governista deve vencer a disputa para a vaga no TCM com uma margem de 35 a 41 votos favor\u00e1veis somando os dois lados da Casa.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3709865443\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A publica\u00e7\u00e3o ainda revela que o fim do processo traz alivio para membros da Alba j\u00e1 que, ap\u00f3s a confirma\u00e7\u00e3o e a pol\u00eamica entorno do nome da esposa do ministro da Casa Civil, Rui Costa (PT), outros assuntos, deixados de lado durante o per\u00edodo, retornar\u00e3o \u00e0 pauta.<\/p>\n<p>&nbsp;<\/p>\n<p>Politicaaovivo<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Correio da Bahia: Aline Peixoto deve vencer disputa para vaga no TCM com at\u00e9 41 votos' data-link='https:\/\/newsinfoco.com.br\/inicio\/correio-da-bahia-aline-peixoto-deve-vencer-disputa-para-vaga-no-tcm-com-ate-41-votos\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Os deputados da Assembleia Legislativa da Bahia votam, nesta quarta-feira (08), a nomea\u00e7\u00e3o do novo conselheiro do Tribunal de Contas dos Munic\u00edpios ap\u00f3s a sabatina realizada com os candidatos do governo, a ex-primeira-dama, Aline Peixoto, e da oposi\u00e7\u00e3o, o ex-deputado estadual Tom Ara\u00fajo (Uni\u00e3o Brasil). Conforme levantado nos bastidores pela coluna Sat\u00e9lite, do jornal Correio, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33262,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-33261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33261"}],"version-history":[{"count":3,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33261\/revisions"}],"predecessor-version":[{"id":33265,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33261\/revisions\/33265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33262"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}