{"id":33280,"date":"2023-03-11T11:51:24","date_gmt":"2023-03-11T14:51:24","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33280"},"modified":"2023-03-11T11:51:24","modified_gmt":"2023-03-11T14:51:24","slug":"nova-regra-fiscal-nao-sera-meta-de-controle-da-divida-diz-haddad","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/nova-regra-fiscal-nao-sera-meta-de-controle-da-divida-diz-haddad\/","title":{"rendered":"Nova regra fiscal n\u00e3o ser\u00e1 meta de controle da d\u00edvida, diz Haddad"},"content":{"rendered":"<p>O ministro da Fazenda, Fernando Haddad, afirmou que a nova regra fiscal que ir\u00e1 substituir o teto de gastos n\u00e3o ser\u00e1 uma meta de controle da d\u00edvida p\u00fablica.<\/p>\n<p>\u201cN\u00e3o \u00e9 uma regra de d\u00edvida, pois n\u00e3o acredito que isso funcionaria nas condi\u00e7\u00f5es locais\u201d, disse Haddad em entrevista \u00e0 CNN na noite desta sexta-feira (10).<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2592187383\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>\u201cA d\u00edvida \u00e9 uma vari\u00e1vel muito importante, que temos de acompanhar, mas meta de d\u00edvida \u00e9 uma coisa que causaria um constrangimento. Em vez de harmonizarmos a pol\u00edtica fiscal com a monet\u00e1ria, criar\u00edamos uma confus\u00e3o em torno disso. Se em um momento tempor\u00e1rio, o Banco Central aumentasse os juros para controlar a infla\u00e7\u00e3o e se tivesse uma regra de d\u00edvida, quem iria fazer esse papel?\u201d, questionou.<\/p>\n<p>\u201cN\u00e3o posso antecipar a nova regra fiscal, estou apenas dando indica\u00e7\u00f5es de como ela foi constru\u00edda. O presidente [Luiz In\u00e1cio Lula da Silva] foi muito feliz na campanha, com seu poder de s\u00edntese que lhe d\u00e1 uma condi\u00e7\u00e3o vantajosa, ao dizer que iria colocar o pobre no Or\u00e7amento e o rico no Imposto de Renda\u201d.<\/p>\n<p>Ele tamb\u00e9m afirmou ter adiantado o an\u00fancio do novo arcabou\u00e7o fiscal de agosto para mar\u00e7o para acalmar expectativas.<\/p>\n<p>\u201cAnunciei que t\u00ednhamos de harmonizar a pol\u00edtica fiscal com a monet\u00e1ria, estamos com uma taxa de juros muito elevada, com um d\u00e9ficit fiscal muito elevado, e o papel das autoridades fiscal e monet\u00e1ria \u00e9 buscar converg\u00eancia para que as empresas consigam se financiar\u201d, disse.<\/p>\n<p>Na entrevista, Haddad tamb\u00e9m refor\u00e7ou a import\u00e2ncia de o governo n\u00e3o deixar faltar dinheiro para acabar com a fome e manter programas que s\u00e3o importantes para Lula, como o Minha Casa, Minha Vida.<\/p>\n<p>O teto de gastos, aprovado durante a gest\u00e3o do ex-presidente Michel Temer (MDB), \u00e9 um mecanismo que limita o crescimento das despesas p\u00fablicas \u00e0 infla\u00e7\u00e3o registrada no ano anterior e est\u00e1 em vigor desde 2017.<\/p>\n<p>O ministro da Fazenda tamb\u00e9m afirmou que tomou provid\u00eancias para que o d\u00e9ficit gerado pela lei or\u00e7ament\u00e1ria herdada do governo de Jair Bolsonaro seja reduzido pela metade, e que ir\u00e1 tomar outras medidas na mesma dire\u00e7\u00e3o.<\/p>\n<p>\u201cUm ano \u00e9 pouco para o investidor, o arcabou\u00e7o fiscal vai oferecer [essa seguran\u00e7a]. O teto de gastos era muito pol\u00eamico e quase inexequ\u00edvel, mas ele introduziu no Brasil uma regra de gastos, como em dezenas de pa\u00edses. Mas teve o problema da s\u00e9rie de medidas fora do teto e o governo anterior n\u00e3o tinha compromisso com a arrecada\u00e7\u00e3o. Hoje eu tive de fazer um acordo com os governadores [sobre o ICMS], j\u00e1 que o Bolsonaro abriu um rombo de R$ 26,9 bilh\u00f5es\u201d.<\/p>\n<p>Mais cedo, o ministro havia anunciado o acordo de R$ 26,9 bilh\u00f5es entre Uni\u00e3o e estados, para repor as perdas impostas pelo corte do ICMS (Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os) sobre combust\u00edveis feito por Bolsonaro \u00e0s v\u00e9speras da elei\u00e7\u00e3o.<\/p>\n<p>Na entrevista, Haddad tamb\u00e9m comentou as falas recentes de Lula questionando o patamar elevados dos juros b\u00e1sicos e as cr\u00edticas do petista \u00e0 gest\u00e3o do presidente do BC, Roberto Campos Neto, e \u00e0 autonomia da institui\u00e7\u00e3o. O ministro disse que a redu\u00e7\u00e3o da Selic estava prevista para acontecer no in\u00edcio deste ano.<\/p>\n<p>\u201cA redu\u00e7\u00e3o da taxa de juros estava programada para acontecer no come\u00e7o do ano, depois da posse do presidente Lula. Quando soltei o primeiro pacote de medidas na dire\u00e7\u00e3o correta, imaginamos que isso fosse colaborar para essa decis\u00e3o\u201d.<\/p>\n<p>\u201cComo fazer uma pol\u00edtica fiscal saud\u00e1vel com uma taxa de juros que derruba a arrecada\u00e7\u00e3o e enfraquece a economia? Essa divis\u00e3o entre pol\u00edtica monet\u00e1ria e fiscal \u00e9 uma forma de pensar a economia que talvez n\u00e3o consiga traduzir a complexidade desse mecanismo, s\u00e3o dois bra\u00e7os que t\u00eam de trabalhar juntos.<\/p>\n<p>Haddad tamb\u00e9m culpou o governo Bolsonaro pela desacelera\u00e7\u00e3o da economia. \u201cAs medidas que o governo anterior tomou durante a elei\u00e7\u00e3o, absolutamente populistas, fizeram com que o mercado come\u00e7asse a cobrar taxas de juros cada vez maiores. Bagun\u00e7ou a economia, a elei\u00e7\u00e3o do Bolsonaro custou R$ 300 bilh\u00f5es\u201d.<\/p>\n<p>O ministro aproveitou para minimizar o embate que travou com a presidente do PT, Gleisi Hoffmann, ao retomar a tributa\u00e7\u00e3o dos combust\u00edveis, no in\u00edcio do m\u00eas. A deputada criticou a reonera\u00e7\u00e3o, por meio de uma dura publica\u00e7\u00e3o no Twitter.<\/p>\n<p>\u201cDefendo a prerrogativa da presidente do PT dizer o que pensa. Quando saiu [a postagem com as cr\u00edticas feitas por Gleisi], que eu estranhei, liguei para ela. Estava na \u00cdndia, conversamos longamente, depois liguei para o presidente Lula, para saber como estava a cabe\u00e7a dele. E, na minha opini\u00e3o, a decis\u00e3o que o presidente Lula tomou foi acertada\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"assinatura_exclusiva\">Douglas Gavras\/Folhapress<\/span><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Nova regra fiscal n\u00e3o ser\u00e1 meta de controle da d\u00edvida, diz Haddad' data-link='https:\/\/newsinfoco.com.br\/inicio\/nova-regra-fiscal-nao-sera-meta-de-controle-da-divida-diz-haddad\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O ministro da Fazenda, Fernando Haddad, afirmou que a nova regra fiscal que ir\u00e1 substituir o teto de gastos n\u00e3o ser\u00e1 uma meta de controle da d\u00edvida p\u00fablica. \u201cN\u00e3o \u00e9 uma regra de d\u00edvida, pois n\u00e3o acredito que isso funcionaria nas condi\u00e7\u00f5es locais\u201d, disse Haddad em entrevista \u00e0 CNN na noite desta sexta-feira (10). \u201cA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10381,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-33280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33280"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33280\/revisions"}],"predecessor-version":[{"id":33281,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33280\/revisions\/33281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/10381"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}