{"id":33303,"date":"2023-03-15T19:20:13","date_gmt":"2023-03-15T22:20:13","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33303"},"modified":"2023-03-15T19:20:13","modified_gmt":"2023-03-15T22:20:13","slug":"mais-cidadania-e-garantia-de-direitos-prefeitura-de-alagoinhas-inaugura-o-procon-municipal","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/mais-cidadania-e-garantia-de-direitos-prefeitura-de-alagoinhas-inaugura-o-procon-municipal\/","title":{"rendered":"Mais cidadania e garantia de direitos: Prefeitura de Alagoinhas inaugura o PROCON Municipal"},"content":{"rendered":"<p>Neste Dia do Consumidor, 15 de mar\u00e7o, a popula\u00e7\u00e3o de Alagoinhas e regi\u00e3o ganhou, da gest\u00e3o Joaquim Neto, o PROCON Municipal. O equipamento p\u00fablico rec\u00e9m-inaugurado funcionar\u00e1 de segunda a sexta-feira, das 07h \u00e0s 13h, no Centro Municipal de Atendimento ao Contribuinte (CMAC), dentro do Shopping Laguna\u00a0\u2013\u00a0<span class=\"LrzXr\">Rua Dr. Dantas Bi\u00e3o, 748, Alagoinhas Velha.\u00a0<\/span>O telefone para contato \u00e9: (75) 3422-8600.<\/p>\n<p>\u201cA estimativa, com o \u00faltimo Censo do IBGE, \u00e9 que Alagoinhas possua cerca de 160 mil habitantes. No entanto, al\u00e9m da popula\u00e7\u00e3o local, recebemos, em m\u00e9dia, 40 mil visitantes por dia, pessoas que trazem renda para a nossa cidade e que tamb\u00e9m precisam desse suporte\u201d, disse o prefeito Joaquim Neto, destacando a pujan\u00e7a cada vez maior do com\u00e9rcio local, que alavanca investimentos no munic\u00edpio, e o apelo das for\u00e7as empresariais pela institui\u00e7\u00e3o do PROCON Municipal. \u201cAgora, o consumidor poder\u00e1 contar com um equipamento que ir\u00e1 proteg\u00ea-lo, dando-lhe uma tranq\u00fcilidade maior na hora das compras\u201d.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2657056451\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63989\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-2-1024x682.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-2-1024x682.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-2-300x200.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-2-768x512.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-2-105x70.jpeg 105w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-2.jpeg 1600w\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><\/p>\n<p>Com o novo \u00f3rg\u00e3o, chefiado pela Dra. Monalisa Morais, o munic\u00edpio passa a integrar o Sistema Nacional de Prote\u00e7\u00e3o e Defesa do Consumidor (SMDC). De acordo com a Diretora, \u201co cidad\u00e3o poder\u00e1 procurar o PROCON em todos os casos que envolvam rela\u00e7\u00f5es de consumo, quer seja compra de servi\u00e7os ou produtos. Por exemplo: cobran\u00e7as indevidas, defeitos no produto, servi\u00e7os de telefonia, empr\u00e9stimos n\u00e3o solicitados e etc\u201d.<\/p>\n<p>A Diretora do PROCON Municipal ressaltou o empenho da deputada Ludmilla Fiscina, sobretudo no interm\u00e9dio com o PROCON Estadual para o treinamento da equipe, que ir\u00e1 receber, analisar, avaliar, apurar e encaminhar consultas, reclama\u00e7\u00f5es, den\u00fancias e sugest\u00f5es apresentadas por consumidores, fornecedores, entidades representativas ou pessoas jur\u00eddicas de direito p\u00fablico ou privado. O PROCON tamb\u00e9m \u00a0far\u00e1 notifica\u00e7\u00f5es aos fornecedores para que prestem informa\u00e7\u00f5es sobre quest\u00f5es de interesse do consumidor; poder\u00e1 mediar conflitos de consumo, designando audi\u00eancias de concilia\u00e7\u00e3o e reuni\u00f5es t\u00e9cnicas; celebrar\u00e1 termos de ajustamento de conduta com fornecedores e demais intervenientes das rela\u00e7\u00f5es, dentre outros encaminhamentos.<\/p>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.54-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63995\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.54-1-1024x682.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.54-1-1024x682.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.54-1-300x200.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.54-1-768x512.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.54-1-105x70.jpeg 105w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.54-1.jpeg 1600w\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><\/p>\n<p>Marcaram presen\u00e7a na inaugura\u00e7\u00e3o, al\u00e9m do prefeito Joaquim Neto e da primeira-dama e deputada estadual Ludmilla Fiscina, a Diretora do PROCON Monalisa Moraes, o vice-prefeito e secret\u00e1rio de Servi\u00e7os P\u00fablicos Roberto Torres, os secret\u00e1rios Jo\u00e3o Rabelo (Governo), Gustavo Carmo (Educa\u00e7\u00e3o), Bruno Fagundes (Desenvolvimento Econ\u00f4mico e Meio Ambiente), George Cabor\u00e9 (Agricultura), M\u00e1rcio Gomes (Comunica\u00e7\u00e3o), \u00a0Roseane Concei\u00e7\u00e3o (Fazenda), Iraci Gama (Cultura, esporte e Turismo), Virg\u00ednia Porto (Planejamento); o Ouvidor Municipal David Ribeiro, o Procurador Geral do Munic\u00edpio James Gaut\u00e9rio, o Subprocurador Hilton Ribeiro; os vereadores \u00a0Anderson Baqueiro, \u00a0Jorge Farinha, Gode Luxo; al\u00e9m do\u00a0 Delegado de Aramari Ricardo Brito, do \u00a0promotor de Justi\u00e7a Dario Jos\u00e9 Kist, da representante dos Juizados Especiais Ta\u00eds Moura, dentre outras autoridades.<\/p>\n<p>Segundo o Procurador-Geral James Gaut\u00e9ro, o PROCON Municipal nasce com o DNA de Alagoinhas, \u201ccom um esp\u00edrito conciliador e um espa\u00e7o de media\u00e7\u00e3o alternativo ao Judici\u00e1rio, com a estrutura do Poder Executivo municipal\u201d. O Subprocurador Hilton Ribeiro reiterou o papel educativo da entidade no contexto das rela\u00e7\u00f5es de consumo, em que o PROCON passa a ser o primeiro contato do consumidor em busca de solu\u00e7\u00f5es para a sua demanda, \u201cisso gera a sensa\u00e7\u00e3o de acolhimento e seguran\u00e7a. Alagoinhas passa a fazer parte de um grupo seleto de munic\u00edpios que vai oferecer esse servi\u00e7o, evitando que muitas demandas sejam ajuizadas\u201d.<\/p>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63992\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-2-1024x682.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-2-1024x682.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-2-300x200.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-2-768x512.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-2-105x70.jpeg 105w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-2.jpeg 1600w\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><\/p>\n<p>Em outubro do ano passado (2022), foi realizada uma Audi\u00eancia P\u00fablica na C\u00e2mara Municipal de Vereadores, requerida pelo vereador Anderson Baqueiro, para discuss\u00e3o do Projeto de Lei a respeito da implanta\u00e7\u00e3o do Procon Municipal. \u201cN\u00e3o t\u00ednhamos na cidade um \u00f3rg\u00e3o dessa magnitude, com um papel extremamente importante dentro da sociedade, resguardando as rela\u00e7\u00f5es de consumo. Essa \u00e9 uma grande conquista que tamb\u00e9m ir\u00e1 desafogar o judici\u00e1rio\u201d,\u00a0resumiu Baqueiro.<\/p>\n<p><strong>Conselho Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor (CONDECON)<\/strong><\/p>\n<p>Durante a inaugura\u00e7\u00e3o do PROCON, o chefe do Executivo tamb\u00e9m assinou um decreto nomeando os membros do\u00a0Conselho Municipal de Prote\u00e7\u00e3o e Defesa do Consumidor (CONDECON), a saber: a Presidente Monalisa Moraes Brito Costa e os conselheiros Jamile de Silva Cerqueira (Secretaria Municipal de Educa\u00e7\u00e3o), Wesley Ricardo Nogueira Chaves (Secretaria Municipal da Fazenda), Vilm\u00e1rio Calazans de Lima (Secretaria Municipal de Desenvolvimento Econ\u00f4mico e Meio Ambiente), Jess\u00e9 Machado dos Reis (Secretaria Municipal de Agricultura), Milton da Silva Ribeiro (Procuradoria Geral do Munic\u00edpio), Davi Ribeiro (Ouvidoria Geral), Rusely dos Santos de Almeida (Vigil\u00e2ncia Sanit\u00e1ria), Isl\u00eanio dos Santos da Trindade (C\u00e2mara de Vereadores de Alagoinhas) , Jo\u00e3o Eduardo Santos Ara\u00fajo (C\u00e2mara dos Dirigentes Lojistas), Jos\u00e9 Carlos Garcia Telles (Associa\u00e7\u00e3o Comercial de Alagoinhas \u2013 ACIA), J\u00falia Cristina Souza Gaud\u00eancio (UAMA), Marcelo Brasileiro Gallo (OAB), Benedito Vieira dos Santos (SICOM\u00c9RCIO).<\/p>\n<p><strong>C\u00f3digo Brasileiro de Defesa do Consumidor<\/strong><\/p>\n<p>O C\u00f3digo Brasileiro de Defesa do Consumidor preconiza os seguintes direitos:<\/p>\n<ul>\n<li>Direito \u00e0 vida, sa\u00fade e seguran\u00e7a. Nesse sentido, os produtos e servi\u00e7os n\u00e3o devem trazer riscos aos consumidores;<\/li>\n<li>Direito \u00e0 educa\u00e7\u00e3o, informa\u00e7\u00e3o e liberdade de escolha, para que consumidores tenham par\u00e2metros para tomar decis\u00f5es;<\/li>\n<li>Direito \u00e0 prote\u00e7\u00e3o contra publicidade enganosa e abusiva, para n\u00e3o prejudicar a compreens\u00e3o do p\u00fablico sobre um produto ou servi\u00e7o;<\/li>\n<li>Direito \u00e0 prote\u00e7\u00e3o contratual, para ningu\u00e9m sair em desvantagem ou ser prejudicado por cl\u00e1usulas abusivas;<\/li>\n<li>Direito \u00e0 preven\u00e7\u00e3o e repara\u00e7\u00e3o de danos, pois o consumidor n\u00e3o pode arcar com preju\u00edzos que sofreu devido aos produtos ou servi\u00e7os;<\/li>\n<li>Direito \u00e0 facilita\u00e7\u00e3o da defesa de direitos, garantindo aos clientes a chance de sempre ir \u00e0 Justi\u00e7a fazer valer seus direitos;<\/li>\n<li>Direito ao servi\u00e7o p\u00fablico adequado e eficaz, pois esse tipo de servi\u00e7o deve ser garantido pelos \u00f3rg\u00e3os p\u00fablicos.<\/li>\n<\/ul>\n<p>Fotos: Roberto Fonseca<\/p>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.50-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63987\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.50-1-1024x682.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.50-1-1024x682.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.50-1-300x200.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.50-1-768x512.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.50-1-105x70.jpeg 105w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.50-1.jpeg 1600w\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-3.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63990\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-3-1024x682.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-3-1024x682.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-3-300x200.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-3-768x512.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-3-105x70.jpeg 105w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.51-3.jpeg 1600w\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63991\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1-1024x682.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1-1024x682.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1-300x200.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1-768x512.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1-105x70.jpeg 105w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1.jpeg 1600w\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63994\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1024x682.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-1024x682.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-300x200.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-768x512.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53-105x70.jpeg 105w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/03\/WhatsApp-Image-2023-03-15-at-10.33.53.jpeg 1600w\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><\/p>\n<div align=\"right\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Mais cidadania e garantia de direitos: Prefeitura de Alagoinhas inaugura o PROCON Municipal' data-link='https:\/\/newsinfoco.com.br\/inicio\/mais-cidadania-e-garantia-de-direitos-prefeitura-de-alagoinhas-inaugura-o-procon-municipal\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Neste Dia do Consumidor, 15 de mar\u00e7o, a popula\u00e7\u00e3o de Alagoinhas e regi\u00e3o ganhou, da gest\u00e3o Joaquim Neto, o PROCON Municipal. O equipamento p\u00fablico rec\u00e9m-inaugurado funcionar\u00e1 de segunda a sexta-feira, das 07h \u00e0s 13h, no Centro Municipal de Atendimento ao Contribuinte (CMAC), dentro do Shopping Laguna\u00a0\u2013\u00a0Rua Dr. Dantas Bi\u00e3o, 748, Alagoinhas Velha.\u00a0O telefone para contato [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-33303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33303"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33303\/revisions"}],"predecessor-version":[{"id":33305,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33303\/revisions\/33305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33304"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}