{"id":33433,"date":"2023-03-22T19:46:20","date_gmt":"2023-03-22T22:46:20","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33433"},"modified":"2023-03-22T19:48:36","modified_gmt":"2023-03-22T22:48:36","slug":"estadao-planalto-teme-repercussao-de-fala-de-lula-sobre-moro-apos-pf-desarticular-plano-de-atentado-do-pcc-contra-o-ex-juiz","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/estadao-planalto-teme-repercussao-de-fala-de-lula-sobre-moro-apos-pf-desarticular-plano-de-atentado-do-pcc-contra-o-ex-juiz\/","title":{"rendered":"Estad\u00e3o: Planalto teme repercuss\u00e3o de fala de Lula sobre Moro ap\u00f3s PF desarticular plano de atentado do PCC contra o ex-juiz"},"content":{"rendered":"<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">O Pal\u00e1cio do Planalto montou opera\u00e7\u00e3o para tentar conter a repercuss\u00e3o negativa da fala do presidente Luiz In\u00e1cio Lula da Silva (PT) que, no per\u00edodo em que esteve preso em Curitiba, admitiu que dizia a procuradores e delegados que s\u00f3 iria \u201cficar bem quando foder com o Moro\u201d. A declara\u00e7\u00e3o de Lula foi dada um dia antes de a Pol\u00edcia Federal divulgar que o senador Sergio Moro (Uni\u00e3o-PR) poderia ser alvo de um atentado organizado por integrantes do Primeiro Comando da Capital (PCC).<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Com Lula fora de Bras\u00edlia para participar de eventos de entregas de obras, o ministro da Secretaria de Comunica\u00e7\u00e3o Social (Secom), Paulo Pimenta (PT), convocou \u00e0s pressas uma coletiva de imprensa para declarar que as tentativas de associar o presidente \u00e0s a\u00e7\u00f5es de grupos criminosos s\u00e3o \u201cperversas\u201d e \u201cfora de prop\u00f3sito\u201d. Pimenta chamou os jornalistas para apresentar a vers\u00e3o do governo com apenas 15 minutos de anteced\u00eancia e foi acompanhado de ao menos cinco assessores. A rea\u00e7\u00e3o veio ap\u00f3s o governo detectar que bolsonaristas estavam explorando o epis\u00f3dio nas redes.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1061565771\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p class=\"continue-read-break\" data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Antes de Pimenta vir a p\u00fablico, o ministro da Justi\u00e7a, Fl\u00e1vio Dino tamb\u00e9m fez quest\u00e3o de desvincular a fala de Lula da opera\u00e7\u00e3o da PF contra a organiza\u00e7\u00e3o criminosa de S\u00e3o Paulo.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">\u201cTentar, como algumas pessoas est\u00e3o tentando, estabelecer um v\u00ednculo entre essa declara\u00e7\u00e3o e a opera\u00e7\u00e3o conduzida pela PF \u00e9 algo absolutamente fora de prop\u00f3sito e serve evidentemente para a disputa pol\u00edtica\u201d, afirmou Pimenta. \u201cQuerer fazer esse v\u00ednculo \u00e9 uma estrat\u00e9gia perversa e mais uma forma de estabelecer uma rela\u00e7\u00e3o de questionamento das institui\u00e7\u00f5es, que enfraquece a democracia e que deve ser repudiada\u201d, argumentou o ministro.<\/p>\n<p class=\"\" tabindex=\"-1\" data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\" aria-expanded=\"true\">Moro est\u00e1 entre os pol\u00edticos que reagiram \u00e0 fala de Lula, assim como t\u00eam feito os parlamentares que apoiam o ex-presidente Jair Bolsonaro (PL). Em entrevista \u00e0 CNN na \u00faltima ter\u00e7a-feira, 21, o senador disse temer risco a seus familiares ap\u00f3s a fala de Lula. \u201cRepudio veementemente, acho que o presidente feriu a liturgia do cargo por utilizar esse palavreado de baixo cal\u00e3o e simplesmente a gente tem que questionar quando isso \u00e9 utilizado como forma de desviar o foco dos fracassos do governo federal\u201d, afirmou.<\/p>\n<p class=\"\" tabindex=\"-1\" data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\" aria-expanded=\"true\">O ministro da Secom tentou minimizar as declara\u00e7\u00f5es de Lula, alegando ser apenas uma manifesta\u00e7\u00e3o de quem esteve preso e se sentiu injusti\u00e7ado. \u201cA manifesta\u00e7\u00e3o do presidente Lula foi uma manifesta\u00e7\u00e3o em que ele relatou o sentimento de injusti\u00e7a e indigna\u00e7\u00e3o. Absolutamente natural e compreens\u00edvel que algu\u00e9m que ficou 580 dias detido numa solit\u00e1ria e que depois teve todos os seus processos anulados\u201d, argumentou. \u201cPortanto, a manifesta\u00e7\u00e3o do presidente Lula tem que ser compreendida dentro do contexto em que ele relata o momento que ele estava vivendo\u201d, prosseguiu.<\/p>\n<p class=\"\" tabindex=\"-1\" data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\" aria-expanded=\"true\">O presidente foi condenado por Moro quando ele ainda era juiz federal na 13\u00aa Vara de Curitiba, ent\u00e3o respons\u00e1vel pelos processo da opera\u00e7\u00e3o Lava Jato. As decis\u00f5es do ex-juiz, no entanto, acabaram anuladas pelo Supremo Tribunal Federal (STF), que o considerou parcial ao julgar Lula e declarou a Justi\u00e7a do Paran\u00e1 incompetente.<\/p>\n<p tabindex=\"-1\" data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\" aria-expanded=\"true\">Estad\u00e3o Conteudo<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Estad\u00e3o: Planalto teme repercuss\u00e3o de fala de Lula sobre Moro ap\u00f3s PF desarticular plano de atentado do PCC contra o ex-juiz' data-link='https:\/\/newsinfoco.com.br\/inicio\/estadao-planalto-teme-repercussao-de-fala-de-lula-sobre-moro-apos-pf-desarticular-plano-de-atentado-do-pcc-contra-o-ex-juiz\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O Pal\u00e1cio do Planalto montou opera\u00e7\u00e3o para tentar conter a repercuss\u00e3o negativa da fala do presidente Luiz In\u00e1cio Lula da Silva (PT) que, no per\u00edodo em que esteve preso em Curitiba, admitiu que dizia a procuradores e delegados que s\u00f3 iria \u201cficar bem quando foder com o Moro\u201d. A declara\u00e7\u00e3o de Lula foi dada um [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-33433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33433"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33433\/revisions"}],"predecessor-version":[{"id":33435,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33433\/revisions\/33435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/11039"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}