{"id":33503,"date":"2023-04-02T19:20:24","date_gmt":"2023-04-02T22:20:24","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33503"},"modified":"2023-04-02T19:20:24","modified_gmt":"2023-04-02T22:20:24","slug":"jeronimo-rodrigues-visita-industria-de-alimentos-na-china-e-empresas-baianas-assinam-acordo-de-cooperacao-estrategica","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/jeronimo-rodrigues-visita-industria-de-alimentos-na-china-e-empresas-baianas-assinam-acordo-de-cooperacao-estrategica\/","title":{"rendered":"Jer\u00f4nimo Rodrigues visita ind\u00fastria de alimentos na China e empresas baianas assinam acordo de coopera\u00e7\u00e3o estrat\u00e9gica"},"content":{"rendered":"<p>O domingo do governador Jer\u00f4nimo Rodrigues foi de trabalho na China. Ele viajou de Pequim para a cidade de Liaocheng, no estado de Shandong, localizada 430 quil\u00f4metros ao sul da capital, para conhecer uma ind\u00fastria de alimentos e produtos de medicina natural, a Deej World. A comitiva baiana se reuniu com a dire\u00e7\u00e3o da companhia que tem interesses em investir na Bahia. Na oportunidade, foi assinado um protocolo de coopera\u00e7\u00e3o estrat\u00e9gica entre a Deej e empresas baianas que atuam no setor agropecu\u00e1rio. O objetivo \u00e9 que essas empresas possam exportar sua produ\u00e7\u00e3o para a China, maior parceiro comercial estrangeiro da Bahia.<\/p>\n<p>O estado de Shandong tem a terceira maior economia da China e a maior produ\u00e7\u00e3o agr\u00edcola de frutas e hortali\u00e7as. Com uma popula\u00e7\u00e3o de 100 milh\u00f5es de habitantes, o equivalente a 7% da popula\u00e7\u00e3o do pa\u00eds, Shandong \u00e9 considerado um estado irm\u00e3o da Bahia com quem mant\u00e9m rela\u00e7\u00f5es comerciais h\u00e1 24 anos.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2793666374\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>\u201cViemos refor\u00e7ar a rela\u00e7\u00e3o que j\u00e1 existe entre a Bahia e Shandong, e aproveitamos para formalizar um acordo de coopera\u00e7\u00e3o estrat\u00e9gica empresarial na \u00e1rea da agropecu\u00e1ria. Com a popula\u00e7\u00e3o que tem, Shandong representa um mercado consumidor importante para os produtores baianos e queremos aproveitar isso\u201d, explicou Jer\u00f4nimo.<\/p>\n<p>No fim do dia (pelo hor\u00e1rio local), a comitiva baiana foi recebida pelo vice-governador de Shandong, Hon Deng, que fez uma apresenta\u00e7\u00e3o sobre o estado e garantiu o interesse em manter rela\u00e7\u00f5es comerciais com a Bahia. \u201cCom o fim da pandemia, criou-se uma situa\u00e7\u00e3o econ\u00f4mica muito favor\u00e1vel para os investimentos em diversas \u00e1reas e podemos fazer neg\u00f3cios na agropecu\u00e1ria, infraestrutura e turismo, por exemplo. O governador Jer\u00f4nimo \u00e9 o primeiro governador brasileiro a ser recebido por um governador chin\u00eas ap\u00f3s a reabertura do pa\u00eds e vamos fazer os esfor\u00e7os necess\u00e1rios para por em pr\u00e1tica os interesses de nossos dois povos\u201d, destacou Hon Deng.<\/p>\n<p>A agenda de Jer\u00f4nimo Rodrigues segue nesta segunda-feira, quando ele retorna a Pequim para encontros empresariais. Est\u00e3o com o governador na miss\u00e3o internacional os secret\u00e1rios estaduais de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, Andr\u00e9 Joazeiro; e de Desenvolvimento Econ\u00f4mico, Angelo Almeida; al\u00e9m do superintendente de Atra\u00e7\u00e3o de Investimentos e Fomento ao Desenvolvimento, da SDE, Paulo Guimar\u00e3es.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"carregar-mais\">Politicalivre<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Jer\u00f4nimo Rodrigues visita ind\u00fastria de alimentos na China e empresas baianas assinam acordo de coopera\u00e7\u00e3o estrat\u00e9gica' data-link='https:\/\/newsinfoco.com.br\/inicio\/jeronimo-rodrigues-visita-industria-de-alimentos-na-china-e-empresas-baianas-assinam-acordo-de-cooperacao-estrategica\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O domingo do governador Jer\u00f4nimo Rodrigues foi de trabalho na China. Ele viajou de Pequim para a cidade de Liaocheng, no estado de Shandong, localizada 430 quil\u00f4metros ao sul da capital, para conhecer uma ind\u00fastria de alimentos e produtos de medicina natural, a Deej World. A comitiva baiana se reuniu com a dire\u00e7\u00e3o da companhia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-33503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33503"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33503\/revisions"}],"predecessor-version":[{"id":33504,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33503\/revisions\/33504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33352"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}