{"id":33559,"date":"2023-04-09T17:07:14","date_gmt":"2023-04-09T20:07:14","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33559"},"modified":"2023-04-09T17:07:14","modified_gmt":"2023-04-09T20:07:14","slug":"alagoinhas-inicia-vacinacao-contra-gripe-influenza-na-proxima-segunda-10","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/alagoinhas-inicia-vacinacao-contra-gripe-influenza-na-proxima-segunda-10\/","title":{"rendered":"Alagoinhas inicia vacina\u00e7\u00e3o contra Gripe Influenza na pr\u00f3xima segunda (10)"},"content":{"rendered":"<p>Inicia na pr\u00f3xima segunda-feira (10) a Campanha Nacional de Vacina\u00e7\u00e3o, que acontece todos os anos, contra a Gripe Influenza em Alagoinhas. A vacina\u00e7\u00e3o ser\u00e1 realizada em todas as unidades b\u00e1sicas de sa\u00fade do munic\u00edpio e na Central de Imuniza\u00e7\u00e3o.<br \/>\nA campanha que \u00e9 direcionada para pessoas idosas com mais 60 anos, crian\u00e7as de 06 meses a menor de 06 anos, gestantes, pu\u00e9rperas ou e profissionais de sa\u00fade, ter\u00e1 atendimentos de segunda a sexta-feira: nas Unidades de Sa\u00fade da Fam\u00edlia das 08h \u00e0s 12h e na Central de Imuniza\u00e7\u00e3o das 08h \u00e0s 11h e das 13h \u00e0s 16h.<\/p>\n<p>Compreende como trabalhadores de sa\u00fade as seguintes categorias bem como seus t\u00e9cnicos e auxiliares:m\u00e9dicos; enfermeiros; nutricionistas; fisioterapeutas; terapeutas ocupacionais; bi\u00f3logos; biom\u00e9dicos; farmac\u00eauticos; odontologistas; fonoaudi\u00f3logos; psic\u00f3logos; assistentes sociais; profissionais de educa\u00e7\u00e3o f\u00edsica; m\u00e9dico veterin\u00e1rios; cuidadores de idosos; e atendente de farm\u00e1cia.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-339451803\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Para receber os imunizantes ser\u00e1 necess\u00e1rio portar documento de identifica\u00e7\u00e3o e cart\u00e3o sus\/CPF, cart\u00e3o de vacina\u00e7\u00e3o (obrigat\u00f3rio).<\/p>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/B91E8835-E971-4C07-B2AD-0F41C659C6BB.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-64723\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/B91E8835-E971-4C07-B2AD-0F41C659C6BB-1024x1024.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/B91E8835-E971-4C07-B2AD-0F41C659C6BB-1024x1024.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/B91E8835-E971-4C07-B2AD-0F41C659C6BB-300x300.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/B91E8835-E971-4C07-B2AD-0F41C659C6BB-768x768.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/B91E8835-E971-4C07-B2AD-0F41C659C6BB-70x70.jpeg 70w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/B91E8835-E971-4C07-B2AD-0F41C659C6BB.jpeg 1080w\" alt=\"\" width=\"800\" height=\"800\" \/><\/a><\/p>\n<p><a class=\"group1 cboxElement\" href=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/E3E3E8EF-63B4-4AB4-8F0C-B28372711F00.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-64724\" src=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/E3E3E8EF-63B4-4AB4-8F0C-B28372711F00-1024x1024.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/E3E3E8EF-63B4-4AB4-8F0C-B28372711F00-1024x1024.jpeg 1024w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/E3E3E8EF-63B4-4AB4-8F0C-B28372711F00-300x300.jpeg 300w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/E3E3E8EF-63B4-4AB4-8F0C-B28372711F00-768x768.jpeg 768w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/E3E3E8EF-63B4-4AB4-8F0C-B28372711F00-70x70.jpeg 70w, https:\/\/www.alagoinhas.ba.gov.br\/wp-content\/uploads\/2023\/04\/E3E3E8EF-63B4-4AB4-8F0C-B28372711F00.jpeg 1080w\" alt=\"\" width=\"800\" height=\"800\" \/><\/a><\/p>\n<div align=\"right\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Alagoinhas inicia vacina\u00e7\u00e3o contra Gripe Influenza na pr\u00f3xima segunda (10)' data-link='https:\/\/newsinfoco.com.br\/inicio\/alagoinhas-inicia-vacinacao-contra-gripe-influenza-na-proxima-segunda-10\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Inicia na pr\u00f3xima segunda-feira (10) a Campanha Nacional de Vacina\u00e7\u00e3o, que acontece todos os anos, contra a Gripe Influenza em Alagoinhas. A vacina\u00e7\u00e3o ser\u00e1 realizada em todas as unidades b\u00e1sicas de sa\u00fade do munic\u00edpio e na Central de Imuniza\u00e7\u00e3o. A campanha que \u00e9 direcionada para pessoas idosas com mais 60 anos, crian\u00e7as de 06 meses [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33560,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-33559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33559"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33559\/revisions"}],"predecessor-version":[{"id":33561,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33559\/revisions\/33561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33560"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}