{"id":33565,"date":"2023-04-09T17:12:45","date_gmt":"2023-04-09T20:12:45","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33565"},"modified":"2023-04-09T17:12:45","modified_gmt":"2023-04-09T20:12:45","slug":"apoio-a-privatizacao-da-salto-e-chega-a-38-da-populacao-diz-datafolha","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/apoio-a-privatizacao-da-salto-e-chega-a-38-da-populacao-diz-datafolha\/","title":{"rendered":"Apoio \u00e0 privatiza\u00e7\u00e3o d\u00e1 salto e chega a 38% da popula\u00e7\u00e3o, diz Datafolha"},"content":{"rendered":"<p>O apoio dos brasileiros \u00e0 privatiza\u00e7\u00e3o de empresas e servi\u00e7os p\u00fablicos deu um salto nos \u00faltimos seis meses, e a maioria da popula\u00e7\u00e3o avalia positivamente a qualidade do atendimento e dos produtos entregues pela iniciativa privada na compara\u00e7\u00e3o com os fornecidos pelo Estado.<\/p>\n<p>A ades\u00e3o da popula\u00e7\u00e3o \u00e0 continuidade da venda de ativos estatais \u00e9 maior nos setores em que j\u00e1 houve privatiza\u00e7\u00f5es e concess\u00f5es, como em rodovias, saneamento, aeroportos e energia el\u00e9trica. Mas, apesar de considerarem melhores os produtos e servi\u00e7os privados, os brasileiros os acham mais caros.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3798119058\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Segundo pesquisa Datafolha, 38% dos brasileiros apoiam as privatiza\u00e7\u00f5es, ante 45% que se dizem contr\u00e1rios. A taxa de aprova\u00e7\u00e3o \u00e9 a maior da s\u00e9rie do Datafolha pelo menos desde 2017, quando apenas 20% eram favor\u00e1veis ao tema. No geral, homens apoiam mais (46%) do que as mulheres (30%).<\/p>\n<p>Apesar de mais brasileiros aprovarem as privatiza\u00e7\u00f5es, n\u00e3o h\u00e1 apoio ou rejei\u00e7\u00e3o majorit\u00e1rios, revelando que a opini\u00e3o sobre o assunto ainda n\u00e3o est\u00e1 cristalizada.<\/p>\n<p>Em setembro do ano passado, apenas 26% se diziam a favor da transfer\u00eancia de empresas e servi\u00e7os p\u00fablicos ao setor privado, enquanto 66% eram contr\u00e1rios.<\/p>\n<p>O aumento do apoio \u00e0s privatiza\u00e7\u00f5es pode ter rela\u00e7\u00e3o com o fato de o Partido dos Trabalhadores, refrat\u00e1rio ao tema, ter vencido as elei\u00e7\u00f5es presidenciais em 2022. Em um cen\u00e1rio de divis\u00e3o do eleitorado, simpatizantes de Jair Bolsonaro (PL) ou de partidos \u00e0 direita podem ter refor\u00e7ado suas convic\u00e7\u00f5es ao responder \u00e0 pesquisa.<\/p>\n<p>Segundo o Datafolha, 70% dos apoiadores do PL s\u00e3o favor\u00e1veis \u00e0s privatiza\u00e7\u00f5es. Entre os simpatizantes do PT, apenas 28%.<\/p>\n<p>Na semana passada, o presidente Luiz In\u00e1cio Lula da Silva (PT) decretou a retirada dos Correios, da EBC (Empresa Brasileira de Comunica\u00e7\u00e3o) e da Conab (Companhia Nacional de Abastecimento) da lista de privatiza\u00e7\u00f5es de Bolsonaro. As tr\u00eas estatais fazem parte de um pacote com mais sete exclu\u00eddas do PPI (Programas de Parceiras e Investimentos) e do PND (Programa Nacional de Desestatiza\u00e7\u00e3o).<\/p>\n<p>Segundo o Datafolha, quanto mais escolarizado e rico, maior a ades\u00e3o \u00e0s privatiza\u00e7\u00f5es. Mas, mesmo entre as fam\u00edlias mais pobres, com renda at\u00e9 dois sal\u00e1rios m\u00ednimos, o apoio n\u00e3o \u00e9 muito discrepante da m\u00e9dia da popula\u00e7\u00e3o \u201434% e 38%, respectivamente.<\/p>\n<p>O Datafolha tamb\u00e9m questionou os brasileiros sobre como avaliam a qualidade dos produtos e servi\u00e7os entregues pela iniciativa privada em compara\u00e7\u00e3o aos de estatais. A maioria (54%) considera melhores os privados; 25% os acham piores; 6% consideram iguais e 15% n\u00e3o souberam responder.<\/p>\n<p>Em termos et\u00e1rios, 63% dos que t\u00eam entre 16 e 34 anos consideram os produtos e servi\u00e7os privados melhores do que os estatais. Para os acima de 60 anos, s\u00f3 42% t\u00eam essa avalia\u00e7\u00e3o. Os mais jovens, no entanto, acham mais caros os produtos e servi\u00e7os privados do que os mais velhos.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 qualidade do atendimento aos clientes, 61% acham melhor a fornecida pelas empresas privadas na compara\u00e7\u00e3o com as estatais, enquanto 22% consideram pior \u2014outros 6% acham igual e 11% n\u00e3o souberam responder.<\/p>\n<p>No entanto, quando questionados sobre os pre\u00e7os dos produtos e servi\u00e7os oferecidos pelas empresas privadas na compara\u00e7\u00e3o com os de estatais, 67% responderam que os primeiros s\u00e3o mais caros, enquanto 19% consideram os p\u00fablicos mais baratos. Quanto mais pobre a fam\u00edlia, maior a percep\u00e7\u00e3o de que os pre\u00e7os privados s\u00e3o mais elevados.<\/p>\n<p>A pesquisa Datafolha ouviu 2.028 pessoas com 16 anos ou mais em 126 munic\u00edpios nos dias 29 e 30 de mar\u00e7o, e tem margem de erro de dois pontos percentuais, para mais ou para menos.<\/p>\n<p>No levantamento, o Datafolha tamb\u00e9m questionou os entrevistados sobre o apoio \u00e0 transfer\u00eancia para o setor privado de empresas e servi\u00e7os estatais.<\/p>\n<p>A ades\u00e3o dos brasileiros \u00e0 privatiza\u00e7\u00e3o \u00e9 menor quando se trata da Petrobras (37% a favor, 53% contra; os demais s\u00e3o indiferentes ou n\u00e3o sabem) e de bancos p\u00fablicos, como Banco do Brasil e Caixa Econ\u00f4mica federal (36% a favor, 55% contra). No caso dos Correios h\u00e1 um virtual empate entre os favor\u00e1veis \u00e0 privatiza\u00e7\u00e3o (45%) e os contr\u00e1rios (46%).<\/p>\n<p>Em setores em que j\u00e1 houve uma s\u00e9rie de desestatiza\u00e7\u00f5es (e grandes investimentos por parte das empresas privadas), o apoio dos brasileiros \u00e0 continuidade da venda de ativos estatais tende a ser maior do que o percentual dos contr\u00e1rios.<\/p>\n<p>No caso das rodovias, 48% dos entrevistados s\u00e3o a favor das privatiza\u00e7\u00f5es; 44%, contra. Segundo associa\u00e7\u00e3o que re\u00fane as concession\u00e1rias no pa\u00eds, elas investiram, nos \u00faltimos 25 anos, cerca de R$ 240 bilh\u00f5es nos 24 mil quil\u00f4metros de rodovias hoje concedidas.<\/p>\n<p>De acordo com a Funda\u00e7\u00e3o Dom Cabral a partir de registros da Pol\u00edcia Rodovi\u00e1ria Federal entre 2018 e 2021, o risco de acidentes em rodovia p\u00fablica \u00e9 quatro vezes maior do que em estradas concedidas.<\/p>\n<p>No setor de aeroportos, 47% apoiam a privatiza\u00e7\u00e3o, enquanto 42% s\u00e3o contra. Nos \u00faltimos anos, o percentual de passageiros que avaliam os aeroportos como bons\/muitos bons saltou de 69%, em 2013, para 92% em 2021, segundo a Secretaria Nacional de Avia\u00e7\u00e3o Civil.<\/p>\n<p>No saneamento b\u00e1sico, em que quase a metade da popula\u00e7\u00e3o ainda n\u00e3o tem esgoto tratado, 49% dos brasileiros apoiam a privatiza\u00e7\u00e3o; 44% s\u00e3o contra.<\/p>\n<p>Desde a aprova\u00e7\u00e3o do chamado novo marco regulat\u00f3rio do saneamento, em 2020, o governo federal contabiliza cerca de R$ 90 bilh\u00f5es em investimentos e outorgas pagas pelas empresas privadas para presta\u00e7\u00e3o de servi\u00e7os em 225 munic\u00edpios. A pretens\u00e3o \u00e9 que, at\u00e9 2033, 90% do esgoto no pa\u00eds seja coletado e tratado.<\/p>\n<p>Na semana passada, o governo Lula fez altera\u00e7\u00f5es no marco, consideradas um retrocesso. Com as mudan\u00e7as, abriu-se o caminho para que estatais estaduais operem os servi\u00e7os de \u00e1gua e esgoto sem licita\u00e7\u00e3o, alterando um dos fundamentos da lei sancionada em 2020.<\/p>\n<p>O Datafolha tamb\u00e9m questionou os brasileiros sobre como avaliam a privatiza\u00e7\u00e3o do sistema de telefonia, a partir da venda da Telebr\u00e1s, em 1998, no governo Fernando Henrique Cardoso (1995-2002).<\/p>\n<p>Para 39%, a transfer\u00eancia do servi\u00e7o estatal foi \u00f3tima\/boa, e outros 25% consideram o resultado regular. Cerca de um quarto (27%) acha que foi ruim\/p\u00e9ssima, e 9% n\u00e3o souberam avaliar.<\/p>\n<p>Antes da privatiza\u00e7\u00e3o da Telebr\u00e1s, o Brasil tinha 7,4 milh\u00f5es de aparelhos celulares ativos, e as linhas fixas eram caras a ponto de serem declaradas no Imposto de Renda. Hoje, o pa\u00eds tem 259,1 milh\u00f5es de linhas m\u00f3veis ativas, e o custo da liga\u00e7\u00e3o, em rela\u00e7\u00e3o a 1998, caiu de R$ 7 por minuto para R$ 0,44, em m\u00e9dia.<\/p>\n<p>As privatiza\u00e7\u00f5es no Brasil come\u00e7aram h\u00e1 mais de tr\u00eas d\u00e9cadas, com o lan\u00e7amento do Programa Nacional de Desestatiza\u00e7\u00e3o. As maiores ocorreram entre 1990 e 2000, em especial no governo FHC, quando foram vendidas empresas dos setores de telefonia, siderurgia, extra\u00e7\u00e3o mineral e bancos.<\/p>\n<p>Cerca de US$ 100,3 bilh\u00f5es foram arrecadados naquele per\u00edodo (em valores nominais). A partir de 2001, a venda de estatais diminuiu e deu lugar \u00e0s concess\u00f5es e \u00e0s PPPs (Parcerias P\u00fablico Privadas) \u2013levando \u00e0 transfer\u00eancia para o setor privado de rodovias e aeroportos, entre outros ativos.<\/p>\n<p>Apesar do enxugamento, o Brasil ainda tem 47 estatais sob controle do governo federal, que empregam cerca de 445 mil funcion\u00e1rios. Em 2021, o gasto com pessoal atingiu R$ 116,1 bilh\u00f5es, com algumas remunera\u00e7\u00f5es mensais superando R$ 100 mil, al\u00e9m de participa\u00e7\u00f5es generosas nos resultados e planos de aposentadoria e sa\u00fade muito superiores aos da iniciativa privada.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"assinatura_exclusiva\">Fernando Canzian, Folhapress<\/span><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Apoio \u00e0 privatiza\u00e7\u00e3o d\u00e1 salto e chega a 38% da popula\u00e7\u00e3o, diz Datafolha' data-link='https:\/\/newsinfoco.com.br\/inicio\/apoio-a-privatizacao-da-salto-e-chega-a-38-da-populacao-diz-datafolha\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O apoio dos brasileiros \u00e0 privatiza\u00e7\u00e3o de empresas e servi\u00e7os p\u00fablicos deu um salto nos \u00faltimos seis meses, e a maioria da popula\u00e7\u00e3o avalia positivamente a qualidade do atendimento e dos produtos entregues pela iniciativa privada na compara\u00e7\u00e3o com os fornecidos pelo Estado. A ades\u00e3o da popula\u00e7\u00e3o \u00e0 continuidade da venda de ativos estatais \u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-33565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33565"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33565\/revisions"}],"predecessor-version":[{"id":33566,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33565\/revisions\/33566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/3715"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}