{"id":33567,"date":"2023-04-09T17:14:55","date_gmt":"2023-04-09T20:14:55","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33567"},"modified":"2023-04-09T17:14:55","modified_gmt":"2023-04-09T20:14:55","slug":"jeronimo-visita-fabricas-da-byd-na-china-batalhar-para-levar-essa-industria-para-a-bahia","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/jeronimo-visita-fabricas-da-byd-na-china-batalhar-para-levar-essa-industria-para-a-bahia\/","title":{"rendered":"Jer\u00f4nimo visita f\u00e1bricas da BYD na China: \u201cbatalhar para levar essa ind\u00fastria para a Bahia\u201d"},"content":{"rendered":"<p>O governador Jer\u00f4nimo Rodrigues visitou, neste domingo (9), duas linhas de produ\u00e7\u00e3o da fabricante de ve\u00edculos el\u00e9tricos chinesa BYD. A primeira, na cidade de Hangzhou, produz \u00f4nibus 100% el\u00e9tricos, e a segunda, na cidade de Chengzhou, carros de passeio com a mesma tecnologia. Juntas, as unidades fabricam mais de 400 mil ve\u00edculos por ano e empregam mais de 9.200 pessoas. Inaugurada em 2021, a f\u00e1brica de carros chega a entregar 1.150 ve\u00edculos, por dia, num processo que tem 93% de automa\u00e7\u00e3o.<\/p>\n<p>\u201cDomingo de trabalho nesta P\u00e1scoa, e hoje come\u00e7amos cedo na visita de uma f\u00e1brica de \u00f4nibus da BYD. Vamos batalhar para levar essa ind\u00fastria para Bahia. Na parte da tarde, conhecemos uma f\u00e1brica de autom\u00f3veis de passeio da mesma empresa\u201d, disse Jer\u00f4nimo.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2189952780\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Com tecnologia criada por um grupo de desenvolvimento pr\u00f3prio, que conta com cerca de 40 mil engenheiros espalhados em diversas f\u00e1bricas pelo mundo, os carros el\u00e9tricos da BYD t\u00eam autonomia de 450 km por carga de bateria, uma das maiores do mercado. A empresa est\u00e1 em negocia\u00e7\u00e3o para ocupar a planta industrial da Ford, em Cama\u00e7ari.<\/p>\n<p>Conforme o governador, o tema ser\u00e1 tratado tamb\u00e9m em \u00e2mbito federal. \u201cA comitiva do presidente Lula chega, na ter\u00e7a ou na quarta-feira, e vou compor o grupo. A inten\u00e7\u00e3o \u00e9 que a gente feche acordo, feche neg\u00f3cios para que essa ind\u00fastria seja instalada na Bahia. Estamos trabalhando para isso, para gerar empregos e renda\u201d, declarou.<\/p>\n<p>A comitiva baiana \u00e9 formada pelos secret\u00e1rios estaduais da Secretaria de Desenvolvimento Econ\u00f4mico (SDE), Angelo Almeida; e de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Secti), Andr\u00e9 Joazeiro; al\u00e9m do superintendente da SDE, Paulo Guimar\u00e3es.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Jer\u00f4nimo visita f\u00e1bricas da BYD na China: \u201cbatalhar para levar essa ind\u00fastria para a Bahia\u201d' data-link='https:\/\/newsinfoco.com.br\/inicio\/jeronimo-visita-fabricas-da-byd-na-china-batalhar-para-levar-essa-industria-para-a-bahia\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O governador Jer\u00f4nimo Rodrigues visitou, neste domingo (9), duas linhas de produ\u00e7\u00e3o da fabricante de ve\u00edculos el\u00e9tricos chinesa BYD. A primeira, na cidade de Hangzhou, produz \u00f4nibus 100% el\u00e9tricos, e a segunda, na cidade de Chengzhou, carros de passeio com a mesma tecnologia. Juntas, as unidades fabricam mais de 400 mil ve\u00edculos por ano e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33568,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-33567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33567"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33567\/revisions"}],"predecessor-version":[{"id":33569,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33567\/revisions\/33569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33568"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}