{"id":33580,"date":"2023-04-09T17:28:15","date_gmt":"2023-04-09T20:28:15","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33580"},"modified":"2023-04-09T17:28:15","modified_gmt":"2023-04-09T20:28:15","slug":"aliados-querem-que-raissa-soares-assuma-a-lideranca-do-bolsonarismo-na-bahia","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/aliados-querem-que-raissa-soares-assuma-a-lideranca-do-bolsonarismo-na-bahia\/","title":{"rendered":"Aliados querem que Raissa Soares assuma a lideran\u00e7a do bolsonarismo na Bahia"},"content":{"rendered":"<p>Uma das grandes surpresas das elei\u00e7\u00f5es de 2022 na Bahia, Raissa Soares (PL), que foi candidata a senadora, deve come\u00e7ar a ser pressionada em breve a liderar a oposi\u00e7\u00e3o a Jer\u00f4nimo Rodrigues (PT) na Bahia.<\/p>\n<p>Apesar de ter conseguido quase meio milh\u00e3o de votos a mais que Jo\u00e3o Roma (PL) mesmo sem ter a exposi\u00e7\u00e3o que um candidato a governador possui, Raissa tem aparecido pouco desde o in\u00edcio deste ano.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-894325139\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A expectativa de bolsonaristas mais alinhados ao ex-presidente Jair Bolsonaro \u00e9 a de que Raissa tome para si a miss\u00e3o de representar Bolsonaro na Bahia, a considerar sua expressiva vota\u00e7\u00e3o, e se cacife a disputar a Prefeitura de alguma grande cidade baiana em 2024.<\/p>\n<p>Por enquanto, Raissa tem sido t\u00edmida nas considera\u00e7\u00f5es sobre pol\u00edtica \u2013 tanto a n\u00edvel estadual como a n\u00edvel nacional.<\/p>\n<p>Politicaaovivo<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Aliados querem que Raissa Soares assuma a lideran\u00e7a do bolsonarismo na Bahia' data-link='https:\/\/newsinfoco.com.br\/inicio\/aliados-querem-que-raissa-soares-assuma-a-lideranca-do-bolsonarismo-na-bahia\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Uma das grandes surpresas das elei\u00e7\u00f5es de 2022 na Bahia, Raissa Soares (PL), que foi candidata a senadora, deve come\u00e7ar a ser pressionada em breve a liderar a oposi\u00e7\u00e3o a Jer\u00f4nimo Rodrigues (PT) na Bahia. Apesar de ter conseguido quase meio milh\u00e3o de votos a mais que Jo\u00e3o Roma (PL) mesmo sem ter a exposi\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-33580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33580"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33580\/revisions"}],"predecessor-version":[{"id":33582,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33580\/revisions\/33582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33581"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}