{"id":33727,"date":"2023-04-18T12:12:14","date_gmt":"2023-04-18T15:12:14","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33727"},"modified":"2023-04-18T12:13:38","modified_gmt":"2023-04-18T15:13:38","slug":"apos-condenacao-de-paulo-cezar-na-justica-conversas-entre-federacaopt-pv-pc-do-b-e-governo-joaquim-neto-por-chapa-unica-em-eleicao-podem-esfriar-por-caio-pimenta","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/apos-condenacao-de-paulo-cezar-na-justica-conversas-entre-federacaopt-pv-pc-do-b-e-governo-joaquim-neto-por-chapa-unica-em-eleicao-podem-esfriar-por-caio-pimenta\/","title":{"rendered":"Ap\u00f3s condena\u00e7\u00e3o de Paulo Cezar na Justi\u00e7a, conversas entre Federa\u00e7\u00e3o(PT, PV, PC do B) e Governo Joaquim Neto por chapa \u00fanica em elei\u00e7\u00e3o podem esfriar &#8211; Por Caio Pimenta"},"content":{"rendered":"<p>A condena\u00e7\u00e3o do ex-prefeito Paulo Cezar a 2 anos e 6 meses de pris\u00e3o por participa\u00e7\u00e3o em um esquema fraudulento que desviou milh\u00f5es de reais do transporte escolar na \u00e9poca em que foi gestor do munic\u00edpio de Alagoinhas j\u00e1 come\u00e7a a interferir na conjuntura eleitoral do ano que vem.<\/p>\n<p>Com a possibilidade real de inexigibilidade do ex-prefeito, que \u00e9 pr\u00e9-candidato a prefeitura, caso uma decis\u00e3o da 2\u00aa instancia referende a condena\u00e7\u00e3o, as for\u00e7as politicas da base do governador Jer\u00f4nimo Rodrigues no munic\u00edpio, que discutem nos bastidores a forma\u00e7\u00e3o de uma chapa \u00fanica para o pleito do ano que vem, devem colocar o p\u00e9 no freio, pelo menos por enquanto.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2096558587\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Integrantes da Federa\u00e7\u00e3o Partid\u00e1ria formada por PT, PV e PC do B, ouvidos por esta coluna, informaram que o momento \u00e9 de avalia\u00e7\u00e3o. Nos pr\u00f3ximos meses devem ser discutidas as chances de Paulo Cezar se tornar ineleg\u00edvel e tamb\u00e9m o impacto politico \u00e0 sua imagem coma condena\u00e7\u00e3o. A mesma ideia \u00e9 tamb\u00e9m compartilhada por pessoas ligadas ao grupo liderado pelo prefeito Joaquim Neto.<\/p>\n<p>A opini\u00e3o \u00e9 que sem Paulo Cezar na disputa, ou com ele enfraquecido, as duas for\u00e7as politicas ligadas ao Governo Estadual, poderiam disputar o protagonismo municipal sem correrem o risco de perder o controle da prefeitura para oposi\u00e7\u00e3o.<\/p>\n<p>Ainda tamb\u00e9m \u00e9 incerto qual ser\u00e1 o posicionamento do grupo liderado pelo deputado federal Paulo Azi, que nas \u00faltimas elei\u00e7\u00f5es foi avalista do nome de Paulo Cezar. Ao defender a candidatura de um &#8220;condenado pela Justi\u00e7a&#8221; o custo politico pode respingar tanto no Grupo, quanto no seu l\u00edder.<\/p>\n<p>Estando na elei\u00e7\u00e3o, ou fora da elei\u00e7\u00e3o do ano que vem, o hoje &#8220;condenado&#8221; Paulo Cezar j\u00e1 influencia a conjuntura politica para o pleito eleitoral do ano que vem.<\/p>\n<p><strong><em>Escrito por Caio Pimenta, advogado, \u00e2ncora do programa Primeira M\u00e3o, da radio Ouro Negro 100,5 FM. Ele tamb\u00e9m escreve sua coluna no site News Infoco, do qual \u00e9 editor- chefe e dirige a radio web 2 de julho.<\/em><\/strong><\/p>\n<div class=\"google-auto-placed\"><\/div>\n<div class=\"google-auto-placed\"><\/div>\n<div class=\"share-to-whatsapp-wrapper\"><\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ap\u00f3s condena\u00e7\u00e3o de Paulo Cezar na Justi\u00e7a, conversas entre Federa\u00e7\u00e3o(PT, PV, PC do B) e Governo Joaquim Neto por chapa \u00fanica em elei\u00e7\u00e3o podem esfriar - Por Caio Pimenta' data-link='https:\/\/newsinfoco.com.br\/inicio\/apos-condenacao-de-paulo-cezar-na-justica-conversas-entre-federacaopt-pv-pc-do-b-e-governo-joaquim-neto-por-chapa-unica-em-eleicao-podem-esfriar-por-caio-pimenta\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A condena\u00e7\u00e3o do ex-prefeito Paulo Cezar a 2 anos e 6 meses de pris\u00e3o por participa\u00e7\u00e3o em um esquema fraudulento que desviou milh\u00f5es de reais do transporte escolar na \u00e9poca em que foi gestor do munic\u00edpio de Alagoinhas j\u00e1 come\u00e7a a interferir na conjuntura eleitoral do ano que vem. Com a possibilidade real de inexigibilidade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20614,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-33727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caio-pimenta"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33727"}],"version-history":[{"count":2,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33727\/revisions"}],"predecessor-version":[{"id":33729,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33727\/revisions\/33729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/20614"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}