{"id":33951,"date":"2023-05-15T17:54:55","date_gmt":"2023-05-15T20:54:55","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33951"},"modified":"2023-05-15T17:54:55","modified_gmt":"2023-05-15T20:54:55","slug":"stf-faz-maioria-e-agora-ja-sao-795-radicais-no-banco-dos-reus-do-8-de-janeiro","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/stf-faz-maioria-e-agora-ja-sao-795-radicais-no-banco-dos-reus-do-8-de-janeiro\/","title":{"rendered":"STF faz maioria e agora j\u00e1 s\u00e3o 795 radicais no banco dos r\u00e9us do 8 de janeiro"},"content":{"rendered":"<p>O Supremo Tribunal Federal (STF) formou maioria nesta segunda-feira, 15, pela abertura de a\u00e7\u00f5es penais contra 245 incitadores e executores dos atos golpistas de 8 de janeiro.<\/p>\n<p>At\u00e9 o momento, o ministro Alexandre de Moraes, relator dos casos, foi acompanhado por Dias Toffoli, Rosa Weber, C\u00e1rmen L\u00facia, Gilmar Mendes e Edson Fachin. Andr\u00e9 Mendon\u00e7a e Kassio Nunes Marques divergiram.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1153425217\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Trata-se da quarta leva de den\u00fancias analisada pelo STF, em bloco. Em um primeiro momento, 250 den\u00fancias haviam sido pautadas para julgamento, mas a an\u00e1lise de cinco delas precisou ser adiada a pedido das defesas. Os advogados alegaram problemas t\u00e9cnicos para incluir as sustenta\u00e7\u00f5es orais no sistema.<\/p>\n<p>At\u00e9 o momento, conforme os tr\u00eas julgamentos anteriores, 550 investigados respondem formalmente \u00e0 Corte m\u00e1xima por crimes ligados aos atos de 8 de janeiro \u2013 350 s\u00e3o apontados como incitadores dos atos de vandalismo e outros 200 como executores materiais dos delitos.<\/p>\n<p>Aos executores dos atos golpistas, a Procuradoria-Geral da Rep\u00fablica (PGR) atribui crimes de associa\u00e7\u00e3o criminosa armada, aboli\u00e7\u00e3o violenta do estado democr\u00e1tico de direito, golpe de estado, dano qualificado e deteriora\u00e7\u00e3o de patrim\u00f4nio tombado. J\u00e1 aos incitadores s\u00e3o atribu\u00eddos delitos de incita\u00e7\u00e3o ao crime e associa\u00e7\u00e3o criminosa.<\/p>\n<p>Com o recebimento das den\u00fancias, as defesas s\u00e3o intimadas a se manifestar sobre as acusa\u00e7\u00f5es da PGR e d\u00e1-se in\u00edcio \u00e0s a\u00e7\u00f5es penais, com os devidos tramites de oitivas e coleta de provas. H\u00e1 a expectativa de que tal processo de instru\u00e7\u00e3o deva tramitar no Supremo.<\/p>\n<p>A Corte m\u00e1xima deve seguir analisando, semanalmente, as acusa\u00e7\u00f5es ofertadas pelo Minist\u00e9rio P\u00fablico Federal. Foram apresentadas mais de 1,3 mil den\u00fancias contra investigados detidos em meio a depreda\u00e7\u00e3o do 8 de janeiro e tamb\u00e9m no dia seguinte \u00e0 ofensiva, no acampamento golpista montado em frente ao QG do Ex\u00e9rcito em Bras\u00edlia.<\/p>\n<p>As investiga\u00e7\u00f5es quanto a autores intelectuais e financiadores dos crimes ainda n\u00e3o foi conclu\u00edda, assim como a apura\u00e7\u00e3o sobre suposta \u2018omiss\u00e3o\u2019 de autoridades ante os atos de vandalismo \u2013 a qual atinge o ex-ministro Anderson Torres e o governador Ibaneis Rocha.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"assinatura_exclusiva\">Pepita Ortega\/Estad\u00e3o Conte\u00fado<\/span><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='STF faz maioria e agora j\u00e1 s\u00e3o 795 radicais no banco dos r\u00e9us do 8 de janeiro' data-link='https:\/\/newsinfoco.com.br\/inicio\/stf-faz-maioria-e-agora-ja-sao-795-radicais-no-banco-dos-reus-do-8-de-janeiro\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O Supremo Tribunal Federal (STF) formou maioria nesta segunda-feira, 15, pela abertura de a\u00e7\u00f5es penais contra 245 incitadores e executores dos atos golpistas de 8 de janeiro. At\u00e9 o momento, o ministro Alexandre de Moraes, relator dos casos, foi acompanhado por Dias Toffoli, Rosa Weber, C\u00e1rmen L\u00facia, Gilmar Mendes e Edson Fachin. Andr\u00e9 Mendon\u00e7a e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-33951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33951"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33951\/revisions"}],"predecessor-version":[{"id":33953,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33951\/revisions\/33953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33952"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}