{"id":33956,"date":"2023-05-15T17:59:15","date_gmt":"2023-05-15T20:59:15","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=33956"},"modified":"2023-05-15T17:59:15","modified_gmt":"2023-05-15T20:59:15","slug":"governador-inova-reune-poderes-e-entrega-lei-de-diretrizes-orcamentarias-2024","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/governador-inova-reune-poderes-e-entrega-lei-de-diretrizes-orcamentarias-2024\/","title":{"rendered":"Governador inova, re\u00fane poderes e entrega Lei de Diretrizes Or\u00e7ament\u00e1rias 2024"},"content":{"rendered":"<p>Uma entrega simb\u00f3lica e in\u00e9dita do projeto de Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) foi realizada durante reuni\u00e3o na manh\u00e3 desta segunda-feira (15), no Pal\u00e1cio de Ondina, entre o governador Jer\u00f4nimo Rodrigues e l\u00edderes da Assembleia Legislativa da Bahia (Alba), do Tribunal de Justi\u00e7a, do Tribunal de Contas do Estado, do Minist\u00e9rio P\u00fablico e da Defensoria P\u00fablica do Estado. O encontro marca um momento de alinhamento entre os poderes para que os repasses or\u00e7ament\u00e1rios do pr\u00f3ximo ano sejam feitos com base nas suas necessidades reais, evitando ajustes nos repasses ao longo do ano.<\/p>\n<p>Jer\u00f4nimo Rodrigues destaca que essa \u00e9 a primeira vez que o projeto \u00e9 entregue ao presidente da Assembleia Legislativa pelo pr\u00f3prio governador. \u201cFizemos um pacto de uma agenda permanente, acompanhando a execu\u00e7\u00e3o or\u00e7ament\u00e1ria, respeitando a autonomia dos poderes e dos \u00f3rg\u00e3os de controle. E discutimos sobre pautas estrat\u00e9gicas para o Estado da Bahia. Esse projeto ser\u00e1 alinhado ao longo desses meses de maio, junho, julho, e hoje foi um ato de di\u00e1logo e de fortalecimento dos poderes\u201d.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2309704993\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>De acordo com o secret\u00e1rio do Planejamento, Cl\u00e1udio Peixoto, a LDO 2024 estabelece uma conex\u00e3o entre o Plano Plurianual (2024-2027) e o Or\u00e7amento Anual (2024), e sinaliza as prioridades da gest\u00e3o estadual, em sintonia com as condi\u00e7\u00f5es econ\u00f4micas e fiscais projetadas para o exerc\u00edcio de 2024. Este ano, particularmente, os instrumentos de planejamento (PPA, LDO e LOA) est\u00e3o sendo elaborados de forma simult\u00e2nea, sob a coordena\u00e7\u00e3o da Seplan.<\/p>\n<p>\u201cO projeto de lei da LDO trata da organiza\u00e7\u00e3o do or\u00e7amento para o ano de 2024. Ele ir\u00e1 regrar como ser\u00e1 elaborado o or\u00e7amento. A partir da Lei de Responsabilidade Fiscal, a LDO ganhou uma import\u00e2ncia muito grande em fun\u00e7\u00e3o dos seus anexos, onde o poder executivo e os demais poderes revelam quais s\u00e3o suas prioridades, al\u00e9m das metas fiscais, que sinalizam a capacidade e sa\u00fade fiscal do ente\u201d, frisou.<\/p>\n<p>Com rela\u00e7\u00e3o \u00e0 receita total projetada para o or\u00e7amento fiscal e da seguridade social de 2024, o valor estimado \u00e9 de aproximadamente R$ 70 bilh\u00f5es, sendo R$ 60 bilh\u00f5es provenientes da receita do tesouro. Essas receitas podem ser revistas e atualizadas quando o projeto de lei do Or\u00e7amento 2024 (PLOA 2024) for finalizado.<\/p>\n<p>A novidade da lei encaminhada este ano fica por conta da mudan\u00e7a na metodologia para a forma\u00e7\u00e3o das cotas or\u00e7ament\u00e1rias do Poder Legislativo \u2013 compreendendo a Assembleia Legislativa, o Tribunal de Contas do Estado e o Tribunal de Contas dos Munic\u00edpios -, do Poder Judici\u00e1rio, do Minist\u00e9rio P\u00fablico e da Defensoria P\u00fablica do Estado.<\/p>\n<p>Pela nova regra, ser\u00e1 considerado o conjunto das despesas liquidadas custeadas com recursos das fontes Bahia 100 \u2013 Recursos Ordin\u00e1rios n\u00e3o Vinculados do Tesouro e 300 \u2013 Recursos Ordin\u00e1rios n\u00e3o Vinculados do Tesouro, do exerc\u00edcio de 2022, atualizado pelo \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo \u2013 IPCA (esperado para 2023) e corrigido pelo \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo \u2013 IPCA (esperado para 2024), divulgados no Focus Relat\u00f3rio de Mercado do Banco Central, no dia 10 de mar\u00e7o de 2023. Os valores das cotas or\u00e7ament\u00e1rias ser\u00e3o informados pela Secretaria de Planejamento do Estado da Bahia (Seplan) aos respectivos \u00f3rg\u00e3os, at\u00e9 o dia 24 de julho de 2023.<\/p>\n<p><strong>Diretrizes<\/strong><\/p>\n<p>Quanto \u00e0s prioridades do governo, o projeto de Lei da LDO aponta algumas diretrizes, como o enfrentamento \u00e0 fome e demais formas de vulnerabilidade social, com vista na garantia de dignidade; consolida\u00e7\u00e3o de obras estrat\u00e9gicas; promo\u00e7\u00e3o da inclus\u00e3o socioprodutiva de povos e comunidades tradicionais; promo\u00e7\u00e3o da forma\u00e7\u00e3o dos cidad\u00e3os e cidad\u00e3s mediante o desenvolvimento da educa\u00e7\u00e3o contextualizada, da expans\u00e3o da educa\u00e7\u00e3o profissional; promo\u00e7\u00e3o da expans\u00e3o da infraestrutura h\u00eddrica, el\u00e9trica, digital e de mobilidade; fortalecimento, amplia\u00e7\u00e3o e qualifica\u00e7\u00e3o das estruturas de promo\u00e7\u00e3o da seguran\u00e7a p\u00fablica como forma de enfrentamento \u00e0 criminalidade; amplia\u00e7\u00e3o da oferta e da territorializa\u00e7\u00e3o dos servi\u00e7os de sa\u00fade; fomento ao desenvolvimento rural em respeito \u00e0 diversidade produtiva e \u00e0s formas de produ\u00e7\u00e3o protagonizadas pela agricultura familiar e o agroneg\u00f3cio, entre outras diretrizes que se relacionam com as \u00e1reas do meio ambiente, cultura, infraestrutura, ci\u00eancia e tecnologia.<\/p>\n<p>No encontro que marcou a entrega, estiveram presentes o vice-governador, Geraldo J\u00fanior; os secret\u00e1rios estaduais do Planejamento, Cl\u00e1udio Peixoto, da Casa Civil, Afonso Florence, das Rela\u00e7\u00f5es Institucionais, Luiz Caetano, da Justi\u00e7a e Direitos Humanos, Felipe Freitas; a procuradora geral do Estado, B\u00e1rbara Camardeli; o conselheiro Marcus Pres\u00eddio, do TCE \u2013 Tribunal de Contas do Estado; o deputado Adolfo Menezes, da Assembl\u00e9ia Legislativa; o deputado estadual Rosemberg Pinto; o desembargador Nilson Castelo Branco, do Tribunal de Justi\u00e7a, a procuradora Norma Ang\u00e9lica, do Minist\u00e9rio P\u00fablico Estadual, e da defensora geral Firmiane Ven\u00e2ncio, da Defensoria P\u00fablica do Estado.<br \/>\n<strong><br \/>\nProje\u00e7\u00f5es Econ\u00f4micas<\/strong><\/p>\n<p>Diante do cen\u00e1rio econ\u00f4mico nacional, a expectativa para o crescimento da economia baiana em 2023 \u00e9 de 1,5%, segundo proje\u00e7\u00f5es elaboradas pela SEI \u2013 Superintend\u00eancia de Estudos Econ\u00f4micos e Sociais, autarquia vinculada \u00e0 Seplan. A conforma\u00e7\u00e3o desse resultado deposita no setor de servi\u00e7os um ritmo mais forte de crescimento, com expectativas positivas quanto ao mercado de trabalho.<\/p>\n<p>Os progn\u00f3sticos para a agropecu\u00e1ria apontam para a manuten\u00e7\u00e3o dos resultados positivos dos \u00faltimos anos, em rela\u00e7\u00e3o \u00e0 safra de gr\u00e3os estimadas para a Bahia em 2024. Para o setor industrial, espera-se resultados positivos em resposta \u00e0 continuidade do crescimento na gera\u00e7\u00e3o de energia e da demanda externa por produtos da ind\u00fastria de transforma\u00e7\u00e3o, especialmente do segmento de derivados de petr\u00f3leo.<\/p>\n<p>Nesse contexto, para 2024, projeta-se um crescimento do PIB nacional em torno de 1,5% e para o estado da Bahia uma expans\u00e3o em torno de 3,2%. Conforme Boletim Focus, as proje\u00e7\u00f5es para a infla\u00e7\u00e3o e as taxas de juros devem fechar o ano com cerca de 4,0% e 11,1%, respectivamente.<\/p>\n<p>No m\u00e9dio e longo prazos, os investimentos estaduais se consolidam como determinantes na expans\u00e3o da atividade econ\u00f4mica no estado. Do lado dos investimentos privados, destacam-se os setores de energia renov\u00e1vel (e\u00f3lica e solar e de hidrog\u00eanio verde) e o de refino de petr\u00f3leo, qu\u00edmicos, automotivo, minera\u00e7\u00e3o, entre outros.<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Governador inova, re\u00fane poderes e entrega Lei de Diretrizes Or\u00e7ament\u00e1rias 2024' data-link='https:\/\/newsinfoco.com.br\/inicio\/governador-inova-reune-poderes-e-entrega-lei-de-diretrizes-orcamentarias-2024\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Uma entrega simb\u00f3lica e in\u00e9dita do projeto de Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) foi realizada durante reuni\u00e3o na manh\u00e3 desta segunda-feira (15), no Pal\u00e1cio de Ondina, entre o governador Jer\u00f4nimo Rodrigues e l\u00edderes da Assembleia Legislativa da Bahia (Alba), do Tribunal de Justi\u00e7a, do Tribunal de Contas do Estado, do Minist\u00e9rio P\u00fablico e da Defensoria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-33956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=33956"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33956\/revisions"}],"predecessor-version":[{"id":33957,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/33956\/revisions\/33957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/33537"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=33956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=33956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=33956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}