{"id":34094,"date":"2023-05-26T16:33:54","date_gmt":"2023-05-26T19:33:54","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=34094"},"modified":"2023-05-26T16:33:54","modified_gmt":"2023-05-26T19:33:54","slug":"presidente-da-associacao-de-moradores-de-santa-terezinha-fabio-moraes-declara-apoio-a-pre-candidatura-de-gustavo-carmo-para-prefeitura-de-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/presidente-da-associacao-de-moradores-de-santa-terezinha-fabio-moraes-declara-apoio-a-pre-candidatura-de-gustavo-carmo-para-prefeitura-de-alagoinhas\/","title":{"rendered":"Presidente da Associa\u00e7\u00e3o de Moradores de Santa Terezinha, Fabio Moraes, declara apoio \u00e0 pr\u00e9-candidatura de Gustavo Carmo para prefeitura de Alagoinhas"},"content":{"rendered":"<p>O presidente da Associa\u00e7\u00e3o de Moradores Novo Horizonte de Santa Terezinha, F\u00e1bio Moraes, anunciou nesta sexta-feira(26) o seu apoio \u00e0 pr\u00e9-candidatura do secret\u00e1rio municipal de educa\u00e7\u00e3o, Gustavo Carmo, \u00e0 prefeitura de Alagoinhas.<\/p>\n<p>O bairro de Santa Terezinha \u00e9 o segundo mais populoso da cidade, ficando atr\u00e1s apenas do bairro Barreiro. Al\u00e9m do alto n\u00famero de habitantes, o bairro possui um com\u00e9rcio muito forte e contar com importantes apoios na localidade \u00e9 essencial para qualquer postulante ao Pa\u00e7o Municipal.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2632978561\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>F\u00e1bio Moraes, que presidente da Associa\u00e7\u00e3o de Moradores da localidade h\u00e1 v\u00e1rios anos, foi candidato a vereador na \u00faltima elei\u00e7\u00e3o. Apesar de obter expressivos 912 votos, n\u00e3o conseguiu se eleger, lhe restando a 1\u00aa suplencia do seu partido, o Republicanos, que elegeu 3 vereadores: Edy da Sa\u00fade, Djalma Santos e Anselmo Bal.<\/p>\n<p>Para F\u00e1bio Moraes, Gustavo Carmo \u00e9 o nome mais preparado dentro da Gest\u00e3o Municipal para representar o grupo politico liderado pelo prefeito Joaquim Neto nas pr\u00f3ximas elei\u00e7\u00f5es. Em conversa com este site News Infoco, F\u00e1bio enalteceu a capacidade de gest\u00e3o e o censo de lideran\u00e7a de Gustavo, nome que ele espera que se torne prefeito do municipio.<\/p>\n<p>&nbsp;<\/p>\n<p>Por Caio Pimenta para o News Infoco<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Presidente da Associa\u00e7\u00e3o de Moradores de Santa Terezinha, Fabio Moraes, declara apoio \u00e0 pr\u00e9-candidatura de Gustavo Carmo para prefeitura de Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/presidente-da-associacao-de-moradores-de-santa-terezinha-fabio-moraes-declara-apoio-a-pre-candidatura-de-gustavo-carmo-para-prefeitura-de-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O presidente da Associa\u00e7\u00e3o de Moradores Novo Horizonte de Santa Terezinha, F\u00e1bio Moraes, anunciou nesta sexta-feira(26) o seu apoio \u00e0 pr\u00e9-candidatura do secret\u00e1rio municipal de educa\u00e7\u00e3o, Gustavo Carmo, \u00e0 prefeitura de Alagoinhas. O bairro de Santa Terezinha \u00e9 o segundo mais populoso da cidade, ficando atr\u00e1s apenas do bairro Barreiro. Al\u00e9m do alto n\u00famero de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34095,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-34094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=34094"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34094\/revisions"}],"predecessor-version":[{"id":34096,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34094\/revisions\/34096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/34095"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=34094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=34094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=34094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}