{"id":34372,"date":"2023-06-14T17:45:22","date_gmt":"2023-06-14T20:45:22","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=34372"},"modified":"2023-06-14T17:45:22","modified_gmt":"2023-06-14T20:45:22","slug":"deputados-do-uniao-brasil-surpreendem-ao-nao-comparecerem-a-reuniao-com-acm-neto","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/deputados-do-uniao-brasil-surpreendem-ao-nao-comparecerem-a-reuniao-com-acm-neto\/","title":{"rendered":"Deputados do Uni\u00e3o Brasil surpreendem ao n\u00e3o comparecerem a reuni\u00e3o com ACM Neto"},"content":{"rendered":"<p>Os deputados estaduais filiados ao Uni\u00e3o Brasil, Marcinho Oliveira e Marcelinho Veiga, n\u00e3o compareceram \u00e0 reuni\u00e3o realizada com o ex-prefeito de Salvador, ACM Neto (UB), na semana passada.<\/p>\n<p>A aus\u00eancia dos nomes foi notada pela coluna Olho de Tandera, do portal Classe Pol\u00edtica. A aus\u00eancia abre brecha para especula\u00e7\u00f5es quanto \u00e0 sa\u00edda dos quadros do grupo.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3704046321\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Caso uma mudan\u00e7a seja confirmada, esses ser\u00e3o mais dois na lista de nomes que abandonaram a base do pol\u00edtico desde a sua derrota para Jer\u00f4nimo Rodrigues (PT) no ano passado, entre eles o ex-deputado Pablo Barroso e prefeitos do interior que o apoiaram no pleito passado.<\/p>\n<p>&nbsp;<\/p>\n<p>Politicaaovivo<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Deputados do Uni\u00e3o Brasil surpreendem ao n\u00e3o comparecerem a reuni\u00e3o com ACM Neto' data-link='https:\/\/newsinfoco.com.br\/inicio\/deputados-do-uniao-brasil-surpreendem-ao-nao-comparecerem-a-reuniao-com-acm-neto\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Os deputados estaduais filiados ao Uni\u00e3o Brasil, Marcinho Oliveira e Marcelinho Veiga, n\u00e3o compareceram \u00e0 reuni\u00e3o realizada com o ex-prefeito de Salvador, ACM Neto (UB), na semana passada. A aus\u00eancia dos nomes foi notada pela coluna Olho de Tandera, do portal Classe Pol\u00edtica. A aus\u00eancia abre brecha para especula\u00e7\u00f5es quanto \u00e0 sa\u00edda dos quadros do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-34372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=34372"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34372\/revisions"}],"predecessor-version":[{"id":34373,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34372\/revisions\/34373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/16505"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=34372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=34372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=34372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}