{"id":34404,"date":"2023-06-16T17:40:29","date_gmt":"2023-06-16T20:40:29","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=34404"},"modified":"2023-06-16T17:40:29","modified_gmt":"2023-06-16T20:40:29","slug":"juscelio-carmo-confirma-que-pode-disputar-eleicao-em-2024-estou-avaliando-possibilidades","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/juscelio-carmo-confirma-que-pode-disputar-eleicao-em-2024-estou-avaliando-possibilidades\/","title":{"rendered":"Jusc\u00e9lio Carmo confirma que pode disputar elei\u00e7\u00e3o em 2024, &#8220;Estou avaliando possibilidades&#8221;"},"content":{"rendered":"<p>O empres\u00e1rio e radialista Jusc\u00e9lio Carmo confirmou na tarde de hoje(16), em conversa com este site News Infoco, que pode disputar um cargo eletivo em Alagoinhas no ano que vem. A informa\u00e7\u00e3o foi divulgada ontem(15) pelo jornalista Caio Pimenta na coluna que assina neste site News Infoco. ( <a href=\"https:\/\/newsinfoco.com.br\/inicio\/juscelio-carmo-pode-disputar-vaga-na-camara-de-vereadores-de-alagoinhas-em-2024-por-caio-pimenta\/\">Leia<\/a> )<\/p>\n<p>Carmo disse que tem sido procurado por alguns partidos pol\u00edticos interessados em sua filia\u00e7\u00e3o e que h\u00e1 o desejo de alguns apoiadores para que dispute uma vaga na C\u00e2mara Municipal. &#8220;Estou avaliando as possibilidades. Posso ser candidato a vereador, posso ser candidato a prefeito&#8230;. Ou posso simplesmente continuar a tocar meus neg\u00f3cios&#8221;, disse Jusc\u00e9lio.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-4120298518\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>A possibilidade de Jusc\u00e9lio Carmo disputar as elei\u00e7\u00f5es de 2024 causou repercuss\u00e3o na cidade. Hoje(16) pela manh\u00e3, durante o programa Primeira M\u00e3o, da r\u00e1dio Ouro Negro 100,5 FM, ouvintes chegaram a festejar uma poss\u00edvel candidatura de Jusc\u00e9lio na C\u00e2mara Municipal. &#8220;Precisamos melhorar a qualidade das discuss\u00f5es na C\u00e2mara&#8221;, disse um ouvinte. &#8220;Meu voto j\u00e1 \u00e9 dele&#8221;, afirmou outro.<\/p>\n<p>Para o radialista Jos\u00e9 Gomes, que faz parte da bancada do programa, a ida de Jusc\u00e9lio Carmo para a C\u00e2mara Municipal seria importante tanto na perspectiva de apresenta\u00e7\u00e3o de propostas para a resolu\u00e7\u00e3o dos problemas da cidade, quanto no trabalho de fiscaliza\u00e7\u00e3o do prefeito que vier a ser eleito.<\/p>\n<p>De acordo com Jusc\u00e9lio, desde ontem, quando a noticia foi publicada, seu telefone n\u00e3o para de tocar. Figuras do meio politico e populares tem entrado em contato para saber detalhes sobre o retorno dele ao cen\u00e1rio politico. Felicita\u00e7\u00f5es e incentivos para que dispute a elei\u00e7\u00e3o tamb\u00e9m lotam o seu WhasApp. &#8220;Vamos ver o que acontece, n\u00e9&#8221;, finalizou, mantendo mist\u00e9rio sobre qual decis\u00e3o ir\u00e1 tomar.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Jusc\u00e9lio Carmo confirma que pode disputar elei\u00e7\u00e3o em 2024, \"Estou avaliando possibilidades\"' data-link='https:\/\/newsinfoco.com.br\/inicio\/juscelio-carmo-confirma-que-pode-disputar-eleicao-em-2024-estou-avaliando-possibilidades\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O empres\u00e1rio e radialista Jusc\u00e9lio Carmo confirmou na tarde de hoje(16), em conversa com este site News Infoco, que pode disputar um cargo eletivo em Alagoinhas no ano que vem. A informa\u00e7\u00e3o foi divulgada ontem(15) pelo jornalista Caio Pimenta na coluna que assina neste site News Infoco. ( Leia ) Carmo disse que tem sido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-34404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=34404"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34404\/revisions"}],"predecessor-version":[{"id":34405,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34404\/revisions\/34405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/14854"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=34404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=34404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=34404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}