{"id":34443,"date":"2023-06-22T17:28:38","date_gmt":"2023-06-22T20:28:38","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=34443"},"modified":"2023-06-22T17:28:38","modified_gmt":"2023-06-22T20:28:38","slug":"passageiros-do-submarino-morreram-em-catastrofica-implosao-diz-guarda-costeira-dos-eua","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/passageiros-do-submarino-morreram-em-catastrofica-implosao-diz-guarda-costeira-dos-eua\/","title":{"rendered":"Passageiros do submarino morreram em \u2018catastr\u00f3fica implos\u00e3o\u2019, diz Guarda Costeira dos EUA"},"content":{"rendered":"<p>A Guarda Costeira dos EUA informou nesta quinta-feira (22) que os destro\u00e7os encontrados nas buscas pelo submers\u00edvel Titan s\u00e3o compat\u00edveis com uma perda de press\u00e3o do ve\u00edculo, o que provocou uma implos\u00e3o e levou \u00e0 morte os cinco passageiros que estavam a bordo.<\/p>\n<p>\u201cFoi uma catastr\u00f3fica implos\u00e3o\u201d, disse John Mauger, porta-voz da Guarda Costeira. Foram achadas cinco pe\u00e7as principais do submers\u00edvel \u2014a primeira delas foi a parte traseira do ve\u00edculo, localizada por um rob\u00f4.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-449705654\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Os ru\u00eddos detectados na noite da ter\u00e7a-feira (20) e nesta quarta (21), que deram esperan\u00e7a de encontrar sobreviventes, n\u00e3o parecem ter conex\u00e3o com o caso, de acordo com an\u00e1lises da equipe de resgate.<\/p>\n<p>O submers\u00edvel perdeu contato com a superf\u00edcie no domingo (18), 1h45 ap\u00f3s o in\u00edcio do mergulho. Ainda \u00e9 cedo para falar se o acidente aconteceu nesse momento ou posteriormente, segundo o porta-voz, mas as equipes de resgate n\u00e3o detectaram implos\u00f5es nas 72 horas em que estiveram embaixo da \u00e1gua.<\/p>\n<p>Mais cedo, a empresa OceanGate Expeditions, respons\u00e1vel pelo submarino, havia divulgado nota na qual dizia acreditar que as cinco pessoas a bordo morreram. \u201cEsses homens eram verdadeiros exploradores que compartilhavam um esp\u00edrito de aventura e uma profunda paix\u00e3o por explorar e proteger os oceanos do mundo\u201d, diz trecho do comunicado, obtido pela CNN americana.<\/p>\n<p>\u201cNossos cora\u00e7\u00f5es est\u00e3o com essas cinco almas e todos os membros de suas fam\u00edlias durante esse per\u00edodo tr\u00e1gico. Lamentamos a perda de vidas e a alegria que eles trouxeram para todos que conheciam\u201d.<\/p>\n<p>Estavam no submarino Titan o empres\u00e1rio americano Stockton Rush, 61 (dono da OceanGate e piloto do ve\u00edculo), o bilion\u00e1rio brit\u00e2nico Hamish Harding, 58 (presidente-executivo da empresa Action Aviation), o empres\u00e1rio paquistan\u00eas Shahzada Dawood, 48 ( vice-presidente do conglomerado Engro) e seu filho Suleman, 19, e o franc\u00eas Paul-Henry Nargeolet, 77 (mergulhador especialista no naufr\u00e1gio).<\/p>\n<p>O mergulho na costa do Canad\u00e1 com cinco pessoas a bordo come\u00e7ou \u00e0s 8 horas no hor\u00e1rio local (9h em Bras\u00edlia) do \u00faltimo domingo (18), de acordo com a ag\u00eancia de not\u00edcias Reuters. A empresa OceanGate, que opera o Titan, diz que o submers\u00edvel tem reserva de oxig\u00eanio para at\u00e9 96 horas \u2014ou quatro dias.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"assinatura_exclusiva\">Folhapress<\/span><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Passageiros do submarino morreram em \u2018catastr\u00f3fica implos\u00e3o\u2019, diz Guarda Costeira dos EUA' data-link='https:\/\/newsinfoco.com.br\/inicio\/passageiros-do-submarino-morreram-em-catastrofica-implosao-diz-guarda-costeira-dos-eua\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Guarda Costeira dos EUA informou nesta quinta-feira (22) que os destro\u00e7os encontrados nas buscas pelo submers\u00edvel Titan s\u00e3o compat\u00edveis com uma perda de press\u00e3o do ve\u00edculo, o que provocou uma implos\u00e3o e levou \u00e0 morte os cinco passageiros que estavam a bordo. \u201cFoi uma catastr\u00f3fica implos\u00e3o\u201d, disse John Mauger, porta-voz da Guarda Costeira. Foram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-34443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=34443"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34443\/revisions"}],"predecessor-version":[{"id":34445,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34443\/revisions\/34445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/34444"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=34443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=34443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=34443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}