{"id":34509,"date":"2023-06-29T15:51:11","date_gmt":"2023-06-29T18:51:11","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=34509"},"modified":"2023-06-29T15:51:11","modified_gmt":"2023-06-29T18:51:11","slug":"medida-extrema-e-sem-precedentes-no-estado-democratico-de-direito-diz-associacao-de-radio-e-tv-sobre-acao-do-mpf-para-cassar-concessoes-da-jovem-pan","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/medida-extrema-e-sem-precedentes-no-estado-democratico-de-direito-diz-associacao-de-radio-e-tv-sobre-acao-do-mpf-para-cassar-concessoes-da-jovem-pan\/","title":{"rendered":"&#8216;Medida extrema e sem precedentes no Estado Democr\u00e1tico de Direito&#8217;, diz associa\u00e7\u00e3o de r\u00e1dio e TV sobre a\u00e7\u00e3o do MPF para cassar concess\u00f5es da Jovem Pan"},"content":{"rendered":"<p>A Associa\u00e7\u00e3o Brasileira de Emissoras de R\u00e1dio e Televis\u00e3o (Abert) classificou nesta ter\u00e7a-feira (27) como \u201cmuito preocupante\u201d a a\u00e7\u00e3o apresentada pelo\u00a0Minist\u00e9rio P\u00fablico Federal (MPF) que pede o cancelamento de tr\u00eas concess\u00f5es p\u00fablicas de r\u00e1dio do grupo Jovem Pan.<\/p>\n<p>\u201cO cancelamento de uma outorga de radiodifus\u00e3o \u00e9 uma medida extrema e grave, sem precedentes em nosso Estado Democr\u00e1tico de Direito\u201d, diz a nota da entidade.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2728771473\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<div id=\"chunk-3rpe4\">\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"26\" data-block-id=\"4\">\n<p>Apresentada pelo MPF \u00e0 Justi\u00e7a Federal de S\u00e3o Paulo na \u00faltima segunda (26), a a\u00e7\u00e3o argumenta que a Jovem Pan \u201cpraticou, ao menos entre janeiro de 2022 e janeiro de 2023, sistem\u00e1ticos e multifacetados abusos \u00e0 sua liberdade de radiodifus\u00e3o\u201d.<\/p>\n<div id=\"chunk-hsf8\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"34\" data-block-id=\"7\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo o Minist\u00e9rio P\u00fablico, a empresa transmitiu, em seus programas, discursos que minaram a \u201cconfian\u00e7a cidad\u00e3os e cidad\u00e3s do pa\u00eds em seus processos c\u00edvicos e na pr\u00f3pria import\u00e2ncia de preserva\u00e7\u00e3o de nosso regime democr\u00e1tico\u201d.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-cfs72\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"27\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O \u00f3rg\u00e3o argumentou que foram veiculados \u201cconte\u00fados desinformativos sobre o funcionamento de institui\u00e7\u00f5es p\u00fablicas nacionais, e conte\u00fados incitat\u00f3rios \u00e0 viol\u00eancia e \u00e0 ruptura do regime democr\u00e1tico brasileiro\u201d.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-30e1n\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"48\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\u201cPor conta disso, \u00e9 impositivo que sejam canceladas as outorgas de r\u00e1dio atualmente detidas pela JOVEM PAN, que ela seja obrigada a indenizar a sociedade brasileira pelos graves danos morais coletivos causados, e que ela seja obrigada a veicular, em sua estrutura, direito de resposta \u00e0 popula\u00e7\u00e3o\u201d, escreveu.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-aj3oq\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"19\" data-block-id=\"10\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Para a Abert, a a\u00e7\u00e3o \u00e9 \u201cconsiderada muito preocupante\u201d. A associa\u00e7\u00e3o tamb\u00e9m defendeu a liberdade de programa\u00e7\u00e3o das emissoras.<\/p>\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\u201cA liberdade de programa\u00e7\u00e3o das emissoras \u00e9 fundamental para o livre exerc\u00edcio do jornalismo e para a exist\u00eancia do pluralismo de opini\u00e3o, que devem ser sempre preservados. A ABERT estar\u00e1 vigilante na defesa da liberdade de express\u00e3o e de imprensa e acompanhar\u00e1 os desdobramentos da a\u00e7\u00e3o\u201d, afirma a associa\u00e7\u00e3o, que representa mais de tr\u00eas mil emissoras privadas de r\u00e1dio e televis\u00e3o.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-6k9u6\">\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"61\" data-block-id=\"11\">\n<p><strong><span style=\"color: #111111; font-family: Roboto, sans-serif; font-size: 27px;\">O que pede a a\u00e7\u00e3o<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-91k9\">\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"5\" data-block-id=\"12\">\n<p>Antes da condena\u00e7\u00e3o ao cancelamento das concess\u00f5es, o MPF pede que a Justi\u00e7a Federal obrigue a Jovem Pan a exibir conte\u00fados produzidos pela Uni\u00e3o a respeito da \u201cconfiabilidade dos processos democr\u00e1ticos\u201d.<\/p>\n<div id=\"chunk-5gq5n\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"33\" data-block-id=\"15\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Os conte\u00fados devem ser veiculados por ao menos 15 vezes por dia, durante quatro meses, entre 6h e 21h. O descumprimento levaria a multa di\u00e1ria em valor n\u00e3o inferior a R$ 100 mil.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-4ajn8\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"41\" data-block-id=\"16\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Durante o andamento da a\u00e7\u00e3o, a Promotoria solicita \u00e0 Justi\u00e7a que pro\u00edba a Jovem Pan de excluir conte\u00fados publicados no canal &#8220;Jovem Pan News&#8221;, na plataforma YouTube, entre os dias 1\u00ba de janeiro de 2022 e 9 de janeiro de 2023.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-1r6oa\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"40\" data-block-id=\"17\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na hip\u00f3tese de condena\u00e7\u00e3o, al\u00e9m da cassa\u00e7\u00e3o de tr\u00eas concess\u00f5es sob responsabilidade da Jovem Pan, o Minist\u00e9rio P\u00fablico defende que a Justi\u00e7a Federal condene o grupo ao pagamento de indeniza\u00e7\u00e3o por danos morais coletivos no valor de R$ 13,4 milh\u00f5es.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-q5t1\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"21\" data-block-id=\"18\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na a\u00e7\u00e3o, o MPF afirmou que &#8220;n\u00e3o tem interesse em resolver a presente demanda por meio de concilia\u00e7\u00e3o ou de media\u00e7\u00e3o&#8221;.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-2ohce\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"85\" data-block-id=\"19\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Qualquer solu\u00e7\u00e3o consensual que viesse a ser entabulada no caso, at\u00e9 onde se consegue ver, teria efeitos meramente prospectivos e, por isso, se mostraria insuficiente como resposta estatal aos graves fatos apurados. A defesa do regime democr\u00e1tico, colocado em perigo por condutas como as praticadas pela JOVEM PAN, \u00e9 uma tarefa irrenunci\u00e1vel, que n\u00e3o comporta negocia\u00e7\u00f5es ordin\u00e1rias. Por maiores que possam ser as promessas de conformidade e de melhoria para o futuro, o passado n\u00e3o se apaga e desafia provid\u00eancias legais severas, proporcionais ao ocorrido.&#8221;<\/p>\n<div id=\"chunk-fiuno\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"7\" data-block-id=\"22\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Leia a \u00edntegra do posicionamento da Abert:<\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-96qun\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"35\" data-block-id=\"23\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong><em>&#8220;A Associa\u00e7\u00e3o Brasileira de Emissoras de R\u00e1dio e Televis\u00e3o (ABERT) considera muito preocupante a a\u00e7\u00e3o civil p\u00fablica ajuizada pelo Minist\u00e9rio P\u00fablico Federal (MPF), que solicita o cancelamento das outorgas concedidas \u00e0 r\u00e1dio Jovem Pan News.<\/em><\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-3seer\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"21\" data-block-id=\"24\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong><em>O cancelamento de uma outorga de radiodifus\u00e3o \u00e9 uma medida extrema e grave, sem precedentes em nosso Estado Democr\u00e1tico de Direito.<\/em><\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-etjk3\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"27\" data-block-id=\"25\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong><em>A liberdade de programa\u00e7\u00e3o das emissoras \u00e9 fundamental para o livre exerc\u00edcio do jornalismo e para a exist\u00eancia do pluralismo de opini\u00e3o, que devem ser sempre preservados.<\/em><\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-rn7r\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"19\" data-block-id=\"26\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong><em>A ABERT estar\u00e1 vigilante na defesa da liberdade de express\u00e3o e de imprensa e acompanhar\u00e1 os desdobramentos da a\u00e7\u00e3o.&#8221;<\/em><\/strong><\/p>\n<\/div>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">G1<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text=''Medida extrema e sem precedentes no Estado Democr\u00e1tico de Direito', diz associa\u00e7\u00e3o de r\u00e1dio e TV sobre a\u00e7\u00e3o do MPF para cassar concess\u00f5es da Jovem Pan' data-link='https:\/\/newsinfoco.com.br\/inicio\/medida-extrema-e-sem-precedentes-no-estado-democratico-de-direito-diz-associacao-de-radio-e-tv-sobre-acao-do-mpf-para-cassar-concessoes-da-jovem-pan\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Brasileira de Emissoras de R\u00e1dio e Televis\u00e3o (Abert) classificou nesta ter\u00e7a-feira (27) como \u201cmuito preocupante\u201d a a\u00e7\u00e3o apresentada pelo\u00a0Minist\u00e9rio P\u00fablico Federal (MPF) que pede o cancelamento de tr\u00eas concess\u00f5es p\u00fablicas de r\u00e1dio do grupo Jovem Pan. \u201cO cancelamento de uma outorga de radiodifus\u00e3o \u00e9 uma medida extrema e grave, sem precedentes em nosso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-34509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=34509"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34509\/revisions"}],"predecessor-version":[{"id":34511,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34509\/revisions\/34511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/34510"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=34509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=34509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=34509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}