{"id":34674,"date":"2023-07-24T13:26:57","date_gmt":"2023-07-24T16:26:57","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=34674"},"modified":"2023-07-24T13:26:57","modified_gmt":"2023-07-24T16:26:57","slug":"ex-vereador-jose-edesio-declara-apoio-a-pre-candidatura-de-gustavo-carmo-para-prefeitura-de-alagoinhas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/ex-vereador-jose-edesio-declara-apoio-a-pre-candidatura-de-gustavo-carmo-para-prefeitura-de-alagoinhas\/","title":{"rendered":"Ex-vereador Jos\u00e9 Ed\u00e9sio declara apoio \u00e0 pr\u00e9-candidatura de Gustavo Carmo para prefeitura de Alagoinhas"},"content":{"rendered":"<p>O ex-vereador de Alagoinhas, Jos\u00e9 Ed\u00e9sio, declarou oficialmente no dia de hoje(24) o seu apoio \u00e0 pr\u00e9-candidatura de Gustavo Carmo \u00e0 prefeitura de Alagoinhas. Vereador por 7 mandatos, e ainda atuante na politica local, Ed\u00e9sio fortalece ainda mais o leque de apoios que Carmo vem arregimentando.<\/p>\n<p>&#8220;Com grande satisfa\u00e7\u00e3o, acolho o nome do amigo Gustavo Carmo que vem se destacando como potencial candidato \u00e0 Prefeitura de Alagoinhas e manifesto meu total apoio a essa poss\u00edvel candidatura.&#8221;, disse o ex-vereador em sua rede social.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2984859841\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Ainda falando em Ed\u00e9sio&#8230; O ex-parlamentar vem trabalhando para concorrer novamente ao cargo em 2024.<\/p>\n<p>&nbsp;<\/p>\n<p>Por Caio Pimenta para o News Infoco<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Ex-vereador Jos\u00e9 Ed\u00e9sio declara apoio \u00e0 pr\u00e9-candidatura de Gustavo Carmo para prefeitura de Alagoinhas' data-link='https:\/\/newsinfoco.com.br\/inicio\/ex-vereador-jose-edesio-declara-apoio-a-pre-candidatura-de-gustavo-carmo-para-prefeitura-de-alagoinhas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O ex-vereador de Alagoinhas, Jos\u00e9 Ed\u00e9sio, declarou oficialmente no dia de hoje(24) o seu apoio \u00e0 pr\u00e9-candidatura de Gustavo Carmo \u00e0 prefeitura de Alagoinhas. Vereador por 7 mandatos, e ainda atuante na politica local, Ed\u00e9sio fortalece ainda mais o leque de apoios que Carmo vem arregimentando. &#8220;Com grande satisfa\u00e7\u00e3o, acolho o nome do amigo Gustavo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-34674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=34674"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34674\/revisions"}],"predecessor-version":[{"id":34676,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/34674\/revisions\/34676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/34675"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=34674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=34674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=34674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}