{"id":35124,"date":"2023-09-26T19:03:00","date_gmt":"2023-09-26T22:03:00","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=35124"},"modified":"2023-09-26T19:03:00","modified_gmt":"2023-09-26T22:03:00","slug":"estadao-maioria-da-populacao-rejeita-decisao-de-toffoli-que-anulou-provas-do-caso-odebrecht-aponta-pesquisa","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/estadao-maioria-da-populacao-rejeita-decisao-de-toffoli-que-anulou-provas-do-caso-odebrecht-aponta-pesquisa\/","title":{"rendered":"Estad\u00e3o: Maioria da popula\u00e7\u00e3o rejeita decis\u00e3o de Toffoli que anulou provas do caso Odebrecht, aponta pesquisa"},"content":{"rendered":"<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">A maioria da popula\u00e7\u00e3o brasileira rejeita a decis\u00e3o do ministro do Supremo Tribunal Federal (STF)\u00a0Dias Toffoli\u00a0que\u00a0anulou um conjunto de provas colhidas pela Lava Jato no caso da Odebrecht\u00a0e que beneficiou a defesa do presidente\u00a0Luiz In\u00e1cio Lula da Silva\u00a0(PT). De acordo com o instituto Atlas, 54,1% dos brasileiros discordam da decis\u00e3o, enquanto 27,6% afirmam concordar com ela. Os que disseram n\u00e3o saber s\u00e3o 18,3%. Os dados foram colhidos por meio do m\u00e9todo de recrutamento digital aleat\u00f3rio, que ouviu 3.038 respondentes entre os dias 20 e 25 deste m\u00eas. A margem de erro do estudo \u00e9 de 2 pontos porcentuais para mais ou para menos e o n\u00edvel de confian\u00e7a \u00e9 de 95%.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Mesmo com Lula sendo beneficiado pela decis\u00e3o, 18,3% de seus eleitores no segundo turno da \u00faltima elei\u00e7\u00e3o discordam da posi\u00e7\u00e3o de Toffoli. Enquanto isso, 50,1% concordam e 31,6% disseram n\u00e3o saber. Entre os bolsonaristas, a reprova\u00e7\u00e3o \u00e9 bem maior: 94,3%, contra 3,3% que concorda e 2,5% que diz n\u00e3o saber. A rejei\u00e7\u00e3o \u00e0 anula\u00e7\u00e3o das provas tamb\u00e9m \u00e9 majorit\u00e1ria entre os eleitores que dizem ter votado em branco (67,8%) e entre os que n\u00e3o votaram (17,7%).<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3266114932\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p class=\"continue-read-break\" data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">A\u00a0Procuradoria-Geral da Rep\u00fablica (PGR) entrou, na sexta-feira, 22, com um recurso no STF\u00a0para o ministro Dias Toffoli esclarecer pontos da decis\u00e3o, que atendeu a um pedido de Lula. A defesa do petista alegou que o acordo foi negociado com a ajuda de autoridades estrangeiras sem observar crit\u00e9rios de colabora\u00e7\u00e3o internacional. O\u00a0Minist\u00e9rio P\u00fablico de S\u00e3o Paulo (MP-SP) tamb\u00e9m entrou com recurso no STF. O procurador-geral de Justi\u00e7a do Estado, Mario Luiz Sarrubbo, afirma que as provas foram usadas em \u201cdiversas a\u00e7\u00f5es e investiga\u00e7\u00f5es\u201d que agora est\u00e3o em xeque. Ele pede que Toffoli reconsidere a decis\u00e3o ou envie o caso ao plen\u00e1rio do STF. Para ele, a decis\u00e3o s\u00f3 deveria valer para o caso de Lula e n\u00e3o em todos os casos em que as provas foram usadas.<\/p>\n<h3 class=\"article-sub-heading\" data-reset-char-count=\"true\"><strong>Condena\u00e7\u00e3o dos primeiros r\u00e9us do 8 de janeiro \u00e9 aprovada<\/strong><\/h3>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Entre os eleitores ouvidos pelo instituto Atlas, 45,4% concordam com a\u00a0decis\u00e3o que condenou os primeiros r\u00e9us pelos ataques de 8 de janeiro. De outro lado, 40,7% discordam da decis\u00e3o. Outros 14% n\u00e3o sabem. Tamb\u00e9m neste caso, como esperado, o apoio \u00e9 maior entre os lulistas (77,4%) do que entre os bolsonaristas (8,8%).<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Al\u00e9m da decis\u00e3o de Toffoli, o Atlas tamb\u00e9m mediu as percep\u00e7\u00f5es dos brasileiros sobre a atua\u00e7\u00e3o dos ministros do STF em diversas quest\u00f5es. Em uma delas, ao serem questionados se confiavam no trabalho e nos ministros da Corte, 47,7% disseram que n\u00e3o, enquanto 44,5% afirmaram que sim. Os que n\u00e3o souberam s\u00e3o 7,8%.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">J\u00e1 em pergunta se h\u00e1 compet\u00eancia e imparcialidade dos ministros no julgamento dos processos, 44,7% disseram que sim, enquanto 40,8% apontam que n\u00e3o. Neste caso, os que n\u00e3o sabem s\u00e3o 14,6%.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Os eleitores ouvidos pelo Atlas tamb\u00e9m foram questionados se odeiam os ministros da Corte, como chegaram a dizer advogados de r\u00e9us do 8 de janeiro no julgamento dos primeiros r\u00e9us pelos ataques. A maioria, 51,7%, diz que n\u00e3o odeia, mas possui posi\u00e7\u00e3o negativa sobre alguns deles. Outros 32,3% afirmam que, ao contr\u00e1rio, possuem opini\u00e3o positiva sobre a maioria dos ministros. Enquanto isso, 16% respondem que \u201csim, odeiam\u201d.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Entre os ministros, o \u00fanico que tem saldo positivo entre as avalia\u00e7\u00f5es favor\u00e1veis e desfavor\u00e1veis \u00e9 o mais novo integrante do STF. Cristiano Zanin tem imagem positiva para 35% dos brasileiros e negativa para 32%. Os mais rejeitados s\u00e3o Gilmar Mendes (51% positiva e 31% negativa), Dias Toffoli (49% negativa e 30% positiva). Alexandre de Moraes \u00e9 o ministro que mais divide opini\u00f5es entre os brasileiros, que praticamente se igualam entre apoio e reprova\u00e7\u00e3o.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\"><b>Veja a avalia\u00e7\u00e3o de cada ministro:<\/b><\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Alexandre de Moraes: 47% positiva e 48% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">C\u00e1rmen L\u00facia: 43% positiva e 45% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Rosa Weber: 40% positiva e 43% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Cristiano Zanin: 35% positiva e 32% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Roberto Barroso: 34% positiva e 44% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Edson Fachin: 32% positiva e 47% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Luiz Fux: 43% positiva e 43% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Gilmar Mendes: 31% positiva e 51% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Andr\u00e9 Mendon\u00e7a: 30% positiva e 42% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Dias Toffoli: 30% positiva e 49% negativa<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Nunes Marques: 27% positiva e 41% negativa<\/p>\n<h3 class=\"article-sub-heading\" data-reset-char-count=\"true\"><strong>Not\u00f3rio saber jur\u00eddico e cargos pesam mais que g\u00eanero e cor por vaga ao STF<\/strong><\/h3>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Os eleitores tamb\u00e9m foram instados a comentar tamb\u00e9m sobre os atributos importantes para a escolha de um ministro para o STF, decis\u00e3o que Lula ter\u00e1 que tomar com a aposentadoria de Rosa Weber nesta quinta-feira, 28. O requisito mais citado como \u201cmuito importante\u201d foi o not\u00f3rio saber jur\u00eddico, citado por 74% dos eleitores. O fato de ter exercido cargos de relev\u00e2ncia nacional foi citado por 36% como muito importantes e por 11% como importantes. J\u00e1 o fato de ser mulher foi lembrado por 32% como muito importante e por 5% como importante. Outro ponto citado por grupos que defendem maior representatividade no STF, a cor do futuro ministro, tem menos apelo junto \u00e0 maioria dos brasileiros. S\u00e3o 28% os que dizem que ser negro \u00e9 muito importante para ser indicado e 6% os que dizem que \u00e9 importante.<\/p>\n<h3 class=\"article-sub-heading\" data-reset-char-count=\"true\"><strong>Avalia\u00e7\u00e3o de governo est\u00e1vel, com leve aumento de desaprova\u00e7\u00e3o<\/strong><\/h3>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">A pesquisa Atlas tamb\u00e9m mostrou uma avalia\u00e7\u00e3o est\u00e1vel do governo Lula. Sobre o desempenho pessoal do presidente, 51,5% aprovam e 46% desaprovam. Houve uma varia\u00e7\u00e3o apenas na margem de erro em rela\u00e7\u00e3o a julho, quando 52,6% aprovaram e 45,8% desaprovavam.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">J\u00e1 em rela\u00e7\u00e3o \u00e0 avalia\u00e7\u00e3o de governo, s\u00e3o 44,1% os que consideram \u00f3timo ou bom, 41,5% os que veem como ruim ou p\u00e9ssimo e 13,1% os que apontam como regular. Em julho, eram 43,5% os que achavam o governo \u00f3timo ou bom, 40% os que achavam ruim ou p\u00e9ssimo e 16% os que viam como regular.<\/p>\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">\n<p data-t=\"{&quot;n&quot;:&quot;blueLinks&quot;}\">Estadao<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Estad\u00e3o: Maioria da popula\u00e7\u00e3o rejeita decis\u00e3o de Toffoli que anulou provas do caso Odebrecht, aponta pesquisa' data-link='https:\/\/newsinfoco.com.br\/inicio\/estadao-maioria-da-populacao-rejeita-decisao-de-toffoli-que-anulou-provas-do-caso-odebrecht-aponta-pesquisa\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A maioria da popula\u00e7\u00e3o brasileira rejeita a decis\u00e3o do ministro do Supremo Tribunal Federal (STF)\u00a0Dias Toffoli\u00a0que\u00a0anulou um conjunto de provas colhidas pela Lava Jato no caso da Odebrecht\u00a0e que beneficiou a defesa do presidente\u00a0Luiz In\u00e1cio Lula da Silva\u00a0(PT). De acordo com o instituto Atlas, 54,1% dos brasileiros discordam da decis\u00e3o, enquanto 27,6% afirmam concordar com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-35124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=35124"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35124\/revisions"}],"predecessor-version":[{"id":35125,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35124\/revisions\/35125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/11778"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=35124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=35124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=35124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}