{"id":35211,"date":"2023-10-15T17:40:13","date_gmt":"2023-10-15T20:40:13","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=35211"},"modified":"2023-10-15T17:40:13","modified_gmt":"2023-10-15T20:40:13","slug":"crise-no-transporte-publico-de-alagoinhas-com-deficit-e-sem-subsidio-da-prefeitura-empresa-demite-7-rodoviarios","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/crise-no-transporte-publico-de-alagoinhas-com-deficit-e-sem-subsidio-da-prefeitura-empresa-demite-7-rodoviarios\/","title":{"rendered":"Crise no transporte p\u00fablico de Alagoinhas: Com d\u00e9ficit e sem subsidio da prefeitura, empresa demite 7 rodovi\u00e1rios"},"content":{"rendered":"<p>Em mais um capitulo da novela que virou a crise no transporte p\u00fablico de Alagoinhas, a empresa ATP, concession\u00e1ria do sistema de transporte p\u00fablico local, anunciou o desligamento de 7 funcion\u00e1rios da empresa. As demiss\u00f5es acontecem dias ap\u00f3s o pagamento dos funcion\u00e1rios que foi realizado este m\u00eas com atraso.<\/p>\n<p>Em oficio enviado ao sindicato, ao anunciar que iria atrasar o pagamento por falta de receita, a ATP acusou os sucessivos aumentos do pre\u00e7o do \u00f3leo diesel nos \u00faltimos 04 meses, assim como o aumento dos pre\u00e7os dos pneus, \u00f3leos lubrificantes e demais insumos utilizados para manuten\u00e7\u00e3o dos \u00f4nibus, em detrimento do aumento expressivo do n\u00famero de gratuidades transportadas por m\u00eas, da diminui\u00e7\u00e3o gradativa do n\u00famero de passageiros pagantes e o valor deficit\u00e1rio da tarifa do sistema como respons\u00e1veis pela crise de receita que inviabiliza cumprir o seu compromisso com os empregados.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3801060350\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Pelo contrato de licita\u00e7\u00e3o firmado entre a prefeitura e a empresa, o sistema deveria ofertar 500 mil usu\u00e1rios\/m\u00eas, esse n\u00famero seria suficiente para arrecadar o valor necess\u00e1rio para custear o sistema. Por\u00e9m, desde o inicio da vig\u00eancia do contrato, esses n\u00fameros ca\u00edram drasticamente, chegando para menos da metade. Pelo contrato, a prefeitura deveria arcar com essa defasagem, pagando por meio de subsidio os valores, ou ent\u00e3o repassando para o usu\u00e1rio pagante o \u00f4nus do d\u00e9ficit por meio de reajuste tarif\u00e1rio. A prefeitura n\u00e3o fez nenhuma coisa, nem outra.<\/p>\n<p>Hoje, a tarifa t\u00e9cnica supera R$ 6,50, mas a praticada \u00e9 de R$4,20. Uma defasagem de R$2,30 por passageiro. O resultado \u00e9 falta de recursos da empresa para promover investimentos no servi\u00e7o.<\/p>\n<p>Desde 2020 at\u00e9 aqui o desequil\u00edbrio contratual do transporte p\u00fablico ultrapassa R$ 30 milh\u00f5es de reais, cerca de R$ 12 milh\u00f5es por ano. Dinheiro que deveria ter entrado no sistema para promover a melhoria do modal.<\/p>\n<p>O diretor do sindicato dos rodovi\u00e1rios, Gil Alagoinhas, em v\u00eddeos compartilhados nas redes sociais criticou o prefeito da cidade Joaquim Neto(PSD) a quem acusa de descumprir um compromisso firmado em subsidiar o sistema.<\/p>\n<p>Este ano, entre os meses de janeiro e junho, a prefeitura repassou R$ 2,4 milh\u00f5es, a titulo de subsidio para o transporte p\u00fablico. Apesar de n\u00e3o suprir o d\u00e9ficit anual de cerca de R$ 12 milh\u00f5es, o valor, segundo o presidente do sindicato dos rodovi\u00e1rios, ajudou a empresa a honrar os pagamentos de sal\u00e1rios dos funcion\u00e1rios, que foi reajustado, ap\u00f3s 2 anos. De acordo com o dirigente sindical outros benef\u00edcios foram concedidos aos mais de 220 colaboradores da empresa, que at\u00e9 ent\u00e3o n\u00e3o possu\u00eda nenhum d\u00e9bito trabalhista e previdenci\u00e1rio. Ainda de acordo com Gil Alagoinhas, o prefeito havia prometido a extens\u00e3o do subsidio nos 6 meses subsequentes, o que garantiria a conserva\u00e7\u00e3o dos benef\u00edcios e aumentos concedidos \u00e0 categoria, o que n\u00e3o ocorreu.<\/p>\n<p>O Sindmetro, sindicato da categoria, acusa a gest\u00e3o municipal de n\u00e3o ter comprometimento com a situa\u00e7\u00e3o do transporte p\u00fablico e promete levar os rodovi\u00e1rios para acampar na porta do prefeito em busca de uma solu\u00e7\u00e3o.<\/p>\n<p>Em nota enviada a este News Infoco, o sindicato informou ainda que paralisar\u00e1 as atividades durante o Bahia Beer, o festival da cerveja, marcado para ocorrer no m\u00eas que vem.<\/p>\n<p>O site News Infoco tentou entrar em contato com a assessoria de imprensa da empresa ATP, mas at\u00e9 o fechamento da mat\u00e9ria n\u00e3o obteve retorno.<\/p>\n<p>O site News Infoco tamb\u00e9m tentou entrar em contato com o prefeito Joaquim Neto, mas tamb\u00e9m n\u00e3o obteve \u00eaxito.<\/p>\n<p>Nesta segunda-feira, 16, o presidente do Sindmetro, M\u00e1rio Kl\u00e9ber, ser\u00e1 o entrevistado do programa Primeira M\u00e3o, da r\u00e1dio Ouro Negro 100,5 FM.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por Caio Pimenta para o News Infoco<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Crise no transporte p\u00fablico de Alagoinhas: Com d\u00e9ficit e sem subsidio da prefeitura, empresa demite 7 rodovi\u00e1rios' data-link='https:\/\/newsinfoco.com.br\/inicio\/crise-no-transporte-publico-de-alagoinhas-com-deficit-e-sem-subsidio-da-prefeitura-empresa-demite-7-rodoviarios\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Em mais um capitulo da novela que virou a crise no transporte p\u00fablico de Alagoinhas, a empresa ATP, concession\u00e1ria do sistema de transporte p\u00fablico local, anunciou o desligamento de 7 funcion\u00e1rios da empresa. As demiss\u00f5es acontecem dias ap\u00f3s o pagamento dos funcion\u00e1rios que foi realizado este m\u00eas com atraso. Em oficio enviado ao sindicato, ao [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[38,167],"tags":[],"class_list":["post-35211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoinhas-e-regiao","category-exclusivas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=35211"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35211\/revisions"}],"predecessor-version":[{"id":35212,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35211\/revisions\/35212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/32334"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=35211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=35211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=35211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}