{"id":35213,"date":"2023-10-15T18:19:55","date_gmt":"2023-10-15T21:19:55","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=35213"},"modified":"2023-10-15T18:19:55","modified_gmt":"2023-10-15T21:19:55","slug":"israel-confirma-que-filha-de-brasileira-esta-entre-refens-do-hamas","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/israel-confirma-que-filha-de-brasileira-esta-entre-refens-do-hamas\/","title":{"rendered":"Israel confirma que filha de brasileira est\u00e1 entre ref\u00e9ns do Hamas"},"content":{"rendered":"<p>A filha de uma brasileira est\u00e1 entre os\u00a0mais de 120 ref\u00e9ns\u00a0do grupo Hamas. A bab\u00e1 Celeste Fishbein, 18 anos,\u00a0estava em um kibutz, esp\u00e9cie de comunidade rural, pr\u00f3xima \u00e0 Faixa de Gaza, quando desapareceu ap\u00f3s o ataque surpresa do Hamas, no dia 7 de outubro.<\/p>\n<p>A fam\u00edlia afirma ter recebido a confirma\u00e7\u00e3o do estado de Israel ap\u00f3s an\u00e1lise de amostra de DNA da m\u00e3e da jovem, que n\u00e3o a identificou entre os 1.300 mortos no ataque. Nas redes sociais, os parentes t\u00eam compartilhado pedidos de ajuda e atualiza\u00e7\u00f5es sobre Celeste.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-2054090860\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p class=\"texto\">O irm\u00e3o, Liel Fishbein e outros familiares conseguiram escapar porque se esconderam em um bunker durante o ataque. Em entrevista ao canal CNN, o tio da jovem, M\u00e1rio Fishbein, contou que a garota trocou mensagens com eles at\u00e9 por volta de 11h20, do s\u00e1bado (7\/10), quando parou de responder. O namorado da garota tamb\u00e9m est\u00e1 desaparecido.<\/p>\n<p class=\"texto\">Al\u00e9m do tio e irm\u00e3o, estavam a m\u00e3e de Celeste; a av\u00f3, de 94 anos; e a cuidadora da idosa. Eles foram resgatados pelo ex\u00e9rcito israelense 20 horas ap\u00f3s o ataque.<\/p>\n<p>&nbsp;<\/p>\n<p>Correio Braziliense<\/p>\n<p>&nbsp;<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Israel confirma que filha de brasileira est\u00e1 entre ref\u00e9ns do Hamas' data-link='https:\/\/newsinfoco.com.br\/inicio\/israel-confirma-que-filha-de-brasileira-esta-entre-refens-do-hamas\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A filha de uma brasileira est\u00e1 entre os\u00a0mais de 120 ref\u00e9ns\u00a0do grupo Hamas. A bab\u00e1 Celeste Fishbein, 18 anos,\u00a0estava em um kibutz, esp\u00e9cie de comunidade rural, pr\u00f3xima \u00e0 Faixa de Gaza, quando desapareceu ap\u00f3s o ataque surpresa do Hamas, no dia 7 de outubro. A fam\u00edlia afirma ter recebido a confirma\u00e7\u00e3o do estado de Israel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-35213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=35213"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35213\/revisions"}],"predecessor-version":[{"id":35215,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35213\/revisions\/35215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/35214"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=35213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=35213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=35213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}