{"id":35775,"date":"2024-02-10T19:22:44","date_gmt":"2024-02-10T22:22:44","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=35775"},"modified":"2024-02-10T19:22:44","modified_gmt":"2024-02-10T22:22:44","slug":"parana-pesquisas-estreante-michelle-bolsonaro-aparece-com-23-para-presidente","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/parana-pesquisas-estreante-michelle-bolsonaro-aparece-com-23-para-presidente\/","title":{"rendered":"Paran\u00e1 Pesquisas: Estreante, Michelle Bolsonaro aparece com 23% para presidente"},"content":{"rendered":"<p>Michelle Bolsonaro teria 23% dos votos para presidente, se a elei\u00e7\u00e3o fosse hoje, segundo levantamento do Paran\u00e1 Pesquisas que aponta o atual presidente Lula (PT) \u00e0 frente, com 37,6%, como o favorito para 2026.<\/p>\n<p>A ex-primeira-dama s\u00f3 perde para o ex-presidente Bolsonaro, que empata tecnicamente contra Lula. Num segundo turno contra Lula, Michelle teria 38,7% e o petista seria reeleito com 45,4% no cen\u00e1rio que tamb\u00e9m apresenta 11,5% de votos brancos e nulos e 4,3% de incertos.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-1263930754\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>Tido como o principal herdeiro do bolsonarismo, o governador paulista Tarc\u00edsio de Freitas (Rep) registraria 17,4% ante 37,4% de Lula.<\/p>\n<p>Outro presidenci\u00e1vel, o governador de Minas Gerais, Romeu Zema (Novo), oscila entre 3,9% e 6,5% dos votos, nos cen\u00e1rios contra Lula.<\/p>\n<p>O paranaense Ratinho Jr (PSD) ficaria entre 3,9% e 6,5% e o governador do Goi\u00e1s, Ronaldo Caiado (Uni\u00e3o), de 1% a 2%.<\/p>\n<p>&nbsp;<\/p>\n<p>Diario do Poder<\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Paran\u00e1 Pesquisas: Estreante, Michelle Bolsonaro aparece com 23% para presidente' data-link='https:\/\/newsinfoco.com.br\/inicio\/parana-pesquisas-estreante-michelle-bolsonaro-aparece-com-23-para-presidente\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Michelle Bolsonaro teria 23% dos votos para presidente, se a elei\u00e7\u00e3o fosse hoje, segundo levantamento do Paran\u00e1 Pesquisas que aponta o atual presidente Lula (PT) \u00e0 frente, com 37,6%, como o favorito para 2026. A ex-primeira-dama s\u00f3 perde para o ex-presidente Bolsonaro, que empata tecnicamente contra Lula. Num segundo turno contra Lula, Michelle teria 38,7% [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-35775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=35775"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35775\/revisions"}],"predecessor-version":[{"id":35777,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/35775\/revisions\/35777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/35776"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=35775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=35775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=35775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}