{"id":36138,"date":"2024-05-28T18:27:53","date_gmt":"2024-05-28T21:27:53","guid":{"rendered":"https:\/\/newsinfoco.com.br\/inicio\/?p=36138"},"modified":"2024-05-28T18:27:53","modified_gmt":"2024-05-28T21:27:53","slug":"presidente-da-assembleia-legislativa-da-bahia-veta-acesso-de-servidores-estaduais-as-galerias-e-e-alvo-de-protestos","status":"publish","type":"post","link":"https:\/\/newsinfoco.com.br\/inicio\/presidente-da-assembleia-legislativa-da-bahia-veta-acesso-de-servidores-estaduais-as-galerias-e-e-alvo-de-protestos\/","title":{"rendered":"Presidente da Assembleia Legislativa da Bahia veta acesso de servidores estaduais \u00e0s galerias e \u00e9 alvo de protestos"},"content":{"rendered":"<p>Gerou protestos a decis\u00e3o do presidente da Assembleia Legislativa da Bahia (AL-BA), deputado Adolfo Menezes (PSD), de impedir o acesso de servidores estaduais \u00e0s galerias da Casa na sess\u00e3o desta ter\u00e7a-feira (28), quando ser\u00e1 votada a proposta de reajuste de 4% para a categoria. Os sindicatos pedem 10%.<\/p>\n<p>Os servidores que foram \u00e0 sede do Legislativo ficaram acomodados no sagu\u00e3o ao lado do plen\u00e1rio, onde foi instalado um tel\u00e3o para transmiss\u00e3o ao vivo da vota\u00e7\u00e3o.<\/p><div class=\"newsi-conteudo_19\" id=\"newsi-3803858035\"><a href=\"https:\/\/www.instagram.com\/prefeituraalagoinhas?igsh=YzgzdDJ1bWR3aWI4\" aria-label=\"SAVE_20251006_221555\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg\" alt=\"\"  srcset=\"https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-rotated.jpg 1140w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-300x52.jpg 300w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1024x177.jpg 1024w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-768x133.jpg 768w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-600x104.jpg 600w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-696x120.jpg 696w, https:\/\/newsinfoco.com.br\/inicio\/wp-content\/uploads\/2025\/10\/SAVE_20251006_221555-1068x185.jpg 1068w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" width=\"1140\" height=\"197\"   \/><\/a><\/div>\n<p>O veto \u00e0s galerias foi alvo de severas cr\u00edticas. No plen\u00e1rio, o deputado Hilton Coelho (PSOL) disse que a medida promovia uma esp\u00e9cie de \u201csess\u00e3o secreta\u201d.<\/p>\n<p>\u201cQue Casa do povo \u00e9 essa? Onde \u00e9 que n\u00f3s temos democracia? Paz sem voz n\u00e3o \u00e9 paz, \u00e9 medo, j\u00e1 diria o poeta. N\u00e3o existe n\u00f3s considerarmos que deputado n\u00e3o pode ser vaiado\u201d, protestou Coelho.<\/p>\n<p>Do lado de fora, os servidores gritavam palavras de ordem contra o presidente Adolfo com extens\u00f5es ao governador Jer\u00f4nimo Rodrigues (PT).<\/p>\n<p>\u201cSe fosse para acompanhar pelo tel\u00e3o, as pessoas ficavam em casa\u201d, emendou Hilton, que chegou a pedir que a quest\u00e3o fosse submetida ao plen\u00e1rio.<\/p>\n<p>Alan Sanches (Uni\u00e3o Brasil), l\u00edder da oposi\u00e7\u00e3o, tamb\u00e9m pediu que a medida fosse ponderada. O pedido foi negado pela presid\u00eancia.<\/p>\n<p>\u201cEu pensei que a Assembleia estava sendo invadida por algum grupo terrorista\u201d, iniciou o deputado Sandro R\u00e9gis (Uni\u00e3o Brasil), ao falar sobre o refor\u00e7o policial presente nos corredores da Casa.<\/p>\n<p>\u201cN\u00e3o \u00e9 certo os servidores usarem as galerias para agredir deputado, mas tamb\u00e9m n\u00e3o \u00e9 certo a Casa tratar o servidor como bandido. Tem que ter o equil\u00edbrio em tudo. Tem que ter o equil\u00edbrio dos servidores nas suas manifesta\u00e7\u00f5es, mas tem que ter o equil\u00edbrio da Casa para que os servidores assistam como os 63 deputados votaram\u201d, ponderou.<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"assinatura_exclusiva\">Pol\u00edtica Livre<\/span><\/p>\n<div class='share-to-whatsapp-wrapper'><div class='share-on-whsp'>Share on: <\/div><a data-text='Presidente da Assembleia Legislativa da Bahia veta acesso de servidores estaduais \u00e0s galerias e \u00e9 alvo de protestos' data-link='https:\/\/newsinfoco.com.br\/inicio\/presidente-da-assembleia-legislativa-da-bahia-veta-acesso-de-servidores-estaduais-as-galerias-e-e-alvo-de-protestos\/' class='whatsapp-button whatsapp-share'>WhatsApp<\/a><div class='clear '><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Gerou protestos a decis\u00e3o do presidente da Assembleia Legislativa da Bahia (AL-BA), deputado Adolfo Menezes (PSD), de impedir o acesso de servidores estaduais \u00e0s galerias da Casa na sess\u00e3o desta ter\u00e7a-feira (28), quando ser\u00e1 votada a proposta de reajuste de 4% para a categoria. Os sindicatos pedem 10%. Os servidores que foram \u00e0 sede do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-36138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/comments?post=36138"}],"version-history":[{"count":1,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36138\/revisions"}],"predecessor-version":[{"id":36139,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/posts\/36138\/revisions\/36139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media\/30366"}],"wp:attachment":[{"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/media?parent=36138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/categories?post=36138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsinfoco.com.br\/inicio\/wp-json\/wp\/v2\/tags?post=36138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}